{"id":8875,"date":"2016-06-06T08:31:49","date_gmt":"2016-06-06T11:31:49","guid":{"rendered":"http:\/\/dana.com.br\/canaldana\/?p=8875"},"modified":"2016-06-06T08:31:49","modified_gmt":"2016-06-06T11:31:49","slug":"fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/","title":{"rendered":"Fiat espera aumentar as vendas do Mobi em 35% com vers\u00e3o aventureira Way"},"content":{"rendered":"<p><em>Carsale<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Um m\u00eas e meio ap\u00f3s o lan\u00e7amento oficial do Mobi, a Fiat come\u00e7ou a enviar aos seus concession\u00e1rios a vers\u00e3o com apelo aventureiro Way. Agora, com a linha completa, a marca pretende crescer o n\u00famero de vendas do subcompacto.<\/p>\n<p>&nbsp;<\/p>\n<p>Se em maio o Mobi conseguiu emplacar 2.400 unidades, a expectativa \u00e9 de chegar a 3.500\/4.000 unidades daqui para frente. Para isso, de acordo com a Fiat, a variante com apelo aventureiro \u00e9 de extrema import\u00e2ncia, uma vez que representar\u00e1, no m\u00ednimo, 35% das vendas. Segundo a marca, esse \u00edndice pode atingir at\u00e9 50%.<\/p>\n<p>&nbsp;<\/p>\n<p>Com a chegada do Mobi Way \u00e0s lojas, a Fiat convidou alguns jornalistas para irem at\u00e9 a Fazenda Capoava, no interior de S\u00e3o Paulo, para refor\u00e7ar alguns pontos da vers\u00e3o rec\u00e9m-lan\u00e7ada.<\/p>\n<p>&nbsp;<\/p>\n<p>O primeiro ponto abordado pela Fiat foi deixar claro que n\u00e3o se trata de um mini-Uno. Para comprovar isso, revelou todas as altera\u00e7\u00f5es feitas na plataforma e carroceira do Mobi. Segundo a marca italiana, apenas 30% das pe\u00e7as usadas no Mobi s\u00e3o provenientes do Uno ou Palio.<\/p>\n<p>&nbsp;<\/p>\n<p>A Fiat tamb\u00e9m aproveitou pra ressaltar que este \u00e9 o menor ve\u00edculo produzido no Brasil, o que refor\u00e7a sua fun\u00e7\u00e3o urbana. Al\u00e9m disso, fez quest\u00e3o de enfatizar que o espa\u00e7o para o motorista no Mobi \u00e9 maior que no principal concorrente, o VW up!.<\/p>\n<p>&nbsp;<\/p>\n<p>Ali\u00e1s, assim que lan\u00e7ado, o Mobi Way enfrentou no Carsale um comparativo com o Cross up!, sendo que o compacto da marca alem\u00e3 venceu o embate, especialmente pelo conjunto mec\u00e2nico. Por\u00e9m, o Mobi sai na frente em termos de equipamento e pre\u00e7o um pouco abaixo do rival.<\/p>\n<p>&nbsp;<\/p>\n<p>Uma quest\u00e3o que sempre preocupa os consumidores \u00e9 a seguran\u00e7a. O up!, testado com as regras antigas, recebeu cinco estrelas nos testes do Latin NCAP, sendo que o Palio, do qual o Mobi herda parte da estrutura, recebeu quatro. Com isso, a Fiat afirma que hoje o subcompacto Mobi conseguiria, no m\u00ednimo, tr\u00eas estrelas mesmo com as mudan\u00e7as na regras.<\/p>\n<p>&nbsp;<\/p>\n<p>Por fim, a Fiat demonstrou a capacidade fora de estrada do Mobi. Obviamente n\u00e3o \u00e9 um carro voltado para off-road, no entanto, os 15 mm a mais de eleva\u00e7\u00e3o em rela\u00e7\u00e3o ao solo fazem bem ao pequeno. Desse jeito, a suspens\u00e3o trabalha bem e suaviza bem os chacoalh\u00f5es dentro do ve\u00edculo.<\/p>\n<p>&nbsp;<\/p>\n<p>O Mobi passar\u00e1 a fazer mais sentido no portf\u00f3lio da Fiat com a pr\u00f3xima reestiliza\u00e7\u00e3o do Uno. Se hoje os irm\u00e3os est\u00e3o muito pr\u00f3ximos, eles devem se distanciar em breve. Assim que o Uno mudar, seu patamar dever\u00e1 subir, inclusive em termos de motoriza\u00e7\u00e3o &#8211; espera-se que a gama ganhe um motor 1.0 de tr\u00eas cilindros. Durante o evento, a Fiat afirmou que o novo motor de tr\u00eas cilindros vir\u00e1 ao Brasil, mas n\u00e3o para o Mobi.<\/p>\n<p>&nbsp;<\/p>\n<p>Nos pr\u00f3ximos meses a Fiat deve fazer o lan\u00e7amento do sistema Live On, que transforma o smartphone em central multim\u00eddia. A partir da\u00ed, a empresa acredita que ter\u00e1 todas as armas para emplacar de vez o Mobi. (Carsale)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carsale &nbsp; Um m\u00eas e meio ap\u00f3s o lan\u00e7amento oficial do Mobi, a Fiat come\u00e7ou a enviar aos seus concession\u00e1rios a vers\u00e3o com apelo aventureiro Way. Agora, com a linha completa, a marca pretende crescer o n\u00famero de vendas do subcompacto. &nbsp; Se em maio o Mobi conseguiu emplacar 2.400 unidades, a expectativa \u00e9 de\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-8875","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiat espera aumentar as vendas do Mobi em 35% com vers\u00e3o aventureira Way - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiat espera aumentar as vendas do Mobi em 35% com vers\u00e3o aventureira Way - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Carsale &nbsp; Um m\u00eas e meio ap\u00f3s o lan\u00e7amento oficial do Mobi, a Fiat come\u00e7ou a enviar aos seus concession\u00e1rios a vers\u00e3o com apelo aventureiro Way. Agora, com a linha completa, a marca pretende crescer o n\u00famero de vendas do subcompacto. &nbsp; Se em maio o Mobi conseguiu emplacar 2.400 unidades, a expectativa \u00e9 de\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-06T11:31:49+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Fiat espera aumentar as vendas do Mobi em 35% com vers\u00e3o aventureira Way\",\"datePublished\":\"2016-06-06T11:31:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\\\/\"},\"wordCount\":553,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\\\/\",\"name\":\"Fiat espera aumentar as vendas do Mobi em 35% com vers\u00e3o aventureira Way - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2016-06-06T11:31:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fiat espera aumentar as vendas do Mobi em 35% com vers\u00e3o aventureira Way\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiat espera aumentar as vendas do Mobi em 35% com vers\u00e3o aventureira Way - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/","og_locale":"pt_BR","og_type":"article","og_title":"Fiat espera aumentar as vendas do Mobi em 35% com vers\u00e3o aventureira Way - Canal Dana","og_description":"Carsale &nbsp; Um m\u00eas e meio ap\u00f3s o lan\u00e7amento oficial do Mobi, a Fiat come\u00e7ou a enviar aos seus concession\u00e1rios a vers\u00e3o com apelo aventureiro Way. Agora, com a linha completa, a marca pretende crescer o n\u00famero de vendas do subcompacto. &nbsp; Se em maio o Mobi conseguiu emplacar 2.400 unidades, a expectativa \u00e9 de\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/","og_site_name":"Canal Dana","article_published_time":"2016-06-06T11:31:49+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Fiat espera aumentar as vendas do Mobi em 35% com vers\u00e3o aventureira Way","datePublished":"2016-06-06T11:31:49+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/"},"wordCount":553,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/","url":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/","name":"Fiat espera aumentar as vendas do Mobi em 35% com vers\u00e3o aventureira Way - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2016-06-06T11:31:49+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/fiat-espera-aumentar-as-vendas-do-mobi-em-35-com-versao-aventureira-way\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Fiat espera aumentar as vendas do Mobi em 35% com vers\u00e3o aventureira Way"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/8875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=8875"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/8875\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=8875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=8875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=8875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}