{"id":8869,"date":"2016-06-06T08:29:36","date_gmt":"2016-06-06T11:29:36","guid":{"rendered":"http:\/\/dana.com.br\/canaldana\/?p=8869"},"modified":"2016-06-06T08:29:36","modified_gmt":"2016-06-06T11:29:36","slug":"ford-tera-de-se-explicar-sobre-cambio","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/","title":{"rendered":"Ford ter\u00e1 de se explicar sobre c\u00e2mbio"},"content":{"rendered":"<p><em>Jornal do Carro<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>O Minist\u00e9rio P\u00fablico de Minas Gerais enviou uma requisi\u00e7\u00e3o para que a Ford responda a 88 quest\u00f5es sobre problemas relacionados ao c\u00e2mbio automatizado Powershift, que equipa os modelos Fiesta, EcoSport e Focus.<\/p>\n<p>&nbsp;<\/p>\n<p>A solicita\u00e7\u00e3o \u00e9 parte de uma investiga\u00e7\u00e3o instaurada pelo Procon (que, em Minas Gerais, \u00e9 ligado ao Minist\u00e9rio P\u00fablico), com o objetivo de apurar se a montadora de S\u00e3o Bernardo do Campo est\u00e1 colocando no mercado ve\u00edculos defeituosos, se est\u00e1 pondo em risco a sa\u00fade e a seguran\u00e7a dos consumidores e se a empresa, por meio de sua rede autorizada, est\u00e1 efetivamente resolvendo os problemas ocorridos.<\/p>\n<p>&nbsp;<\/p>\n<p>As perguntas foram elaboradas com base n\u00e3o somente em queixas feitas ao Procon-MG, mas tamb\u00e9m em depoimentos colhidos em audi\u00eancia p\u00fablica feita durante a investiga\u00e7\u00e3o e em documentos que o \u00f3rg\u00e3o obteve junto a concession\u00e1rias da marca. Elas versam sobre aspectos t\u00e9cnicos da transmiss\u00e3o, a assist\u00eancia das concession\u00e1rias aos consumidores afetados e a eventual extens\u00e3o da garantia pela f\u00e1brica.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre outras quest\u00f5es, o \u00f3rg\u00e3o pergunta se a Ford reconhece a exist\u00eancia de v\u00edcio de produto (defeito de f\u00e1brica recorrente), se os manuais dos ve\u00edculos alertam os consumidores sobre o comportamento do c\u00e2mbio e se os frequentes relatos de panes e travamentos s\u00fabitos n\u00e3o seriam suficientes para a convoca\u00e7\u00e3o de um recall. A Ford tem at\u00e9 o dia 29 de junho para enviar as respostas.<\/p>\n<p>&nbsp;<\/p>\n<p>O \u00f3rg\u00e3o de defesa do consumidor decidiu agir depois de ter recebido uma grande quantidade de reclama\u00e7\u00f5es de propriet\u00e1rios de ve\u00edculos equipados com o c\u00e2mbio Powershift. Os relatos descrevem sintomas como trepida\u00e7\u00e3o excessiva, patina\u00e7\u00e3o, demora na retomada da marcha, falta de resposta do carro e superaquecimento. As panes e travamentos inesperados chegam a colocar os consumidores em risco, em situa\u00e7\u00f5es como ultrapassagens, trechos rodovi\u00e1rios ermos e mesmo cruzamentos urbanos.<\/p>\n<p>&nbsp;<\/p>\n<p>Esses problemas j\u00e1 s\u00e3o velhos conhecidos de quem acompanha o Jornal do Carro. A coluna Defenda-se, que publica queixas contra montadoras, tem mostrado v\u00e1rias reclama\u00e7\u00f5es de leitores que passam por maus bocados com seus exemplares de Fiesta e EcoSport &#8211; entre 2014 e 2015, a coluna recebeu, em m\u00e9dia, um novo relato nesse sentido a cada 23 dias. Isso motivou a publica\u00e7\u00e3o de uma mat\u00e9ria em 9 de dezembro de 2015.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c0 \u00e9poca, procurada pela nossa reportagem, a Ford emitiu uma nota dizendo que estenderia a garantia de f\u00e1brica, de tr\u00eas para cinco anos, dos conjuntos automatizados Powershift &#8211; mas apenas nos ve\u00edculos que tivessem sido fabricados at\u00e9 agosto de 2013. Na investiga\u00e7\u00e3o feita pelo Minist\u00e9rio P\u00fablico, uma das perguntas questiona, inclusive, os crit\u00e9rios da marca para limitar esse benef\u00edcio a apenas um grupo de unidades produzidas.<\/p>\n<p>&nbsp;<\/p>\n<p>Chegou a se especular que a Ford estaria preparando um recall mais amplo para a corre\u00e7\u00e3o dessas falhas, mas isso n\u00e3o se concretizou at\u00e9 hoje. Enquanto isso, novas queixas continuam chegando \u00e0 coluna Defenda-se e, em alguns desses casos, panes e travamentos ocorrem mesmo ap\u00f3s a substitui\u00e7\u00e3o do kit de embreagem pela montadora.<\/p>\n<p>&nbsp;<\/p>\n<p>Mesmo com todos esses percal\u00e7os, por\u00e9m, tudo indica que a Ford continuar\u00e1 renovando suas apostas no c\u00e2mbio Powershift. A maior prova disso \u00e9 que o novo motor Ecoboost 1.0 turbo de 125 cv, que equipar\u00e1 o hatch Fiesta dentro de algumas semanas, ser\u00e1 oferecido ao p\u00fablico unicamente com a transmiss\u00e3o automatizada. (Jornal do Carro)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jornal do Carro &nbsp; O Minist\u00e9rio P\u00fablico de Minas Gerais enviou uma requisi\u00e7\u00e3o para que a Ford responda a 88 quest\u00f5es sobre problemas relacionados ao c\u00e2mbio automatizado Powershift, que equipa os modelos Fiesta, EcoSport e Focus. &nbsp; A solicita\u00e7\u00e3o \u00e9 parte de uma investiga\u00e7\u00e3o instaurada pelo Procon (que, em Minas Gerais, \u00e9 ligado ao Minist\u00e9rio\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-8869","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ford ter\u00e1 de se explicar sobre c\u00e2mbio - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ford ter\u00e1 de se explicar sobre c\u00e2mbio - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Jornal do Carro &nbsp; O Minist\u00e9rio P\u00fablico de Minas Gerais enviou uma requisi\u00e7\u00e3o para que a Ford responda a 88 quest\u00f5es sobre problemas relacionados ao c\u00e2mbio automatizado Powershift, que equipa os modelos Fiesta, EcoSport e Focus. &nbsp; A solicita\u00e7\u00e3o \u00e9 parte de uma investiga\u00e7\u00e3o instaurada pelo Procon (que, em Minas Gerais, \u00e9 ligado ao Minist\u00e9rio\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-06T11:29:36+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/ford-tera-de-se-explicar-sobre-cambio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/ford-tera-de-se-explicar-sobre-cambio\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Ford ter\u00e1 de se explicar sobre c\u00e2mbio\",\"datePublished\":\"2016-06-06T11:29:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/ford-tera-de-se-explicar-sobre-cambio\\\/\"},\"wordCount\":608,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/ford-tera-de-se-explicar-sobre-cambio\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/ford-tera-de-se-explicar-sobre-cambio\\\/\",\"name\":\"Ford ter\u00e1 de se explicar sobre c\u00e2mbio - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2016-06-06T11:29:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/ford-tera-de-se-explicar-sobre-cambio\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/ford-tera-de-se-explicar-sobre-cambio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/06\\\/06\\\/ford-tera-de-se-explicar-sobre-cambio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ford ter\u00e1 de se explicar sobre c\u00e2mbio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ford ter\u00e1 de se explicar sobre c\u00e2mbio - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/","og_locale":"pt_BR","og_type":"article","og_title":"Ford ter\u00e1 de se explicar sobre c\u00e2mbio - Canal Dana","og_description":"Jornal do Carro &nbsp; O Minist\u00e9rio P\u00fablico de Minas Gerais enviou uma requisi\u00e7\u00e3o para que a Ford responda a 88 quest\u00f5es sobre problemas relacionados ao c\u00e2mbio automatizado Powershift, que equipa os modelos Fiesta, EcoSport e Focus. &nbsp; A solicita\u00e7\u00e3o \u00e9 parte de uma investiga\u00e7\u00e3o instaurada pelo Procon (que, em Minas Gerais, \u00e9 ligado ao Minist\u00e9rio\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/","og_site_name":"Canal Dana","article_published_time":"2016-06-06T11:29:36+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Ford ter\u00e1 de se explicar sobre c\u00e2mbio","datePublished":"2016-06-06T11:29:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/"},"wordCount":608,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/","url":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/","name":"Ford ter\u00e1 de se explicar sobre c\u00e2mbio - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2016-06-06T11:29:36+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2016\/06\/06\/ford-tera-de-se-explicar-sobre-cambio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Ford ter\u00e1 de se explicar sobre c\u00e2mbio"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/8869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=8869"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/8869\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=8869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=8869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=8869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}