{"id":79516,"date":"2025-02-06T08:52:56","date_gmt":"2025-02-06T11:52:56","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=79516"},"modified":"2025-02-06T08:52:56","modified_gmt":"2025-02-06T11:52:56","slug":"producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/","title":{"rendered":"Produ\u00e7\u00e3o brasileira de implementos rodovi\u00e1rios cresce 1,5% em janeiro"},"content":{"rendered":"<p><em>Truck &amp; Bus Builder Am\u00e9rica do Sul<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Segundo dados divulgados pela ANFIR-Associa\u00e7\u00e3o Nacional dos Fabricantes de Implementos Rodovi\u00e1rios, o volume de produtos comercializados no primeiro m\u00eas de 2025 foi 1,5% superior ao mesmo per\u00edodo de 2024. Foram 11.461 produtos, ante 11.288 unidades registradas no primeiro m\u00eas de 2024.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cO resultado desse primeiro m\u00eas ficou dentro da expectativa da ANFIR com o segmento Leve se destacando e o Pesado registrando volume de emplacamentos abaixo do mesmo m\u00eas do ano passado\u201d, avalia Jos\u00e9 Carlos Spricigo, presidente da ANFIR. Segundo ele, as opera\u00e7\u00f5es log\u00edsticas do agroneg\u00f3cio, como a colheita da soja, est\u00e3o no in\u00edcio e isso deve refletir positivamente nas vendas de Reboques e Semirreboques.<\/p>\n<p>&nbsp;<\/p>\n<p>Em janeiro de 2025 o total de produtos Leves comercializados foi de 5.270 unidades, com crescimento de 25,1% em rela\u00e7\u00e3o aos 4.213 produtos do mesmo m\u00eas de 2024. Com exce\u00e7\u00e3o de Betoneira e Ba\u00fa Lonado todas as linhas de produtos apresentaram crescimento.<\/p>\n<p>&nbsp;<\/p>\n<p>No segmento Pesado, foram entregues ao mercado 6.191 unidades, 12,5% abaixo dos 7.075 produtos comercializados em janeiro do ano passado. Alguns dos destaques foram Porta Conteiner, Ba\u00fa Carga Geral, Carrega Tudo, Frigor\u00edfico, Tanque Carbono e Ba\u00fa Lonado. (Truck &amp; Bus Builder Am\u00e9rica do Sul)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Truck &amp; Bus Builder Am\u00e9rica do Sul &nbsp; Segundo dados divulgados pela ANFIR-Associa\u00e7\u00e3o Nacional dos Fabricantes de Implementos Rodovi\u00e1rios, o volume de produtos comercializados no primeiro m\u00eas de 2025 foi 1,5% superior ao mesmo per\u00edodo de 2024. Foram 11.461 produtos, ante 11.288 unidades registradas no primeiro m\u00eas de 2024. &nbsp; \u201cO resultado desse primeiro m\u00eas\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[61],"tags":[],"class_list":["post-79516","post","type-post","status-publish","format-standard","hentry","category-destaques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Produ\u00e7\u00e3o brasileira de implementos rodovi\u00e1rios cresce 1,5% em janeiro - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Produ\u00e7\u00e3o brasileira de implementos rodovi\u00e1rios cresce 1,5% em janeiro - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Truck &amp; Bus Builder Am\u00e9rica do Sul &nbsp; Segundo dados divulgados pela ANFIR-Associa\u00e7\u00e3o Nacional dos Fabricantes de Implementos Rodovi\u00e1rios, o volume de produtos comercializados no primeiro m\u00eas de 2025 foi 1,5% superior ao mesmo per\u00edodo de 2024. Foram 11.461 produtos, ante 11.288 unidades registradas no primeiro m\u00eas de 2024. &nbsp; \u201cO resultado desse primeiro m\u00eas\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-06T11:52:56+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/06\\\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/06\\\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Produ\u00e7\u00e3o brasileira de implementos rodovi\u00e1rios cresce 1,5% em janeiro\",\"datePublished\":\"2025-02-06T11:52:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/06\\\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\\\/\"},\"wordCount\":216,\"articleSection\":[\"Destaques\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/06\\\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/06\\\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\\\/\",\"name\":\"Produ\u00e7\u00e3o brasileira de implementos rodovi\u00e1rios cresce 1,5% em janeiro - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2025-02-06T11:52:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/06\\\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/06\\\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/06\\\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destaques\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/destaques\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Produ\u00e7\u00e3o brasileira de implementos rodovi\u00e1rios cresce 1,5% em janeiro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Produ\u00e7\u00e3o brasileira de implementos rodovi\u00e1rios cresce 1,5% em janeiro - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/","og_locale":"pt_BR","og_type":"article","og_title":"Produ\u00e7\u00e3o brasileira de implementos rodovi\u00e1rios cresce 1,5% em janeiro - Canal Dana","og_description":"Truck &amp; Bus Builder Am\u00e9rica do Sul &nbsp; Segundo dados divulgados pela ANFIR-Associa\u00e7\u00e3o Nacional dos Fabricantes de Implementos Rodovi\u00e1rios, o volume de produtos comercializados no primeiro m\u00eas de 2025 foi 1,5% superior ao mesmo per\u00edodo de 2024. Foram 11.461 produtos, ante 11.288 unidades registradas no primeiro m\u00eas de 2024. &nbsp; \u201cO resultado desse primeiro m\u00eas\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/","og_site_name":"Canal Dana","article_published_time":"2025-02-06T11:52:56+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Produ\u00e7\u00e3o brasileira de implementos rodovi\u00e1rios cresce 1,5% em janeiro","datePublished":"2025-02-06T11:52:56+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/"},"wordCount":216,"articleSection":["Destaques"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/","url":"https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/","name":"Produ\u00e7\u00e3o brasileira de implementos rodovi\u00e1rios cresce 1,5% em janeiro - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2025-02-06T11:52:56+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2025\/02\/06\/producao-brasileira-de-implementos-rodoviarios-cresce-15-em-janeiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Destaques","item":"https:\/\/dana.com.br\/canaldana\/destaques\/"},{"@type":"ListItem","position":3,"name":"Produ\u00e7\u00e3o brasileira de implementos rodovi\u00e1rios cresce 1,5% em janeiro"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/79516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=79516"}],"version-history":[{"count":1,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/79516\/revisions"}],"predecessor-version":[{"id":79517,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/79516\/revisions\/79517"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=79516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=79516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=79516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}