{"id":79470,"date":"2025-02-05T08:26:40","date_gmt":"2025-02-05T11:26:40","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=79470"},"modified":"2025-02-05T08:26:40","modified_gmt":"2025-02-05T11:26:40","slug":"mercado-de-veiculos-usados-inicia-2025-com-alta-de-21","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/","title":{"rendered":"Mercado de ve\u00edculos usados inicia 2025 com alta de 2,1%"},"content":{"rendered":"<p><em>AutoInd\u00fastria<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Depois de baterem recorde hist\u00f3rico no ano passado, com 15,8 milh\u00f5es de unidades, as vendas de ve\u00edculos usados iniciaram 2025 novamente em ascens\u00e3o e sinalizando para um ano t\u00e3o bom quanto ou at\u00e9 melhor do que o anterior.<\/p>\n<p>&nbsp;<\/p>\n<p>Nesta ter\u00e7a-feira, 4, a Fenauto, entidade que re\u00fane cerca de 48 mil lojas de autom\u00f3veis, comerciais leves e pesados, motos e implementos rodovi\u00e1rios, informou que os neg\u00f3cios em janeiro superaram 1,22 milh\u00e3o de unidades, 2,1% a mais do que no primeiro m\u00eas de 2024.<\/p>\n<p>&nbsp;<\/p>\n<p>A compara\u00e7\u00e3o com as transa\u00e7\u00f5es de dezembro \u00faltimo, entretanto, indicam forte recuo de 16,9%. Mas nada que n\u00e3o estivesse previsto pelo setor.<\/p>\n<p>&nbsp;<\/p>\n<p>Segundo a Fenauto, historicamente os gastos acentuados do come\u00e7o do ano com, por exemplo, IPVA, IPTU, f\u00e9rias e matr\u00edculas escolares, afugentam os consumidores temporariamente.<\/p>\n<p>&nbsp;<\/p>\n<p>Os neg\u00f3cios com motos e comerciais leves foram os que mais avan\u00e7aram: respectivamente, 5,8% e 4,4%. As vendas de autom\u00f3veis de passeio oscilaram positivamente 0,5%, de 766,5 mil mil para 770,5 mil unidades. Ainda assim, o segmento respondeu por cerca de 63% do total de usados.<\/p>\n<p>&nbsp;<\/p>\n<p>Em algumas regi\u00f5es, o crescimento com rela\u00e7\u00e3o a janeiro foram substancialmente mais relevantes. \u00c9 o caso do Nordeste, onde as vendas superaram em 15,7% as do mesmo m\u00eas de 2024 \u2014 muito em fun\u00e7\u00e3o das atividades tur\u00edsticas na regi\u00e3o. Na contram\u00e3o, ficaram os estados do Sudeste, cujas vendas recuaram 4,6%.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cAcreditamos que se as condi\u00e7\u00f5es da economia se mantiverem est\u00e1veis, as vendas devem crescer paulatinamente nos pr\u00f3ximos meses\u201d, avalia Enilson Sales, presidente da entidade.<\/p>\n<p>&nbsp;<\/p>\n<p>No ranking de autom\u00f3veis de passeio mais negociados, destaque para lideran\u00e7a do Volkswagen Gol, com 56,5 mil unidades no m\u00eas passado, quase o dobro do segundo colocado Chevrolet Onix (31,2 mil) e do terceiro Fiat Palio (30,2 mil).<\/p>\n<p>&nbsp;<\/p>\n<p>Entre os comerciais leves, a Fiat Strada repete o sucesso que vem registrando no segmento de novos. A picape compacta alcan\u00e7ou 26,7 mil unidades contra 16,1 mil da Volkswagen Saveiro e 13,3 mil da Toyota Hilux.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u00edder hist\u00f3rica do mercado brasileiro de motos, a Honda CG acumulou 66,8 mil unidades negociadas. A marca japonesa tamb\u00e9m teve a segunda e terceira colocada Biz (33,8 mil) e NXR (25.8 mil). (AutoInd\u00fastria\/George Guimar\u00e3es)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AutoInd\u00fastria &nbsp; Depois de baterem recorde hist\u00f3rico no ano passado, com 15,8 milh\u00f5es de unidades, as vendas de ve\u00edculos usados iniciaram 2025 novamente em ascens\u00e3o e sinalizando para um ano t\u00e3o bom quanto ou at\u00e9 melhor do que o anterior. &nbsp; Nesta ter\u00e7a-feira, 4, a Fenauto, entidade que re\u00fane cerca de 48 mil lojas de\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-79470","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercado de ve\u00edculos usados inicia 2025 com alta de 2,1% - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercado de ve\u00edculos usados inicia 2025 com alta de 2,1% - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"AutoInd\u00fastria &nbsp; Depois de baterem recorde hist\u00f3rico no ano passado, com 15,8 milh\u00f5es de unidades, as vendas de ve\u00edculos usados iniciaram 2025 novamente em ascens\u00e3o e sinalizando para um ano t\u00e3o bom quanto ou at\u00e9 melhor do que o anterior. &nbsp; Nesta ter\u00e7a-feira, 4, a Fenauto, entidade que re\u00fane cerca de 48 mil lojas de\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-05T11:26:40+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/05\\\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/05\\\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Mercado de ve\u00edculos usados inicia 2025 com alta de 2,1%\",\"datePublished\":\"2025-02-05T11:26:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/05\\\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\\\/\"},\"wordCount\":390,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/05\\\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/05\\\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\\\/\",\"name\":\"Mercado de ve\u00edculos usados inicia 2025 com alta de 2,1% - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2025-02-05T11:26:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/05\\\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/05\\\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2025\\\/02\\\/05\\\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mercado de ve\u00edculos usados inicia 2025 com alta de 2,1%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercado de ve\u00edculos usados inicia 2025 com alta de 2,1% - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/","og_locale":"pt_BR","og_type":"article","og_title":"Mercado de ve\u00edculos usados inicia 2025 com alta de 2,1% - Canal Dana","og_description":"AutoInd\u00fastria &nbsp; Depois de baterem recorde hist\u00f3rico no ano passado, com 15,8 milh\u00f5es de unidades, as vendas de ve\u00edculos usados iniciaram 2025 novamente em ascens\u00e3o e sinalizando para um ano t\u00e3o bom quanto ou at\u00e9 melhor do que o anterior. &nbsp; Nesta ter\u00e7a-feira, 4, a Fenauto, entidade que re\u00fane cerca de 48 mil lojas de\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/","og_site_name":"Canal Dana","article_published_time":"2025-02-05T11:26:40+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Mercado de ve\u00edculos usados inicia 2025 com alta de 2,1%","datePublished":"2025-02-05T11:26:40+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/"},"wordCount":390,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/","url":"https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/","name":"Mercado de ve\u00edculos usados inicia 2025 com alta de 2,1% - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2025-02-05T11:26:40+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2025\/02\/05\/mercado-de-veiculos-usados-inicia-2025-com-alta-de-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Mercado de ve\u00edculos usados inicia 2025 com alta de 2,1%"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/79470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=79470"}],"version-history":[{"count":1,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/79470\/revisions"}],"predecessor-version":[{"id":79471,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/79470\/revisions\/79471"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=79470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=79470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=79470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}