{"id":78075,"date":"2024-11-25T09:23:14","date_gmt":"2024-11-25T12:23:14","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=78075"},"modified":"2024-11-25T09:23:14","modified_gmt":"2024-11-25T12:23:14","slug":"governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/","title":{"rendered":"Governo de SP investe em novo centro para produ\u00e7\u00e3o de hidrog\u00eanio"},"content":{"rendered":"<p><em>Estrad\u00e3o <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>O Governo do Estado de S\u00e3o Paulo inaugurou o Centro de Ci\u00eancias para o Desenvolvimento de Energias Renov\u00e1veis e Combust\u00edveis do Futuro (CCD &#8211; ERCF), no Instituto de Pesquisas Tecnol\u00f3gicas (IPT), em S\u00e3o Paulo. De acordo com o governo paulista, o principal objetivo do novo centro \u00e9 estudar o uso do hidrog\u00eanio de baixo carbono.<\/p>\n<p>&nbsp;<\/p>\n<p>A cria\u00e7\u00e3o do CCD-ERCF contou com um aporte governamental de R$ 32 milh\u00f5es. A Funda\u00e7\u00e3o de Amparo \u00e0 Pesquisa do Estado de S\u00e3o Paulo (Fapesp) financia R$ 9 milh\u00f5es desse montante; o IPT e a Secretaria de Meio Ambiente, Infraestrutura e Log\u00edstica (Semil) contribuem com R$ 11 milh\u00f5es; e a Secretaria de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o do Estado de S\u00e3o Paulo aporta mais R$ 12 milh\u00f5es em recursos financeiros.<\/p>\n<p>&nbsp;<\/p>\n<p>O Governo de SP informou que o novo centro de pesquisas avaliar\u00e1 diferentes aspectos da produ\u00e7\u00e3o, armazenamento, transporte, distribui\u00e7\u00e3o, uso e regulamenta\u00e7\u00e3o do hidrog\u00eanio de baixo carbono. Dessa forma, os trabalhos no CCD ter\u00e3o apoio t\u00e9cnico da Semil e da Fapesp, sob coordena\u00e7\u00e3o do IPT.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Estamos em um momento crucial para investir na pesquisa e no desenvolvimento de tecnologias que far\u00e3o parte da estrat\u00e9gia de mitiga\u00e7\u00e3o das na\u00e7\u00f5es rumo \u00e0 neutralidade de carbono&#8221;, afirma Marisa Barros, subsecret\u00e1ria de Energia e Minera\u00e7\u00e3o da Semil.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Hidrog\u00eanio de baixo carbono<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>O hidrog\u00eanio de baixo carbono resulta de um processo que gera baixo impacto ambiental. Ou seja, com uma quantidade reduzida de emiss\u00f5es de gases de efeito estufa durante sua produ\u00e7\u00e3o. Especialistas consideram esse combust\u00edvel uma das solu\u00e7\u00f5es para a descarboniza\u00e7\u00e3o, com aplica\u00e7\u00f5es que v\u00e3o desde a gera\u00e7\u00e3o de eletricidade at\u00e9 o uso em processos industriais e no transporte.<\/p>\n<p>&nbsp;<\/p>\n<p>Existem diferentes formas de produzir o hidrog\u00eanio de baixo carbono, classificadas por cores, sendo as principais: verde, azul e turquesa.<\/p>\n<p>&nbsp;<\/p>\n<p>O hidrog\u00eanio &#8220;verde&#8221; resulta da eletr\u00f3lise da \u00e1gua, utilizando energia de fontes renov\u00e1veis, como solar ou e\u00f3lica. Esse processo n\u00e3o emite CO2, tornando-o o hidrog\u00eanio de menor impacto ambiental. Obt\u00e9m-se o hidrog\u00eanio &#8220;azul&#8221; a partir de g\u00e1s natural, enquanto o &#8220;turquesa&#8221; vem do metano, ambos com captura e armazenamento de carbono.<\/p>\n<p>&nbsp;<\/p>\n<p>H\u00e1 outras \u201ccores\u201d que se referem a diferentes m\u00e9todos de produ\u00e7\u00e3o de hidrog\u00eanio e ao impacto ambiental associado a cada processo. Por exemplo, produz-se o hidrog\u00eanio \u201ccinza\u201d tamb\u00e9m com g\u00e1s natural, mas sem a captura de carbono. J\u00e1 o hidrog\u00eanio \u201cmarrom\u201d ou \u201cpreto\u201d, que emite grandes volumes de CO\u2082, vem do carv\u00e3o. (Estrad\u00e3o\/Thiago Vinholes)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estrad\u00e3o &nbsp; O Governo do Estado de S\u00e3o Paulo inaugurou o Centro de Ci\u00eancias para o Desenvolvimento de Energias Renov\u00e1veis e Combust\u00edveis do Futuro (CCD &#8211; ERCF), no Instituto de Pesquisas Tecnol\u00f3gicas (IPT), em S\u00e3o Paulo. De acordo com o governo paulista, o principal objetivo do novo centro \u00e9 estudar o uso do hidrog\u00eanio de\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-78075","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo de SP investe em novo centro para produ\u00e7\u00e3o de hidrog\u00eanio - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo de SP investe em novo centro para produ\u00e7\u00e3o de hidrog\u00eanio - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Estrad\u00e3o &nbsp; O Governo do Estado de S\u00e3o Paulo inaugurou o Centro de Ci\u00eancias para o Desenvolvimento de Energias Renov\u00e1veis e Combust\u00edveis do Futuro (CCD &#8211; ERCF), no Instituto de Pesquisas Tecnol\u00f3gicas (IPT), em S\u00e3o Paulo. De acordo com o governo paulista, o principal objetivo do novo centro \u00e9 estudar o uso do hidrog\u00eanio de\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-25T12:23:14+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/25\\\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/25\\\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Governo de SP investe em novo centro para produ\u00e7\u00e3o de hidrog\u00eanio\",\"datePublished\":\"2024-11-25T12:23:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/25\\\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\\\/\"},\"wordCount\":472,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/25\\\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/25\\\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\\\/\",\"name\":\"Governo de SP investe em novo centro para produ\u00e7\u00e3o de hidrog\u00eanio - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2024-11-25T12:23:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/25\\\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/25\\\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/25\\\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Governo de SP investe em novo centro para produ\u00e7\u00e3o de hidrog\u00eanio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo de SP investe em novo centro para produ\u00e7\u00e3o de hidrog\u00eanio - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo de SP investe em novo centro para produ\u00e7\u00e3o de hidrog\u00eanio - Canal Dana","og_description":"Estrad\u00e3o &nbsp; O Governo do Estado de S\u00e3o Paulo inaugurou o Centro de Ci\u00eancias para o Desenvolvimento de Energias Renov\u00e1veis e Combust\u00edveis do Futuro (CCD &#8211; ERCF), no Instituto de Pesquisas Tecnol\u00f3gicas (IPT), em S\u00e3o Paulo. De acordo com o governo paulista, o principal objetivo do novo centro \u00e9 estudar o uso do hidrog\u00eanio de\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/","og_site_name":"Canal Dana","article_published_time":"2024-11-25T12:23:14+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Governo de SP investe em novo centro para produ\u00e7\u00e3o de hidrog\u00eanio","datePublished":"2024-11-25T12:23:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/"},"wordCount":472,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/","url":"https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/","name":"Governo de SP investe em novo centro para produ\u00e7\u00e3o de hidrog\u00eanio - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2024-11-25T12:23:14+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/25\/governo-de-sp-investe-em-novo-centro-para-producao-de-hidrogenio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Governo de SP investe em novo centro para produ\u00e7\u00e3o de hidrog\u00eanio"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/78075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=78075"}],"version-history":[{"count":1,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/78075\/revisions"}],"predecessor-version":[{"id":78076,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/78075\/revisions\/78076"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=78075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=78075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=78075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}