{"id":77790,"date":"2024-11-11T08:29:36","date_gmt":"2024-11-11T11:29:36","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=77790"},"modified":"2024-11-11T08:29:36","modified_gmt":"2024-11-11T11:29:36","slug":"vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/","title":{"rendered":"Vendas em alta de caminh\u00f5es e \u00f4nibus evidenciam o bom momento do setor"},"content":{"rendered":"<p><em>Frota &amp; Cia <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>A Anfavea, que re\u00fane os fabricantes de ve\u00edculos, divulgou os dados consolidados do mercado de ve\u00edculos comerciais at\u00e9 o m\u00eas de outubro. Os licenciamentos de caminh\u00f5es somaram 103,3 mil unidades no per\u00edodo, evidenciando uma alta de 16,8% frente \u00e0s 88,5 mil unidades de igual per\u00edodo do ano anterior. Da mesma forma, os emplacamentos de chassis de \u00f4nibus mostraram uma evolu\u00e7\u00e3o de 5,6% nos dez primeiros meses no ano, com 18.336 unidades apontadas no Renavam em 2024, ante 17.370 registradas em 2023.<\/p>\n<p>&nbsp;<\/p>\n<p>J\u00e1 a produ\u00e7\u00e3o das f\u00e1bricas, considerando as vendas ao mercado interno somadas com as exporta\u00e7\u00f5es alcan\u00e7aram resultados ainda mais expressivos. Do lado dos caminh\u00f5es, a produ\u00e7\u00e3o alcan\u00e7ou a marca de 117,4 mil unidades em 2024, o que equivale a um incremento da ordem de 42,8% na compara\u00e7\u00e3o com as 82,2 mil unidades contabilizadas nos dez primeiros meses de 2023. A produ\u00e7\u00e3o de chassis de \u00f4nibus, por sua vez, somou 23.711 unidades, ou 35,3% a mais que as 17,4 mil do ano anterior.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Incrementos<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Os n\u00fameros revelam o momento do mercado de caminh\u00f5es e \u00f4nibus, que podem sofrer um incremento ainda maior em fun\u00e7\u00e3o da realiza\u00e7\u00e3o das duas principais feiras desses setores: a LatBus realizada em agosto desse ano e a Fenatran 2024, que acontece essa semana em S\u00e3o Paulo.<\/p>\n<p>&nbsp;<\/p>\n<p>Na vis\u00e3o de Eduardo Freitas, vice-presidente da Anfavea, o aumento da demanda de caminh\u00f5es reflete o crescimento do PIB brasileiro e a boa aceita\u00e7\u00e3o dos ve\u00edculos Euro 6. J\u00e1 a produ\u00e7\u00e3o de chassis de \u00f4nibus mostra que o setor est\u00e1 vivendo um momento especial, diante a recupera\u00e7\u00e3o dos operadores p\u00f3s-pandemia. E, tamb\u00e9m, as entregas para o Programa Caminho da Escola, que seguem em ritmo acelerado. (Frota &amp; Cia\/Jos\u00e9 Augusto Ferraz)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frota &amp; Cia &nbsp; A Anfavea, que re\u00fane os fabricantes de ve\u00edculos, divulgou os dados consolidados do mercado de ve\u00edculos comerciais at\u00e9 o m\u00eas de outubro. Os licenciamentos de caminh\u00f5es somaram 103,3 mil unidades no per\u00edodo, evidenciando uma alta de 16,8% frente \u00e0s 88,5 mil unidades de igual per\u00edodo do ano anterior. Da mesma forma,\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-77790","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vendas em alta de caminh\u00f5es e \u00f4nibus evidenciam o bom momento do setor - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vendas em alta de caminh\u00f5es e \u00f4nibus evidenciam o bom momento do setor - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Frota &amp; Cia &nbsp; A Anfavea, que re\u00fane os fabricantes de ve\u00edculos, divulgou os dados consolidados do mercado de ve\u00edculos comerciais at\u00e9 o m\u00eas de outubro. Os licenciamentos de caminh\u00f5es somaram 103,3 mil unidades no per\u00edodo, evidenciando uma alta de 16,8% frente \u00e0s 88,5 mil unidades de igual per\u00edodo do ano anterior. Da mesma forma,\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-11T11:29:36+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/11\\\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/11\\\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Vendas em alta de caminh\u00f5es e \u00f4nibus evidenciam o bom momento do setor\",\"datePublished\":\"2024-11-11T11:29:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/11\\\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\\\/\"},\"wordCount\":315,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/11\\\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/11\\\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\\\/\",\"name\":\"Vendas em alta de caminh\u00f5es e \u00f4nibus evidenciam o bom momento do setor - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2024-11-11T11:29:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/11\\\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/11\\\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/11\\\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vendas em alta de caminh\u00f5es e \u00f4nibus evidenciam o bom momento do setor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vendas em alta de caminh\u00f5es e \u00f4nibus evidenciam o bom momento do setor - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Vendas em alta de caminh\u00f5es e \u00f4nibus evidenciam o bom momento do setor - Canal Dana","og_description":"Frota &amp; Cia &nbsp; A Anfavea, que re\u00fane os fabricantes de ve\u00edculos, divulgou os dados consolidados do mercado de ve\u00edculos comerciais at\u00e9 o m\u00eas de outubro. Os licenciamentos de caminh\u00f5es somaram 103,3 mil unidades no per\u00edodo, evidenciando uma alta de 16,8% frente \u00e0s 88,5 mil unidades de igual per\u00edodo do ano anterior. Da mesma forma,\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/","og_site_name":"Canal Dana","article_published_time":"2024-11-11T11:29:36+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Vendas em alta de caminh\u00f5es e \u00f4nibus evidenciam o bom momento do setor","datePublished":"2024-11-11T11:29:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/"},"wordCount":315,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/","url":"https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/","name":"Vendas em alta de caminh\u00f5es e \u00f4nibus evidenciam o bom momento do setor - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2024-11-11T11:29:36+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/11\/vendas-em-alta-de-caminhoes-e-onibus-evidenciam-o-bom-momento-do-setor-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Vendas em alta de caminh\u00f5es e \u00f4nibus evidenciam o bom momento do setor"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/77790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=77790"}],"version-history":[{"count":1,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/77790\/revisions"}],"predecessor-version":[{"id":77791,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/77790\/revisions\/77791"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=77790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=77790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=77790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}