{"id":77754,"date":"2024-11-08T08:48:14","date_gmt":"2024-11-08T11:48:14","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=77754"},"modified":"2024-11-08T08:48:14","modified_gmt":"2024-11-08T11:48:14","slug":"demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/","title":{"rendered":"Demanda por projetos de biocombust\u00edveis supera em 30 vezes pr\u00e9via do BNDES"},"content":{"rendered":"<p><em>O Estado de S. Paulo<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>A demanda por recursos para o desenvolvimento de projetos de biocombust\u00edveis a taxas subsidiadas atingiu quase 30 vezes o valor anunciado na chamada p\u00fablica feita pelo Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES) e pela Financiadora de Estudos e Projetos (Finep). Com valor inicial de R$ 6 bilh\u00f5es, a chamada teve demanda para desenvolvimento de combust\u00edvel sustent\u00e1vel de avia\u00e7\u00e3o (SAF, na sigla em ingl\u00eas) e de \u201cbunker\u201d verde (combust\u00edvel para navios com biodiesel) de R$ 167 bilh\u00f5es, em 76 projetos. Do total, 43 propostas s\u00e3o de produ\u00e7\u00e3o de combust\u00edveis de avia\u00e7\u00e3o, somando R$ 120 bilh\u00f5es, t\u00eam por objetivo desenvolver os de navega\u00e7\u00e3o. Agora, o banco vai avali\u00e1-las e decidir, at\u00e9 o fim do ano, quais ser\u00e3o eleg\u00edveis e os instrumentos de financiamento. (O Estado de S. Paulo)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Estado de S. Paulo &nbsp; A demanda por recursos para o desenvolvimento de projetos de biocombust\u00edveis a taxas subsidiadas atingiu quase 30 vezes o valor anunciado na chamada p\u00fablica feita pelo Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES) e pela Financiadora de Estudos e Projetos (Finep). Com valor inicial de R$ 6 bilh\u00f5es,\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-77754","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Demanda por projetos de biocombust\u00edveis supera em 30 vezes pr\u00e9via do BNDES - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Demanda por projetos de biocombust\u00edveis supera em 30 vezes pr\u00e9via do BNDES - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"O Estado de S. Paulo &nbsp; A demanda por recursos para o desenvolvimento de projetos de biocombust\u00edveis a taxas subsidiadas atingiu quase 30 vezes o valor anunciado na chamada p\u00fablica feita pelo Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES) e pela Financiadora de Estudos e Projetos (Finep). Com valor inicial de R$ 6 bilh\u00f5es,\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-08T11:48:14+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/08\\\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/08\\\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Demanda por projetos de biocombust\u00edveis supera em 30 vezes pr\u00e9via do BNDES\",\"datePublished\":\"2024-11-08T11:48:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/08\\\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\\\/\"},\"wordCount\":161,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/08\\\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/08\\\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\\\/\",\"name\":\"Demanda por projetos de biocombust\u00edveis supera em 30 vezes pr\u00e9via do BNDES - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2024-11-08T11:48:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/08\\\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/08\\\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/11\\\/08\\\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Demanda por projetos de biocombust\u00edveis supera em 30 vezes pr\u00e9via do BNDES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Demanda por projetos de biocombust\u00edveis supera em 30 vezes pr\u00e9via do BNDES - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/","og_locale":"pt_BR","og_type":"article","og_title":"Demanda por projetos de biocombust\u00edveis supera em 30 vezes pr\u00e9via do BNDES - Canal Dana","og_description":"O Estado de S. Paulo &nbsp; A demanda por recursos para o desenvolvimento de projetos de biocombust\u00edveis a taxas subsidiadas atingiu quase 30 vezes o valor anunciado na chamada p\u00fablica feita pelo Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES) e pela Financiadora de Estudos e Projetos (Finep). Com valor inicial de R$ 6 bilh\u00f5es,\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/","og_site_name":"Canal Dana","article_published_time":"2024-11-08T11:48:14+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Demanda por projetos de biocombust\u00edveis supera em 30 vezes pr\u00e9via do BNDES","datePublished":"2024-11-08T11:48:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/"},"wordCount":161,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/","url":"https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/","name":"Demanda por projetos de biocombust\u00edveis supera em 30 vezes pr\u00e9via do BNDES - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2024-11-08T11:48:14+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2024\/11\/08\/demanda-por-projetos-de-biocombustiveis-supera-em-30-vezes-previa-do-bndes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Demanda por projetos de biocombust\u00edveis supera em 30 vezes pr\u00e9via do BNDES"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/77754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=77754"}],"version-history":[{"count":1,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/77754\/revisions"}],"predecessor-version":[{"id":77755,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/77754\/revisions\/77755"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=77754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=77754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=77754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}