{"id":74482,"date":"2024-06-27T08:42:44","date_gmt":"2024-06-27T11:42:44","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=74482"},"modified":"2024-06-27T08:42:44","modified_gmt":"2024-06-27T11:42:44","slug":"com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/","title":{"rendered":"Com facelift \u00e0 vista, Volkswagen Amarok 2024 tem R$ 35 mil de desconto"},"content":{"rendered":"<p><em>Motor 1 <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Volkswagen est\u00e1 com condi\u00e7\u00f5es especiais de compra para interessados em fechar neg\u00f3cio na picape Amarok agora em junho. At\u00e9 o pr\u00f3ximo dia 30, revela a marca em seu site de ofertas, a vers\u00e3o Highline 2024\/2024 da caminhonete poder\u00e1 ser adquirida com generoso desconto sobre o pre\u00e7o de tabela e financiamento sem juros.<\/p>\n<p>&nbsp;<\/p>\n<p>Tabelada em R$ 319.290, a Amarok Highline poder\u00e1 ser comprada at\u00e9 o final do m\u00eas por R$ 284.290 \u00e0 vista, o que representa desconto de R$ 35.000 sobre os valores oficiais. Al\u00e9m disso, o cliente poder\u00e1 financiar a picape no plano com entrada de R$ 142.145,00 (50%) e saldo dividido em 24 presta\u00e7\u00f5es mensais de R$ 6.125,08, sem juros. O valor final fica em R$ 289.147,03, com taxas.<\/p>\n<p>&nbsp;<\/p>\n<p>De s\u00e9rie, a Amarok Highline 2024 oferece c\u00e2mera de r\u00e9, retrovisor interno eletrocr\u00f4mico, volante com ajuste de altura e profundidade, piloto autom\u00e1tico, controle eletr\u00f4nico de estabilidade, airbags frontais e laterais, far\u00f3is bix\u00eanon com luz de condu\u00e7\u00e3o diurna em LED, sensor de chuva, sistema multim\u00eddia Discover Media, far\u00f3is de neblina, ar-condicionado digital de duas zonas, rodas de 18 polegadas e outros.<\/p>\n<p>&nbsp;<\/p>\n<p>Sob o cap\u00f4, o motor V6 3.0 turbodiesel entrega 258 cv de pot\u00eancia a 3.250 rpm e 59,1 kgfm de torque a 1.400 rpm. A transmiss\u00e3o \u00e9 sempre autom\u00e1tica de 8 marchas, enquanto a tra\u00e7\u00e3o \u00e9 integral 4Motion.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Facelift \u00e0 vista<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>A oferta de condi\u00e7\u00f5es especiais de compra coincide com o lan\u00e7amento da reestiliza\u00e7\u00e3o de meia-vida da Amarok. O modelo produzido em Pacheco, na Argentina, ser\u00e1 renovado ainda neste ano e acabar\u00e1 por compensar a aus\u00eancia da Amarok de nova gera\u00e7\u00e3o por aqui. Como j\u00e1 dito, a linhagem renovada &#8211; e agora baseada na Ford Ranger &#8211; n\u00e3o ser\u00e1 lan\u00e7ada em mercados da Am\u00e9rica do Sul.<\/p>\n<p>&nbsp;<\/p>\n<p>Aqui, a velha Amarok ser\u00e1 renovada e seguir\u00e1 em linha por pelo menos mais 10 anos. Ganhar\u00e1 dianteira atualizada, ter\u00e1 equipamentos adicionais no interior e modificar\u00e1 o desenho interno das lanternas na traseira. Mecanicamente, n\u00e3o ter\u00e1 mudan\u00e7as. (Motor 1\/Dyogo Fagundes)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Motor 1 &nbsp; Volkswagen est\u00e1 com condi\u00e7\u00f5es especiais de compra para interessados em fechar neg\u00f3cio na picape Amarok agora em junho. At\u00e9 o pr\u00f3ximo dia 30, revela a marca em seu site de ofertas, a vers\u00e3o Highline 2024\/2024 da caminhonete poder\u00e1 ser adquirida com generoso desconto sobre o pre\u00e7o de tabela e financiamento sem juros.\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-74482","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Com facelift \u00e0 vista, Volkswagen Amarok 2024 tem R$ 35 mil de desconto - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Com facelift \u00e0 vista, Volkswagen Amarok 2024 tem R$ 35 mil de desconto - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Motor 1 &nbsp; Volkswagen est\u00e1 com condi\u00e7\u00f5es especiais de compra para interessados em fechar neg\u00f3cio na picape Amarok agora em junho. At\u00e9 o pr\u00f3ximo dia 30, revela a marca em seu site de ofertas, a vers\u00e3o Highline 2024\/2024 da caminhonete poder\u00e1 ser adquirida com generoso desconto sobre o pre\u00e7o de tabela e financiamento sem juros.\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-27T11:42:44+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/06\\\/27\\\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/06\\\/27\\\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Com facelift \u00e0 vista, Volkswagen Amarok 2024 tem R$ 35 mil de desconto\",\"datePublished\":\"2024-06-27T11:42:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/06\\\/27\\\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\\\/\"},\"wordCount\":353,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/06\\\/27\\\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/06\\\/27\\\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\\\/\",\"name\":\"Com facelift \u00e0 vista, Volkswagen Amarok 2024 tem R$ 35 mil de desconto - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2024-06-27T11:42:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/06\\\/27\\\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/06\\\/27\\\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2024\\\/06\\\/27\\\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Com facelift \u00e0 vista, Volkswagen Amarok 2024 tem R$ 35 mil de desconto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Com facelift \u00e0 vista, Volkswagen Amarok 2024 tem R$ 35 mil de desconto - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/","og_locale":"pt_BR","og_type":"article","og_title":"Com facelift \u00e0 vista, Volkswagen Amarok 2024 tem R$ 35 mil de desconto - Canal Dana","og_description":"Motor 1 &nbsp; Volkswagen est\u00e1 com condi\u00e7\u00f5es especiais de compra para interessados em fechar neg\u00f3cio na picape Amarok agora em junho. At\u00e9 o pr\u00f3ximo dia 30, revela a marca em seu site de ofertas, a vers\u00e3o Highline 2024\/2024 da caminhonete poder\u00e1 ser adquirida com generoso desconto sobre o pre\u00e7o de tabela e financiamento sem juros.\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/","og_site_name":"Canal Dana","article_published_time":"2024-06-27T11:42:44+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Com facelift \u00e0 vista, Volkswagen Amarok 2024 tem R$ 35 mil de desconto","datePublished":"2024-06-27T11:42:44+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/"},"wordCount":353,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/","url":"https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/","name":"Com facelift \u00e0 vista, Volkswagen Amarok 2024 tem R$ 35 mil de desconto - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2024-06-27T11:42:44+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2024\/06\/27\/com-facelift-a-vista-volkswagen-amarok-2024-tem-r-35-mil-de-desconto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Com facelift \u00e0 vista, Volkswagen Amarok 2024 tem R$ 35 mil de desconto"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/74482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=74482"}],"version-history":[{"count":2,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/74482\/revisions"}],"predecessor-version":[{"id":74484,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/74482\/revisions\/74484"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=74482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=74482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=74482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}