{"id":62049,"date":"2022-11-07T09:34:18","date_gmt":"2022-11-07T12:34:18","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=62049"},"modified":"2022-11-07T09:34:18","modified_gmt":"2022-11-07T12:34:18","slug":"iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/","title":{"rendered":"Iveco eleva o patamar de oferta com lan\u00e7amento do S-Way"},"content":{"rendered":"<p><em>AutoInd\u00fastria <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>A Iveco reuniu na noite da \u00faltima quinta-feira, 3, em Belo Horizonte (MG), uma multid\u00e3o de parceiros e clientes para festejar a chegada do S-Way. Afinal, como definiu Marcio Querichelli, presidente da Iveco para Am\u00e9rica Latina, em sua apresenta\u00e7\u00e3o, \u201co caminh\u00e3o \u00e9 o mais tecnol\u00f3gico do portf\u00f3lio.\u201d\u00a0 O modelo ser\u00e1 a estrela da Fenatran 2022 e antecipa as novidades da fabricante para atender ao Proconve P8, a partir de janeiro de 2023.<\/p>\n<p>&nbsp;<\/p>\n<p>O modelo chega com pretens\u00f5es claras. Pelo porte, acabamento, recursos e capacidades, o S-Way re\u00fane atributos para atrair olhares em faixa de atua\u00e7\u00e3o na qual rivais tradicionais do mercado de pesados se sobressaem em lista de mais vendidos.<\/p>\n<p>&nbsp;<\/p>\n<p>Com o S-Way, a Iveco come\u00e7a atender a um p\u00fablico transportador exigente, que cobra por desempenho, grande capacidade de carga e menores custos operacionais em rotas de longas dist\u00e2ncias rodovi\u00e1rias. Al\u00e9m de suporte capaz de garantir disponibilidade e ferramentas de gest\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Para colocar o S-Way em produ\u00e7\u00e3o na f\u00e1brica de Sete Lagoas (MG), a Iveco investiu parte do R$ 1 bilh\u00e3o para a regi\u00e3o, anunciado no in\u00edcio de 2022, para o per\u00edodo de 2022-2025. O desenvolvimento, no entanto, demandou tr\u00eas anos, per\u00edodo no qual a engenharia utilizou 70 prot\u00f3tipos e rodou mais 2,5 milh\u00f5es de quil\u00f4metros em testes. \u201cFoi o pesado mais teste no mercado brasileiro, tr\u00eas vezes mais que o habitual\u201d, contou Querichelli.<\/p>\n<p>&nbsp;<\/p>\n<p>O resultado comp\u00f4s uma linha de tr\u00eas vers\u00f5es com motores Cursor 13 da FPT com 450 cv, 480 cv e 540 cv nas configura\u00e7\u00f5es 4\u00d72, 6\u00d72 e 6\u00d74, todos associados \u00e0 caixa de transmiss\u00e3o Traxxon, da ZF. Os conjuntos, de acordo com a marca, chegam para entregar at\u00e9 15% de economia de combust\u00edvel se comparados \u00e0 gera\u00e7\u00e3o anterior de caminh\u00f5es pesados da marca.<\/p>\n<p>&nbsp;<\/p>\n<p>O S-Way ainda traz ainda recursos de seguran\u00e7a ativa semiaut\u00f4noma do pacote conhecido como ADAS, no qual a intelig\u00eancia eletr\u00f4nica alerta e identifica faixa de rodagem e obst\u00e1culo, al\u00e9m de ser capaz de fazer frenagens at\u00e9 a imobilidade.<\/p>\n<p>&nbsp;<\/p>\n<p>Na esteira do lan\u00e7amento, a conectividade ganhou relev\u00e2ncia com o Easy Way, aplicativo que permite controle sobre o ve\u00edculo, bem como atualiza softwares embarcados, presta socorro em assist\u00eancia t\u00e9cnica e ajuda o motorista a aproveitar todo o potencial do caminh\u00e3o. A ferramenta ainda \u00e9 associada a sala de controle de equipe de p\u00f3s-venda da marca, o que garante ao transportador apoio na gest\u00e3o da frota.<\/p>\n<p>&nbsp;<\/p>\n<p>A oferta do S-Way disp\u00f5e de quatro pacotes, concebida de acordo com prioridades do transportador: Standard, Confort, Tech e Safety. Segundo a marca, por\u00e9m, com o aux\u00edlio de 25 acess\u00f3rios dispon\u00edveis, o S-Way permite at\u00e9 1 mil combina\u00e7\u00f5es. (AutoInd\u00fastria\/D\u00e9cio Costa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AutoInd\u00fastria &nbsp; A Iveco reuniu na noite da \u00faltima quinta-feira, 3, em Belo Horizonte (MG), uma multid\u00e3o de parceiros e clientes para festejar a chegada do S-Way. Afinal, como definiu Marcio Querichelli, presidente da Iveco para Am\u00e9rica Latina, em sua apresenta\u00e7\u00e3o, \u201co caminh\u00e3o \u00e9 o mais tecnol\u00f3gico do portf\u00f3lio.\u201d\u00a0 O modelo ser\u00e1 a estrela da\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-62049","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Iveco eleva o patamar de oferta com lan\u00e7amento do S-Way - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iveco eleva o patamar de oferta com lan\u00e7amento do S-Way - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"AutoInd\u00fastria &nbsp; A Iveco reuniu na noite da \u00faltima quinta-feira, 3, em Belo Horizonte (MG), uma multid\u00e3o de parceiros e clientes para festejar a chegada do S-Way. Afinal, como definiu Marcio Querichelli, presidente da Iveco para Am\u00e9rica Latina, em sua apresenta\u00e7\u00e3o, \u201co caminh\u00e3o \u00e9 o mais tecnol\u00f3gico do portf\u00f3lio.\u201d\u00a0 O modelo ser\u00e1 a estrela da\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-07T12:34:18+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/11\\\/07\\\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/11\\\/07\\\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Iveco eleva o patamar de oferta com lan\u00e7amento do S-Way\",\"datePublished\":\"2022-11-07T12:34:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/11\\\/07\\\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\\\/\"},\"wordCount\":488,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/11\\\/07\\\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/11\\\/07\\\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\\\/\",\"name\":\"Iveco eleva o patamar de oferta com lan\u00e7amento do S-Way - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2022-11-07T12:34:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/11\\\/07\\\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/11\\\/07\\\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/11\\\/07\\\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Iveco eleva o patamar de oferta com lan\u00e7amento do S-Way\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iveco eleva o patamar de oferta com lan\u00e7amento do S-Way - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/","og_locale":"pt_BR","og_type":"article","og_title":"Iveco eleva o patamar de oferta com lan\u00e7amento do S-Way - Canal Dana","og_description":"AutoInd\u00fastria &nbsp; A Iveco reuniu na noite da \u00faltima quinta-feira, 3, em Belo Horizonte (MG), uma multid\u00e3o de parceiros e clientes para festejar a chegada do S-Way. Afinal, como definiu Marcio Querichelli, presidente da Iveco para Am\u00e9rica Latina, em sua apresenta\u00e7\u00e3o, \u201co caminh\u00e3o \u00e9 o mais tecnol\u00f3gico do portf\u00f3lio.\u201d\u00a0 O modelo ser\u00e1 a estrela da\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/","og_site_name":"Canal Dana","article_published_time":"2022-11-07T12:34:18+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Iveco eleva o patamar de oferta com lan\u00e7amento do S-Way","datePublished":"2022-11-07T12:34:18+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/"},"wordCount":488,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/","url":"https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/","name":"Iveco eleva o patamar de oferta com lan\u00e7amento do S-Way - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2022-11-07T12:34:18+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2022\/11\/07\/iveco-eleva-o-patamar-de-oferta-com-lancamento-do-s-way\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Iveco eleva o patamar de oferta com lan\u00e7amento do S-Way"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/62049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=62049"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/62049\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=62049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=62049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=62049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}