{"id":59037,"date":"2022-06-20T08:49:16","date_gmt":"2022-06-20T11:49:16","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=59037"},"modified":"2022-06-20T08:49:16","modified_gmt":"2022-06-20T11:49:16","slug":"mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/","title":{"rendered":"Mercado equatoriano fechou o m\u00eas de maio com evolu\u00e7\u00e3o de vendas de caminh\u00f5es e \u00f4nibus"},"content":{"rendered":"<p><em>Truck &amp; Bus Builder Am\u00e9rica do Sul<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>O mercado equatoriano de ve\u00edculos comerciais registrou crescimento de 16,06%, com a venda de 961 unidades, contra 828 no mesmo m\u00eas de 2021. Segundo a AEADE (Associa\u00e7\u00e3o das Empresas Automotrizes do Equador), em maio deste ano, foram 896 caminh\u00f5es, com crescimento de 12,0% sobre as 800 unidades comercializadas no mesmo m\u00eas de 2021, e 65 \u00f4nibus vendidos, com evolu\u00e7\u00e3o de 132,14% sobre os 28 ve\u00edculos do mesmo m\u00eas do ano passado.<\/p>\n<p>&nbsp;<\/p>\n<p>No acumulado dos cinco primeiros meses deste ano foram vendidos 4.842 ve\u00edculos comerciais, 21,23% acima das 3.994 unidades vendidas no mesmo per\u00edodo de 2021. Em caminh\u00f5es, o aumento foi de 17,92%, com 4.592 unidades, contra 3.894 unidades no mesmo per\u00edodo de 2021. Em \u00f4nibus, o crescimento foi maior, com a venda de 250 unidades e 150% de eleva\u00e7\u00e3o em rela\u00e7\u00e3o \u00e0s 100 unidades comercializadas de janeiro a maio de 2021.<\/p>\n<p>&nbsp;<\/p>\n<p>Segundo a AEADE o resultado \u00e9 consequ\u00eancia do aumento do n\u00edvel de confian\u00e7a do mercado e dos empres\u00e1rios, acrescida pelo retorno gradativo da normalidade das atividades com a menor preocupa\u00e7\u00e3o com a pandemia da covid -19.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre as marcas, a japonesa Hino manteve a lideran\u00e7a de vendas com 264 ve\u00edculos vendidos em maio e 1.189 unidades comercializadas nos cinco primeiros meses deste ano.<\/p>\n<p>&nbsp;<\/p>\n<p>A JAC ficou em segundo lugar, com a venda de 169 unidades, em maio, e de 900 ve\u00edculos no acumulado do ano, seguida pela Chevrolet, com 114 unidades em maio e 778 nos cinco primeiros meses de 2022.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Venda de ve\u00edculos comerciais<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Marca &#8211; maio &#8211; Janeiro\/Maio\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>1 \u2013 Hino &#8211; 264 &#8211; 1.189<\/p>\n<p>2 \u2013 JAC &#8211; 169 &#8211; 900<\/p>\n<p>3 \u2013 Chevrolet &#8211; 114 &#8211; 778<\/p>\n<p>4 \u2013 Shineray &#8211; 94 &#8211; 547<\/p>\n<p>5 \u2013 Sinotruk &#8211; 136 &#8211; 537<\/p>\n<p>6 \u2013 JMC &#8211; 68 &#8211; 365<\/p>\n<p>7 \u2013 DFSK &#8211; 92 &#8211; 347<\/p>\n<p>8 \u2013 Foton &#8211; 54 &#8211; 325<\/p>\n<p>9 \u2013 Hyundai &#8211; 77 &#8211; 271<\/p>\n<p>10 \u2013 Kerry &#8211; 20 &#8211; 231<\/p>\n<p>(Truck &amp; Bus Builder Am\u00e9rica do Sul)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Truck &amp; Bus Builder Am\u00e9rica do Sul &nbsp; O mercado equatoriano de ve\u00edculos comerciais registrou crescimento de 16,06%, com a venda de 961 unidades, contra 828 no mesmo m\u00eas de 2021. Segundo a AEADE (Associa\u00e7\u00e3o das Empresas Automotrizes do Equador), em maio deste ano, foram 896 caminh\u00f5es, com crescimento de 12,0% sobre as 800 unidades\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-59037","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercado equatoriano fechou o m\u00eas de maio com evolu\u00e7\u00e3o de vendas de caminh\u00f5es e \u00f4nibus - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercado equatoriano fechou o m\u00eas de maio com evolu\u00e7\u00e3o de vendas de caminh\u00f5es e \u00f4nibus - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Truck &amp; Bus Builder Am\u00e9rica do Sul &nbsp; O mercado equatoriano de ve\u00edculos comerciais registrou crescimento de 16,06%, com a venda de 961 unidades, contra 828 no mesmo m\u00eas de 2021. Segundo a AEADE (Associa\u00e7\u00e3o das Empresas Automotrizes do Equador), em maio deste ano, foram 896 caminh\u00f5es, com crescimento de 12,0% sobre as 800 unidades\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-20T11:49:16+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Mercado equatoriano fechou o m\u00eas de maio com evolu\u00e7\u00e3o de vendas de caminh\u00f5es e \u00f4nibus\",\"datePublished\":\"2022-06-20T11:49:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\\\/\"},\"wordCount\":315,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\\\/\",\"name\":\"Mercado equatoriano fechou o m\u00eas de maio com evolu\u00e7\u00e3o de vendas de caminh\u00f5es e \u00f4nibus - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2022-06-20T11:49:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mercado equatoriano fechou o m\u00eas de maio com evolu\u00e7\u00e3o de vendas de caminh\u00f5es e \u00f4nibus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercado equatoriano fechou o m\u00eas de maio com evolu\u00e7\u00e3o de vendas de caminh\u00f5es e \u00f4nibus - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/","og_locale":"pt_BR","og_type":"article","og_title":"Mercado equatoriano fechou o m\u00eas de maio com evolu\u00e7\u00e3o de vendas de caminh\u00f5es e \u00f4nibus - Canal Dana","og_description":"Truck &amp; Bus Builder Am\u00e9rica do Sul &nbsp; O mercado equatoriano de ve\u00edculos comerciais registrou crescimento de 16,06%, com a venda de 961 unidades, contra 828 no mesmo m\u00eas de 2021. Segundo a AEADE (Associa\u00e7\u00e3o das Empresas Automotrizes do Equador), em maio deste ano, foram 896 caminh\u00f5es, com crescimento de 12,0% sobre as 800 unidades\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/","og_site_name":"Canal Dana","article_published_time":"2022-06-20T11:49:16+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Mercado equatoriano fechou o m\u00eas de maio com evolu\u00e7\u00e3o de vendas de caminh\u00f5es e \u00f4nibus","datePublished":"2022-06-20T11:49:16+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/"},"wordCount":315,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/","url":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/","name":"Mercado equatoriano fechou o m\u00eas de maio com evolu\u00e7\u00e3o de vendas de caminh\u00f5es e \u00f4nibus - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2022-06-20T11:49:16+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/mercado-equatoriano-fechou-o-mes-de-maio-com-evolucao-de-vendas-de-caminhoes-e-onibus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Mercado equatoriano fechou o m\u00eas de maio com evolu\u00e7\u00e3o de vendas de caminh\u00f5es e \u00f4nibus"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/59037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=59037"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/59037\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=59037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=59037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=59037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}