{"id":59035,"date":"2022-06-20T08:48:21","date_gmt":"2022-06-20T11:48:21","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=59035"},"modified":"2022-06-20T08:48:21","modified_gmt":"2022-06-20T11:48:21","slug":"transporte-publico-acesso-ou-bloqueio","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/","title":{"rendered":"Transporte p\u00fablico: acesso ou bloqueio?"},"content":{"rendered":"<p><em>O Estado de S. Paulo<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>J\u00e1 virou lugar-comum afirmar que a pandemia levou o transporte p\u00fablico \u00e0 maior crise de sua hist\u00f3ria. De um dia para o outro, tal como o filme Querida, encolhi as crian\u00e7as, a demanda simplesmente sumiu. Alguns sistemas registraram perdas de mais de 70%, enquanto os custos fixos se mantiveram nos patamares e o pre\u00e7o dos insumos (especialmente, energia) dispararam.<\/p>\n<p>&nbsp;<\/p>\n<p>Mas n\u00e3o vamos nos iludir. J\u00e1 havia algum tempo a crise assombrava o setor e ele caminhava para o colapso em passos lentos.<\/p>\n<p>&nbsp;<\/p>\n<p>Muitas s\u00e3o as medidas que podem e devem ser adotadas para a retomada e a prosperidade do transporte coletivo. Digo devem porque as cidades n\u00e3o podem renunciar aos sistemas de transporte de massa, organizados e padronizados, sob pena de ampliar a desigualdade e a falta de acesso das pessoas que mais precisam.<\/p>\n<p>&nbsp;<\/p>\n<p>Um pilar essencial para facilitar ou n\u00e3o o acesso ao transporte p\u00fablico \u00e9 o seu sistema de cobran\u00e7a, o seu sistema de pagamento. Ou, como dizem os t\u00e9cnicos, o sistema de bilhetagem.<\/p>\n<p>&nbsp;<\/p>\n<p>Esse componente do sistema de transporte p\u00fablico, que aparentemente \u00e9 algo simples, tal como um ingresso para um show ou um cinema, na verdade \u00e9 um dos elementos mais complexos e mais fundamentais. Ele n\u00e3o diz respeito apenas \u00e0 compra e venda de um direito de viagem. Ele define a efici\u00eancia, a capacidade de promover integra\u00e7\u00f5es, permite a coleta de dados sobre as viagens, amplia a capacidade de gerenciamento e planejamento do servi\u00e7o. Em outras palavras, a moderniza\u00e7\u00e3o do sistema de bilhetagem significa a indu\u00e7\u00e3o de impactos diretos na experi\u00eancia do usu\u00e1rio, na desonera\u00e7\u00e3o do poder p\u00fablico e na gera\u00e7\u00e3o de novos neg\u00f3cios.<\/p>\n<p>&nbsp;<\/p>\n<p>Precisa ser capaz de comercializar os diferentes tipos de bilhetes: vale-transporte, passe estudantil, gratuidades, calcular descontos instant\u00e2neos na integra\u00e7\u00e3o, ser imune a fraudes, ser confi\u00e1vel mantendo-se operacional o tempo todo. Qualquer falha penaliza diretamente o usu\u00e1rio.<\/p>\n<p>&nbsp;<\/p>\n<p>Tamb\u00e9m h\u00e1, ao redor da quest\u00e3o, a gest\u00e3o dos recursos financeiros do sistema. O sistema de bilhetagem costuma ser cobi\u00e7ado porque ele permite administrar uma quantidade grande de recursos oriundos da compra de passagens e que demoram para ser utilizadas.<\/p>\n<p>&nbsp;<\/p>\n<p>Ao longo dos anos, o mercado privado desenvolveu diferentes tecnologias e solu\u00e7\u00f5es para a opera\u00e7\u00e3o dos sistemas de bilhetagem. Mas, antes das solu\u00e7\u00f5es na ponta da linha, o mercado e as entidades certificadoras desenvolveram padr\u00f5es de tr\u00e2mite dos dados e de seguran\u00e7a, al\u00e9m da interoperabilidade, ou seja, a capacidade de o sistema ser utilizado por diferentes meios de pagamento, abrindo novas possibilidades. O blockchain, a capacidade de produzir transa\u00e7\u00f5es seguras, inaugura uma nova era para a bilhetagem do transporte p\u00fablico.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c9 preciso considerar, ainda, a integra\u00e7\u00e3o institucional. Lembro da revolu\u00e7\u00e3o que foi a integra\u00e7\u00e3o entre o bilhete \u00fanico da Prefeitura de S\u00e3o Paulo e o sistema de trilhos, gerido pelo governo do Estado de S\u00e3o Paulo, implantada entre 2005 e 2006. Usu\u00e1rios que n\u00e3o tinham condi\u00e7\u00f5es de acessar \u00f4nibus e metr\u00f4 na mesma viagem, pois tinham de pagar duas passagens, passaram a viajar mais rapidamente, apenas com a integra\u00e7\u00e3o tecnol\u00f3gica, o desconto na tarifa. Tudo isso s\u00f3 foi poss\u00edvel gra\u00e7as ao di\u00e1logo institucional entre os dois entes: prefeitura e governo do Estado.<\/p>\n<p>&nbsp;<\/p>\n<p>Este \u00e9 um mercado em que a oferta de diferentes solu\u00e7\u00f5es e em que, em ambiente competitivo (por meio de licita\u00e7\u00f5es p\u00fablicas) e aberto \u00e0 participa\u00e7\u00e3o da sociedade civil (audi\u00eancias e consultas p\u00fablicas), os sistemas de transporte podem ser modernizados e ampliar \u2013 e muito \u2013 o acesso e a sua atratividade.<\/p>\n<p>&nbsp;<\/p>\n<p>Ao contr\u00e1rio, escolhas erradas, sem certifica\u00e7\u00e3o, sem protocolos e sem interoperabilidade podem limitar o acesso, excluindo usu\u00e1rios e perdendo atratividade. Solu\u00e7\u00f5es que n\u00e3o sejam transparentes e abertas \u00e0 sociedade podem levar \u00e0 diminui\u00e7\u00e3o do acesso, e n\u00e3o \u00e0 desejada amplia\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Quanto \u00e0 contrata\u00e7\u00e3o de empresas para organizar e explorar o sistema de bilhetagem, vemos tr\u00eas diferentes op\u00e7\u00f5es para o poder p\u00fablico. A primeira \u00e9 explorar diretamente o servi\u00e7o, o que traz a imensa desvantagem da falta de agilidade e de flexibilidade para a contrata\u00e7\u00e3o de solu\u00e7\u00f5es de tecnologia, que evoluem muito mais rapidamente que o tempo de decis\u00e3o do poder p\u00fablico. A segunda \u00e9 contratar, sempre mediante licita\u00e7\u00e3o, uma empresa privada para explorar o servi\u00e7o. E a terceira possibilidade \u2013 e que me parece ser a melhor, do ponto de vista do interesse p\u00fablico e dos usu\u00e1rios \u2013 \u00e9 o credenciamento de empresas que atendam a protocolos predefinidos, com interoperabilidade, possibilitando a oferta aos usu\u00e1rios de diferentes solu\u00e7\u00f5es.<\/p>\n<p>&nbsp;<\/p>\n<p>Para atingir a efici\u00eancia das cidades, \u00e9 essencial que o poder p\u00fablico esteja atento \u00e0s oportunidades que se desenvolvem em parceria com o setor privado. Dessa forma, ambos os setores podem trabalhar de forma integrada e complementar, abrindo espa\u00e7o para que iniciativas privadas contribuam com ideias e projetos que t\u00eam potencial para transformar o segmento, melhorando a experi\u00eancia para o usu\u00e1rio do transporte p\u00fablico, gerando novos produtos e servi\u00e7os e contribuindo para o progresso da mobilidade urbana no Pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c9 tempo de investir na moderniza\u00e7\u00e3o e na facilidade do acesso, e n\u00e3o o contr\u00e1rio.<\/p>\n<p>&nbsp;<\/p>\n<p>Para atingir efici\u00eancia, \u00e9 essencial que o poder p\u00fablico esteja atento \u00e0s oportunidades em parceria com o setor privado. (O Estado de S. Paulo\/Sergio Avelleda)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Estado de S. Paulo &nbsp; J\u00e1 virou lugar-comum afirmar que a pandemia levou o transporte p\u00fablico \u00e0 maior crise de sua hist\u00f3ria. De um dia para o outro, tal como o filme Querida, encolhi as crian\u00e7as, a demanda simplesmente sumiu. Alguns sistemas registraram perdas de mais de 70%, enquanto os custos fixos se mantiveram\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[102],"tags":[],"class_list":["post-59035","post","type-post","status-publish","format-standard","hentry","category-mobilidade"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transporte p\u00fablico: acesso ou bloqueio? - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transporte p\u00fablico: acesso ou bloqueio? - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"O Estado de S. Paulo &nbsp; J\u00e1 virou lugar-comum afirmar que a pandemia levou o transporte p\u00fablico \u00e0 maior crise de sua hist\u00f3ria. De um dia para o outro, tal como o filme Querida, encolhi as crian\u00e7as, a demanda simplesmente sumiu. Alguns sistemas registraram perdas de mais de 70%, enquanto os custos fixos se mantiveram\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-20T11:48:21+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/transporte-publico-acesso-ou-bloqueio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/transporte-publico-acesso-ou-bloqueio\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Transporte p\u00fablico: acesso ou bloqueio?\",\"datePublished\":\"2022-06-20T11:48:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/transporte-publico-acesso-ou-bloqueio\\\/\"},\"wordCount\":945,\"articleSection\":[\"Mobilidade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/transporte-publico-acesso-ou-bloqueio\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/transporte-publico-acesso-ou-bloqueio\\\/\",\"name\":\"Transporte p\u00fablico: acesso ou bloqueio? - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2022-06-20T11:48:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/transporte-publico-acesso-ou-bloqueio\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/transporte-publico-acesso-ou-bloqueio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/06\\\/20\\\/transporte-publico-acesso-ou-bloqueio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mobilidade\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mobilidade\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Transporte p\u00fablico: acesso ou bloqueio?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transporte p\u00fablico: acesso ou bloqueio? - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/","og_locale":"pt_BR","og_type":"article","og_title":"Transporte p\u00fablico: acesso ou bloqueio? - Canal Dana","og_description":"O Estado de S. Paulo &nbsp; J\u00e1 virou lugar-comum afirmar que a pandemia levou o transporte p\u00fablico \u00e0 maior crise de sua hist\u00f3ria. De um dia para o outro, tal como o filme Querida, encolhi as crian\u00e7as, a demanda simplesmente sumiu. Alguns sistemas registraram perdas de mais de 70%, enquanto os custos fixos se mantiveram\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/","og_site_name":"Canal Dana","article_published_time":"2022-06-20T11:48:21+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Transporte p\u00fablico: acesso ou bloqueio?","datePublished":"2022-06-20T11:48:21+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/"},"wordCount":945,"articleSection":["Mobilidade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/","url":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/","name":"Transporte p\u00fablico: acesso ou bloqueio? - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2022-06-20T11:48:21+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2022\/06\/20\/transporte-publico-acesso-ou-bloqueio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mobilidade","item":"https:\/\/dana.com.br\/canaldana\/mobilidade\/"},{"@type":"ListItem","position":3,"name":"Transporte p\u00fablico: acesso ou bloqueio?"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/59035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=59035"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/59035\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=59035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=59035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=59035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}