{"id":58121,"date":"2022-05-11T09:11:04","date_gmt":"2022-05-11T12:11:04","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=58121"},"modified":"2022-05-11T09:11:04","modified_gmt":"2022-05-11T12:11:04","slug":"primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/","title":{"rendered":"Primeiro carro el\u00e9trico da BMW completa 50 anos em 2022"},"content":{"rendered":"<p><em>Olhar Digital <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Ganhando fama nos \u00faltimos anos, o carro el\u00e9trico no mundo teve sua hist\u00f3ria iniciada h\u00e1 muito tempo e o 1\u00ba modelo de uma das marcas mais renomadas do setor, a BMW, \u00e9 prova disso. O modelo do ve\u00edculo est\u00e1 completando 50 anos em 2022.<\/p>\n<p>&nbsp;<\/p>\n<p>Tido como o \u201cpai\u201d do i3 (tipo de motor el\u00e9trico), o 1602 saiu do papel em 1972, perto do come\u00e7o dos Jogos Ol\u00edmpicos de Munique. \u201cChamado de Elektro-antrieb, que em tradu\u00e7\u00e3o livre significa acionamento el\u00e9trico, o 1602 laranja brilhante utilizava os recursos mais avan\u00e7ados da sua \u00e9poca\u201d, disse a marca, ao comemorar o feito de 50 anos do lan\u00e7amento.<\/p>\n<p>&nbsp;<\/p>\n<p>Segundo a BMW, o 1602 possu\u00eda motor el\u00e9trico de 32 kW de pot\u00eancia, que \u00e9 equivalente a 43 cavalos e ainda, sob o cap\u00f4, constava 12 baterias padr\u00e3o de chumbo-\u00e1cido, com peso de 350 quilos que eram as respons\u00e1veis por fornecer energia para acionar o motor el\u00e9trico.<\/p>\n<p>&nbsp;<\/p>\n<p>O primeiro carro el\u00e9trico da BMW era equipado com um sistema de freios regenerativo, que era capaz de gerar eletricidade com a for\u00e7a das frenagens e assim, \u201crecarregava\u201d a bateria enquanto andava. Agora, o modelo descansa no acervo da marca \u2013 em pleno funcionamento \u2013 e \u00e0s vezes \u00e9 incorporado \u00e0s exposi\u00e7\u00f5es no BMW Museum, que fica em Munique. (Olhar Digital\/Gabriela Bulh\u00f5es)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olhar Digital &nbsp; Ganhando fama nos \u00faltimos anos, o carro el\u00e9trico no mundo teve sua hist\u00f3ria iniciada h\u00e1 muito tempo e o 1\u00ba modelo de uma das marcas mais renomadas do setor, a BMW, \u00e9 prova disso. O modelo do ve\u00edculo est\u00e1 completando 50 anos em 2022. &nbsp; Tido como o \u201cpai\u201d do i3 (tipo\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[110],"tags":[],"class_list":["post-58121","post","type-post","status-publish","format-standard","hentry","category-eletricos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Primeiro carro el\u00e9trico da BMW completa 50 anos em 2022 - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primeiro carro el\u00e9trico da BMW completa 50 anos em 2022 - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Olhar Digital &nbsp; Ganhando fama nos \u00faltimos anos, o carro el\u00e9trico no mundo teve sua hist\u00f3ria iniciada h\u00e1 muito tempo e o 1\u00ba modelo de uma das marcas mais renomadas do setor, a BMW, \u00e9 prova disso. O modelo do ve\u00edculo est\u00e1 completando 50 anos em 2022. &nbsp; Tido como o \u201cpai\u201d do i3 (tipo\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-11T12:11:04+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/11\\\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/11\\\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Primeiro carro el\u00e9trico da BMW completa 50 anos em 2022\",\"datePublished\":\"2022-05-11T12:11:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/11\\\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\\\/\"},\"wordCount\":232,\"articleSection\":[\"El\u00e9tricos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/11\\\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/11\\\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\\\/\",\"name\":\"Primeiro carro el\u00e9trico da BMW completa 50 anos em 2022 - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2022-05-11T12:11:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/11\\\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/11\\\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/11\\\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El\u00e9tricos\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/eletricos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Primeiro carro el\u00e9trico da BMW completa 50 anos em 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primeiro carro el\u00e9trico da BMW completa 50 anos em 2022 - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/","og_locale":"pt_BR","og_type":"article","og_title":"Primeiro carro el\u00e9trico da BMW completa 50 anos em 2022 - Canal Dana","og_description":"Olhar Digital &nbsp; Ganhando fama nos \u00faltimos anos, o carro el\u00e9trico no mundo teve sua hist\u00f3ria iniciada h\u00e1 muito tempo e o 1\u00ba modelo de uma das marcas mais renomadas do setor, a BMW, \u00e9 prova disso. O modelo do ve\u00edculo est\u00e1 completando 50 anos em 2022. &nbsp; Tido como o \u201cpai\u201d do i3 (tipo\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/","og_site_name":"Canal Dana","article_published_time":"2022-05-11T12:11:04+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Primeiro carro el\u00e9trico da BMW completa 50 anos em 2022","datePublished":"2022-05-11T12:11:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/"},"wordCount":232,"articleSection":["El\u00e9tricos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/","url":"https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/","name":"Primeiro carro el\u00e9trico da BMW completa 50 anos em 2022 - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2022-05-11T12:11:04+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2022\/05\/11\/primeiro-carro-eletrico-da-bmw-completa-50-anos-em-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"El\u00e9tricos","item":"https:\/\/dana.com.br\/canaldana\/eletricos\/"},{"@type":"ListItem","position":3,"name":"Primeiro carro el\u00e9trico da BMW completa 50 anos em 2022"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/58121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=58121"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/58121\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=58121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=58121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=58121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}