{"id":58111,"date":"2022-05-10T08:46:15","date_gmt":"2022-05-10T11:46:15","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=58111"},"modified":"2022-05-10T08:46:15","modified_gmt":"2022-05-10T11:46:15","slug":"gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/","title":{"rendered":"GM est\u00e1 em posi\u00e7\u00e3o mais positiva do que as demais montadoras, diz sindicato"},"content":{"rendered":"<p><em>Rep\u00f3rter Di\u00e1rio <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Depois de fechar o acordo considerado um dos melhores entre as montadoras do Pa\u00eds e que vai garantir a PLR (Participa\u00e7\u00e3o nos Lucros e Resultados) de R$ 15,5 mil mais um abono de R$ 1,5 mil para os cerca de 7,5 mil trabalhadores, o presidente do Sindicato dos Metal\u00fargicos de S\u00e3o Caetano, Aparecido In\u00e1cio da Silva, o Cid\u00e3o, disse que a GM de S\u00e3o Caetano \u00e9 uma das montadoras que est\u00e1 em melhor condi\u00e7\u00e3o em termos de investimentos, com sua planta atualizada e capaz de assumir novas linhas de produ\u00e7\u00e3o. O acordo entre a montadora e os trabalhadores foi firmado ap\u00f3s assembleia realizada com os metal\u00fargicos no p\u00e1tio da empresa na quarta-feira (04\/05).<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cA situa\u00e7\u00e3o atual \u00e9 confort\u00e1vel quanto aos investimentos. O que nos preocupa \u00e9 essa falta de componentes\u201d, disse Cid\u00e3o. A falta de semicondutores, fez a Volkswagen parar parte da produ\u00e7\u00e3o na f\u00e1brica da Anchieta, em S\u00e3o Bernardo e dar f\u00e9rias a 2,5 mil trabalhadores. \u201cAgora a China \u2013 principal fabricante dos semicondutores \u2013 est\u00e1 em lockdowm ent\u00e3o a gente n\u00e3o sabe o que vai acontecer, \u00e9 imprevis\u00edvel\u201d, disse Cid\u00e3o, preocupado com que a falta dos componentes possa afetar a GM tamb\u00e9m.<\/p>\n<p>&nbsp;<\/p>\n<p>Mas fora a falta dos insumos que v\u00eam de fora, a f\u00e1brica de S\u00e3o Caetano est\u00e1 saud\u00e1vel, de acordo com o acompanhamento que o presidente do sindicato faz. \u201cTodos os investimentos j\u00e1 foram feitos para a produ\u00e7\u00e3o da nova Montana e a al\u00e9m dela f\u00e1brica est\u00e1 preparada para atender outras linhas de ve\u00edculos\u201d, disse Cid\u00e3o. Al\u00e9m disso, a montadora est\u00e1 prestes a ingressar tamb\u00e9m na produ\u00e7\u00e3o de ve\u00edculos el\u00e9tricos. \u201cJ\u00e1 tem um cen\u00e1rio para come\u00e7ar j\u00e1 em 2025 seguindo at\u00e9 parar, em 2035, a produ\u00e7\u00e3o de ve\u00edculos \u00e0 combust\u00e3o\u201d, disse o sindicalista.<\/p>\n<p>&nbsp;<\/p>\n<p>O acordo celebrado na quarta-feira vai injetar cerca de R$ 127 milh\u00f5es na economia, calculando o PLR e o abono para os cerca de 7,5 mil trabalhadores da f\u00e1brica de S\u00e3o Caetano. \u201cEsse \u00e9 um acordo hist\u00f3rico e revela um compromisso nosso do sindicato com a gera\u00e7\u00e3o de emprego e renda\u201d, comemorou Cid\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>O RD pediu \u00e0 GM o detalhamento dos investimentos previstos para a planta do ABC, mas at\u00e9 o fechamento desta reportagem n\u00e3o obteve resposta.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Cen\u00e1rio<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m da Volkswagen, onde os 2,5 mil trabalhadores ficar\u00e3o em f\u00e9rias coletivas de 9 a 28 de maio, na Mercedes-Benz, que tamb\u00e9m fica em S\u00e3o Bernardo, 5 mil oper\u00e1rios tamb\u00e9m ficaram em casa entre 18 de abril e 3 de maio, tamb\u00e9m por conta da falta de componentes eletr\u00f4nicos.<\/p>\n<p>&nbsp;<\/p>\n<p>Nesta \u00faltima quinta-feira (05\/05) a Caoa Chery anunciou o fechamento da sua f\u00e1brica de Jacare\u00ed, no interior do Estado. A empresa vai transferir a sua produ\u00e7\u00e3o para a An\u00e1polis (Goi\u00e1s) para que a f\u00e1brica paulista seja equipada para reiniciar a produ\u00e7\u00e3o, s\u00f3 que de ve\u00edculos el\u00e9tricos. Cerca de 600 trabalhadores, que correspondem a toda a linha de produ\u00e7\u00e3o e metade da administra\u00e7\u00e3o de Jacare\u00ed ser\u00e3o demitidos. Em nota, a companhia informou que negocia com o Sindicato dos Metal\u00fargicos de S\u00e3o Jos\u00e9 dos Campos e Regi\u00e3o para definir um pacote de indeniza\u00e7\u00e3o suplementar. \u201cPara que as mudan\u00e7as ocorram de forma efetiva, a Caoa Chery informa a parada tempor\u00e1ria da unidade fabril de Jacare\u00ed. A suspens\u00e3o das atividades tem como objetivo ajustar os processos produtivos da planta para novos modelos com tecnologias h\u00edbridas e el\u00e9tricas, visando a moderniza\u00e7\u00e3o e atualiza\u00e7\u00e3o das linhas de produ\u00e7\u00e3o\u201d, sustentou.<\/p>\n<p>&nbsp;<\/p>\n<p>A Toyota foi outra montadora de ve\u00edculos que anunciou em abril deste ano o fechamento da unidade de S\u00e3o Bernardo que fabrica componentes de motores. A f\u00e1brica foi a primeira da montadora fora do Jap\u00e3o e data de 1962. Em outubro de 2019 a Ford, que tinha tamb\u00e9m uma f\u00e1brica hist\u00f3rica no bairro Tabo\u00e3o, na mesma cidade, encerrou a produ\u00e7\u00e3o e os \u00faltimos 600 oper\u00e1rios foram demitidos. Os casos s\u00e3o distintos, a montadora japonesa mant\u00e9m suas atividades no pa\u00eds enquanto a americana decidiu encerrar a produ\u00e7\u00e3o no pa\u00eds e apenas comercializar ve\u00edculos que v\u00eam de fora. (Rep\u00f3rter Di\u00e1rio\/George Garcia)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rep\u00f3rter Di\u00e1rio &nbsp; Depois de fechar o acordo considerado um dos melhores entre as montadoras do Pa\u00eds e que vai garantir a PLR (Participa\u00e7\u00e3o nos Lucros e Resultados) de R$ 15,5 mil mais um abono de R$ 1,5 mil para os cerca de 7,5 mil trabalhadores, o presidente do Sindicato dos Metal\u00fargicos de S\u00e3o Caetano,\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[61],"tags":[],"class_list":["post-58111","post","type-post","status-publish","format-standard","hentry","category-destaques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GM est\u00e1 em posi\u00e7\u00e3o mais positiva do que as demais montadoras, diz sindicato - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GM est\u00e1 em posi\u00e7\u00e3o mais positiva do que as demais montadoras, diz sindicato - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Rep\u00f3rter Di\u00e1rio &nbsp; Depois de fechar o acordo considerado um dos melhores entre as montadoras do Pa\u00eds e que vai garantir a PLR (Participa\u00e7\u00e3o nos Lucros e Resultados) de R$ 15,5 mil mais um abono de R$ 1,5 mil para os cerca de 7,5 mil trabalhadores, o presidente do Sindicato dos Metal\u00fargicos de S\u00e3o Caetano,\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-10T11:46:15+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/10\\\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/10\\\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"GM est\u00e1 em posi\u00e7\u00e3o mais positiva do que as demais montadoras, diz sindicato\",\"datePublished\":\"2022-05-10T11:46:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/10\\\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\\\/\"},\"wordCount\":756,\"articleSection\":[\"Destaques\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/10\\\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/10\\\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\\\/\",\"name\":\"GM est\u00e1 em posi\u00e7\u00e3o mais positiva do que as demais montadoras, diz sindicato - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2022-05-10T11:46:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/10\\\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/10\\\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2022\\\/05\\\/10\\\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destaques\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/destaques\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GM est\u00e1 em posi\u00e7\u00e3o mais positiva do que as demais montadoras, diz sindicato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GM est\u00e1 em posi\u00e7\u00e3o mais positiva do que as demais montadoras, diz sindicato - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/","og_locale":"pt_BR","og_type":"article","og_title":"GM est\u00e1 em posi\u00e7\u00e3o mais positiva do que as demais montadoras, diz sindicato - Canal Dana","og_description":"Rep\u00f3rter Di\u00e1rio &nbsp; Depois de fechar o acordo considerado um dos melhores entre as montadoras do Pa\u00eds e que vai garantir a PLR (Participa\u00e7\u00e3o nos Lucros e Resultados) de R$ 15,5 mil mais um abono de R$ 1,5 mil para os cerca de 7,5 mil trabalhadores, o presidente do Sindicato dos Metal\u00fargicos de S\u00e3o Caetano,\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/","og_site_name":"Canal Dana","article_published_time":"2022-05-10T11:46:15+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"GM est\u00e1 em posi\u00e7\u00e3o mais positiva do que as demais montadoras, diz sindicato","datePublished":"2022-05-10T11:46:15+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/"},"wordCount":756,"articleSection":["Destaques"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/","url":"https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/","name":"GM est\u00e1 em posi\u00e7\u00e3o mais positiva do que as demais montadoras, diz sindicato - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2022-05-10T11:46:15+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2022\/05\/10\/gm-esta-em-posicao-mais-positiva-do-que-as-demais-montadoras-diz-sindicato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Destaques","item":"https:\/\/dana.com.br\/canaldana\/destaques\/"},{"@type":"ListItem","position":3,"name":"GM est\u00e1 em posi\u00e7\u00e3o mais positiva do que as demais montadoras, diz sindicato"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/58111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=58111"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/58111\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=58111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=58111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=58111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}