{"id":51336,"date":"2021-07-05T08:21:50","date_gmt":"2021-07-05T11:21:50","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=51336"},"modified":"2021-07-05T08:21:50","modified_gmt":"2021-07-05T11:21:50","slug":"dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/","title":{"rendered":"DPaschoal lan\u00e7a novo e-commerce com mais de 25 mil itens"},"content":{"rendered":"<p><em>Frota &amp; Cia <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>A DPaschoal lan\u00e7ou no \u00faltimo dia 15 de junho, um novo e-commerce. Dessa forma, o consumidor pode fazer todo o processo de compra com maior rapidez, efici\u00eancia e seguran\u00e7a. Al\u00e9m disso, outra novidade \u00e9 que o site passa a oferecer pe\u00e7as e pneus para motocicletas e ve\u00edculos agr\u00edcolas.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cO principal impulso para a reformula\u00e7\u00e3o partiu do nosso DNA, que tem nos pilares inova\u00e7\u00e3o, tecnologia, intelig\u00eancia e o relacionamento humano. Sab\u00edamos que ao oferecer uma plataforma intuitiva e segura aos mais de 5 milh\u00f5es de clientes do sistema de relacionamento AutoCard, conseguir\u00edamos entregar solu\u00e7\u00f5es mais assertivas para os consumidores, frotistas, agricultores, caminhoneiros e aplicadores,\u201d explica Bruno Gomes, diretor de neg\u00f3cios da DPaschoal.<\/p>\n<p>&nbsp;<\/p>\n<p>A oferta de produtos tamb\u00e9m foi ampliada, dos 250 dispon\u00edveis anteriormente, agora, s\u00e3o mais de 25 mil itens. O aumento consider\u00e1vel s\u00f3 foi poss\u00edvel porque o novo modelo se transformou em um marketplace, onde o DPaschoal.com.br passa ser uma enorme vitrine para os fornecedores de autope\u00e7as e equipamentos. Os produtos que s\u00e3o vendidos no Auto Z, portal refer\u00eancia no mercado on-line e no e-commerce automotivo, tamb\u00e9m podem ser comprados diretamente no site da DPaschoal. (Frota &amp; Cia\/Andr\u00e9 Garcia)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frota &amp; Cia &nbsp; A DPaschoal lan\u00e7ou no \u00faltimo dia 15 de junho, um novo e-commerce. Dessa forma, o consumidor pode fazer todo o processo de compra com maior rapidez, efici\u00eancia e seguran\u00e7a. Al\u00e9m disso, outra novidade \u00e9 que o site passa a oferecer pe\u00e7as e pneus para motocicletas e ve\u00edculos agr\u00edcolas. &nbsp; \u201cO principal\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-51336","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DPaschoal lan\u00e7a novo e-commerce com mais de 25 mil itens - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DPaschoal lan\u00e7a novo e-commerce com mais de 25 mil itens - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Frota &amp; Cia &nbsp; A DPaschoal lan\u00e7ou no \u00faltimo dia 15 de junho, um novo e-commerce. Dessa forma, o consumidor pode fazer todo o processo de compra com maior rapidez, efici\u00eancia e seguran\u00e7a. Al\u00e9m disso, outra novidade \u00e9 que o site passa a oferecer pe\u00e7as e pneus para motocicletas e ve\u00edculos agr\u00edcolas. &nbsp; \u201cO principal\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-05T11:21:50+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/07\\\/05\\\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/07\\\/05\\\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"DPaschoal lan\u00e7a novo e-commerce com mais de 25 mil itens\",\"datePublished\":\"2021-07-05T11:21:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/07\\\/05\\\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\\\/\"},\"wordCount\":227,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/07\\\/05\\\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/07\\\/05\\\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\\\/\",\"name\":\"DPaschoal lan\u00e7a novo e-commerce com mais de 25 mil itens - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2021-07-05T11:21:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/07\\\/05\\\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/07\\\/05\\\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/07\\\/05\\\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DPaschoal lan\u00e7a novo e-commerce com mais de 25 mil itens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DPaschoal lan\u00e7a novo e-commerce com mais de 25 mil itens - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/","og_locale":"pt_BR","og_type":"article","og_title":"DPaschoal lan\u00e7a novo e-commerce com mais de 25 mil itens - Canal Dana","og_description":"Frota &amp; Cia &nbsp; A DPaschoal lan\u00e7ou no \u00faltimo dia 15 de junho, um novo e-commerce. Dessa forma, o consumidor pode fazer todo o processo de compra com maior rapidez, efici\u00eancia e seguran\u00e7a. Al\u00e9m disso, outra novidade \u00e9 que o site passa a oferecer pe\u00e7as e pneus para motocicletas e ve\u00edculos agr\u00edcolas. &nbsp; \u201cO principal\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/","og_site_name":"Canal Dana","article_published_time":"2021-07-05T11:21:50+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"DPaschoal lan\u00e7a novo e-commerce com mais de 25 mil itens","datePublished":"2021-07-05T11:21:50+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/"},"wordCount":227,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/","url":"https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/","name":"DPaschoal lan\u00e7a novo e-commerce com mais de 25 mil itens - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2021-07-05T11:21:50+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2021\/07\/05\/dpaschoal-lanca-novo-e-commerce-com-mais-de-25-mil-itens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"DPaschoal lan\u00e7a novo e-commerce com mais de 25 mil itens"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/51336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=51336"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/51336\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=51336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=51336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=51336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}