{"id":51159,"date":"2021-06-25T08:08:05","date_gmt":"2021-06-25T11:08:05","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=51159"},"modified":"2021-06-25T08:08:05","modified_gmt":"2021-06-25T11:08:05","slug":"tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/","title":{"rendered":"Tokio Marine fecha parceria com a Kinto para seguro de servi\u00e7os de mobilidade"},"content":{"rendered":"<p><em>Revista Ap\u00f3lice<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>A Tokio Marine firmou parceria com a Kinto, bra\u00e7o de servi\u00e7os de mobilidade para Pessoas F\u00edsicas e Jur\u00eddicas da Toyota, que chegou ao Pa\u00eds em 2020. A colabora\u00e7\u00e3o \u00e9 fruto de concorr\u00eancia realizada pela Kinto, que levou em conta todo o pacote de valor que a companhia oferece para os clientes da carteira de autom\u00f3vel, e escolheu a Tokio Marine como sua fornecedora.<\/p>\n<p>&nbsp;<\/p>\n<p>Por meio da parceria, a Tokio Marine entregar\u00e1 sua expertise e qualidade em duas modalidades: personalizado com diversas coberturas e servi\u00e7os conforme a necessidade dos clientes do Kinto One, servi\u00e7o da empresa de gest\u00e3o de frotas corporativas; e cobertura compreensiva e servi\u00e7os exclusivos de gerenciamento de ve\u00edculos do Kinto Share, servi\u00e7o de compartilhamento de ve\u00edculos por meio de aplicativo e esta\u00e7\u00f5es localizadas nas concession\u00e1rias Toyota.<\/p>\n<p>&nbsp;<\/p>\n<p>A Toyota \u00e9 hoje um dos maiores clientes globais da Tokio Marine. No Brasil, a maior parte dos seguros da montadora s\u00e3o feitos em parceria com a seguradora. \u201cTemos muito orgulho de atuar mais uma vez com a Toyota, desta vez na \u00e1rea de mobilidade, pela qual temos enorme interesse de atua\u00e7\u00e3o. Ambas somos multinacionais japonesas, com trajet\u00f3rias de sucesso em seus segmentos, que compartilham dos mesmos valores e refer\u00eancias, buscando contribuir sempre para o desenvolvimento econ\u00f4mico e social das regi\u00f5es em que atuamos. Temos certeza de que essa colabora\u00e7\u00e3o s\u00f3 vai agregar valor aos servi\u00e7os oferecidos aos clientes da Kinto\u201d, afirma Luiz Padial, diretor de Autom\u00f3vel da Tokio Marine.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre os diferenciais da Kinto est\u00e3o a aplica\u00e7\u00e3o dos conceitos e padr\u00f5es do Sistema Toyota de Produ\u00e7\u00e3o, que ajudam a otimizar resultados dos neg\u00f3cios com foco em seguran\u00e7a, log\u00edstica e gest\u00e3o de processos. Al\u00e9m disso, a empresa tem uma ampla oferta de ve\u00edculos h\u00edbridos, cada vez mais relevantes para a sociedade e as estrat\u00e9gias de sustentabilidade das corpora\u00e7\u00f5es.<\/p>\n<p>&nbsp;<\/p>\n<p>Para Roger Armellini, diretor de Mobilidade da Toyota, \u00e9 importante contar com a expertise da Tokio Marine ao oferecer os servi\u00e7os de mobilidade e gest\u00e3o de frota corporativa dos clientes e consumidores da Kinto. \u201cTemos como premissa oferecer as melhores solu\u00e7\u00f5es de mobilidade de forma simples, inteligente e confi\u00e1vel, sempre contando com parceiros que agreguem valor e qualidade aos nossos servi\u00e7os.\u201d, afirma o executivo<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEstamos trabalhando incansavelmente para desenvolver produtos que atendam \u00e0s novas demandas de mobilidade, como o rec\u00e9m-lan\u00e7ado seguro pague pelo tempo que ficou protegido, e seguimos atentos \u00e0s iniciativas que contemplam op\u00e7\u00f5es de deslocamento inovadoras, como as da KINTO. Por meio dessa parceria, estamos mais uma vez proporcionando alternativas de prote\u00e7\u00e3o e seguran\u00e7a que unem comodidade e conveni\u00eancia \u00e0s escolhas do consumidor\u201d, conclui Padial. (Revista Ap\u00f3lice)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Revista Ap\u00f3lice &nbsp; A Tokio Marine firmou parceria com a Kinto, bra\u00e7o de servi\u00e7os de mobilidade para Pessoas F\u00edsicas e Jur\u00eddicas da Toyota, que chegou ao Pa\u00eds em 2020. A colabora\u00e7\u00e3o \u00e9 fruto de concorr\u00eancia realizada pela Kinto, que levou em conta todo o pacote de valor que a companhia oferece para os clientes da\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-51159","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tokio Marine fecha parceria com a Kinto para seguro de servi\u00e7os de mobilidade - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tokio Marine fecha parceria com a Kinto para seguro de servi\u00e7os de mobilidade - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Revista Ap\u00f3lice &nbsp; A Tokio Marine firmou parceria com a Kinto, bra\u00e7o de servi\u00e7os de mobilidade para Pessoas F\u00edsicas e Jur\u00eddicas da Toyota, que chegou ao Pa\u00eds em 2020. A colabora\u00e7\u00e3o \u00e9 fruto de concorr\u00eancia realizada pela Kinto, que levou em conta todo o pacote de valor que a companhia oferece para os clientes da\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-25T11:08:05+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/06\\\/25\\\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/06\\\/25\\\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Tokio Marine fecha parceria com a Kinto para seguro de servi\u00e7os de mobilidade\",\"datePublished\":\"2021-06-25T11:08:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/06\\\/25\\\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\\\/\"},\"wordCount\":495,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/06\\\/25\\\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/06\\\/25\\\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\\\/\",\"name\":\"Tokio Marine fecha parceria com a Kinto para seguro de servi\u00e7os de mobilidade - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2021-06-25T11:08:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/06\\\/25\\\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/06\\\/25\\\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/06\\\/25\\\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tokio Marine fecha parceria com a Kinto para seguro de servi\u00e7os de mobilidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tokio Marine fecha parceria com a Kinto para seguro de servi\u00e7os de mobilidade - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Tokio Marine fecha parceria com a Kinto para seguro de servi\u00e7os de mobilidade - Canal Dana","og_description":"Revista Ap\u00f3lice &nbsp; A Tokio Marine firmou parceria com a Kinto, bra\u00e7o de servi\u00e7os de mobilidade para Pessoas F\u00edsicas e Jur\u00eddicas da Toyota, que chegou ao Pa\u00eds em 2020. A colabora\u00e7\u00e3o \u00e9 fruto de concorr\u00eancia realizada pela Kinto, que levou em conta todo o pacote de valor que a companhia oferece para os clientes da\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/","og_site_name":"Canal Dana","article_published_time":"2021-06-25T11:08:05+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Tokio Marine fecha parceria com a Kinto para seguro de servi\u00e7os de mobilidade","datePublished":"2021-06-25T11:08:05+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/"},"wordCount":495,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/","url":"https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/","name":"Tokio Marine fecha parceria com a Kinto para seguro de servi\u00e7os de mobilidade - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2021-06-25T11:08:05+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2021\/06\/25\/tokio-marine-fecha-parceria-com-a-kinto-para-seguro-de-servicos-de-mobilidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Tokio Marine fecha parceria com a Kinto para seguro de servi\u00e7os de mobilidade"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/51159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=51159"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/51159\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=51159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=51159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=51159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}