{"id":48459,"date":"2021-03-03T08:14:15","date_gmt":"2021-03-03T11:14:15","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=48459"},"modified":"2021-03-03T08:14:15","modified_gmt":"2021-03-03T11:14:15","slug":"novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/","title":{"rendered":"Novo IVECO Daily pronto para emerg\u00eancias nas rodovias do Brasil"},"content":{"rendered":"<p><em>Coisas de Agora<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Apresentada em 2020, a linha do Novo IVECO Daily j\u00e1 mostrou ampla versatilidade em aplica\u00e7\u00f5es que v\u00e3o al\u00e9m do transporte de cargas, como as vers\u00f5es motorhome, verdadeiras \u2018casas sobre rodas\u2019. Recentemente quatro unidades ambul\u00e2ncia, montadas sobre a estrutura chassi-cabine, entraram para a frota da Way-306 para refor\u00e7ar o atendimento de emerg\u00eancia na rodovia MS-306, com cerca de 218 quil\u00f4metros de extens\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Os ve\u00edculos passam por um sofisticado processo de customiza\u00e7\u00e3o para se \u2018transformarem\u2019 em unidades m\u00f3veis com estrutura apropriada para o socorro de v\u00edtimas, com materiais e equipamentos de \u00faltima gera\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Para George Carloto, gerente Comercial da IVECO, a utiliza\u00e7\u00e3o da vers\u00e3o chassi-cabine \u00e9 uma nova forma de atuar no segmento de ambul\u00e2ncias, que tradicionalmente utiliza furg\u00f5es para esse tipo de opera\u00e7\u00e3o. \u201cO uso de vers\u00f5es chassi-cabine para a aplica\u00e7\u00e3o de ambul\u00e2ncia j\u00e1 \u00e9 algo amplamente adotado fora do Brasil e abre novas portas para a marca e nossos parceiros pela versatilidade, efici\u00eancia e custo que a solu\u00e7\u00e3o proporciona. O Daily usa uma estrutura com longarinas em perfil \u201cC\u201d de 5mm, \u2013 a mais robusta da categoria, aliado a um refor\u00e7ado conjunto de suspens\u00e3o, o que torna o ve\u00edculo a melhor solu\u00e7\u00e3o para essa proposta. Estamos abrindo novas possibilidades de aplica\u00e7\u00f5es para um ve\u00edculo que j\u00e1 \u00e9 l\u00edder no segmento e se destaca pela robustez e durabilidade, atributos essenciais para esse mercado\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>A Way-306, empresa do Grupo Way Brasil, assinou o contrato de concess\u00e3o da rodovia com o Governo do Estado de Mato Grosso do Sul em 19 de mar\u00e7o de 2020 e, a partir de 22 de abril, assumiu por 30 anos a responsabilidade pela administra\u00e7\u00e3o, recupera\u00e7\u00e3o, conserva\u00e7\u00e3o, manuten\u00e7\u00e3o, implanta\u00e7\u00e3o de melhorias e amplia\u00e7\u00e3o da rodovia.<\/p>\n<p>&nbsp;<\/p>\n<p>Para dar suporte \u00e0 Way, e os outros clientes no Brasil, a IVECO, que em 2020 cresceu +30% em um mercado que registrou queda, disp\u00f5e de uma rede com 77 pontos de atendimento de norte a sul do pa\u00eds. \u201cNas concession\u00e1rias da marca temos equipes treinadas pela montadora para atender nossos parceiros \u2013 empresas, transportadores e aut\u00f4nomos \u2013 com foco total na qualidade e na agilidade na presta\u00e7\u00e3o de servi\u00e7os\u201d, finaliza Carloto.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Novo IVECO Daily<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Vencedora do Pr\u00eamio \u201cTop of Mind do Transporte 2020\u201d, categoria Leves, a Daily segue o desenho da linha europeia da marca, e se destaca pela modernidade das linhas da cabine, arrojadas e com atributos aerodin\u00e2micos, como a nova grade frontal (preta ou cromada), carroceria redesenhada, novo farol, novas luzes de posi\u00e7\u00e3o e farol de neblina. O visual tamb\u00e9m foi projetado com foco na opera\u00e7\u00e3o do cliente, o novo para-choque dianteiro \u00e9 agora tripartido, o que reduz os custos de reparo em caso de colis\u00f5es leves.<\/p>\n<p>&nbsp;<\/p>\n<p>J\u00e1 o novo interior foi totalmente pensado para privilegiar a ergonomia e incluir um novo \u2018pacote tecnol\u00f3gico\u2019 digno de um autom\u00f3vel premium. Conforto, organiza\u00e7\u00e3o e funcionalidade se destacam como um conjunto de componentes que colocam a Daily como a melhor op\u00e7\u00e3o do segmento.<\/p>\n<p>&nbsp;<\/p>\n<p>O novo painel de instrumentos tem fun\u00e7\u00f5es como controle de cruzeiro, limitador de velocidade, mensagens de feedback e manuten\u00e7\u00e3o. O motorista conta ainda com a comodidade do sensor de r\u00e9, para facilitar as manobras nos furg\u00f5es e vans, e volante com comando de telefone e voz. Destaque para o sistema multim\u00eddia, com tela de sete polegadas, que amplia a integra\u00e7\u00e3o \u2018homem\/m\u00e1quina\u2019 com fun\u00e7\u00f5es ativadas pelo reconhecimento de voz, tela touchscreen, Android Auto e Apple Car Play e para o novo ar-condicionado autom\u00e1tico digital.<\/p>\n<p>&nbsp;<\/p>\n<p>As novidades da cabine n\u00e3o param por a\u00ed: novo \u00e2ngulo de inclina\u00e7\u00e3o do para-brisa para melhorar a visibilidade, dire\u00e7\u00e3o com coluna ajust\u00e1vel para proporcionar mais conforto e seguran\u00e7a, diminui\u00e7\u00e3o do tamanho do volante para gerar a sensa\u00e7\u00e3o de que o motorista est\u00e1 dirigindo um autom\u00f3vel, melhor isolamento ac\u00fastico e porta-objetos na cabine pensados no motorista que vive seu dia a dia dentro do caminh\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Para impulsionar esse campe\u00e3o de vendas a IVECO mant\u00e9m a consagrada linha de motores da FPT Industrial, com os modelos F1A e F1C, de 130, 150 e 170 cavalos. S\u00e3o motores modernos, que combinam alta performance com baixo consumo de combust\u00edvel.<\/p>\n<p>&nbsp;<\/p>\n<p>No quesito consumo de combust\u00edvel, a tecnologia tamb\u00e9m se mostra presente. A novidade fica por conta do EcoSwitch, um bot\u00e3o projetado para reduzir o consumo de diesel. O sistema altera o mapeamento da calibra\u00e7\u00e3o do motor reduzindo ainda mais o consumo de combust\u00edvel. O conjunto torna a nova Daily ainda melhor que a vers\u00e3o anterior, que j\u00e1 era considerada \u2018a melhor\u2019 na categoria.<\/p>\n<p>&nbsp;<\/p>\n<p>A seguran\u00e7a fica por conta de uma s\u00e9rie de itens que tornam a viagem mais segura para o motorista, ajudantes e passageiros:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Assistente de estabilidade eletr\u00f4nica = atua no controle do torque do motor e nos freios, freando cada roda individualmente quando ve\u00edculo se torna inst\u00e1vel.<\/li>\n<li>Assistente de freio hidr\u00e1ulico = aumenta a press\u00e3o do freio quando o pedal \u00e9 acionado de forma r\u00e1pida reduzindo a dist\u00e2ncia de parada.<\/li>\n<li>Compensa\u00e7\u00e3o hidr\u00e1ulica de frenagem = detecta condi\u00e7\u00e3o anormal do sistema de freio e aumenta a press\u00e3o do circuito at\u00e9 a interven\u00e7\u00e3o do ABS.<\/li>\n<li>Performance Hidr\u00e1ulica do freio traseiro\u00a0 = no caso de uma frenagem de emerg\u00eancia, quando os freios dianteiros j\u00e1 est\u00e3o em controle de ABS, aumenta a press\u00e3o nos freios traseiros, maximizando a efici\u00eancia total da frenagem.<\/li>\n<li>Controle estendido de estabilidade = no caso de o ve\u00edculo perder ader\u00eancia das rodas dianteiras atua intervindo no torque e no freio aumentando a capacidade de manobra.<\/li>\n<li>Interven\u00e7\u00e3o do movimento de rolagem = suaviza situa\u00e7\u00f5es de rolagem perigosa durante a condu\u00e7\u00e3o altamente din\u00e2mica.<\/li>\n<li>Mitiga\u00e7\u00e3o de capotagem = suaviza situa\u00e7\u00f5es de rolagem perigosa durante situa\u00e7\u00f5es de parada.<\/li>\n<li>Mitiga\u00e7\u00e3o do balan\u00e7o do reboque = mitiga\u00e7\u00e3o da instabilidade do trailer.<\/li>\n<li>Modo de controle adaptativo de carga = controle adaptativo de carga.<\/li>\n<li>Controle de partida em subidas = mant\u00e9m a press\u00e3o nos freios por dois ou tr\u00eas segundos, auxiliando na partida do ve\u00edculo em rampas.<\/li>\n<\/ul>\n<p>(Coisas de Agora)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coisas de Agora &nbsp; Apresentada em 2020, a linha do Novo IVECO Daily j\u00e1 mostrou ampla versatilidade em aplica\u00e7\u00f5es que v\u00e3o al\u00e9m do transporte de cargas, como as vers\u00f5es motorhome, verdadeiras \u2018casas sobre rodas\u2019. Recentemente quatro unidades ambul\u00e2ncia, montadas sobre a estrutura chassi-cabine, entraram para a frota da Way-306 para refor\u00e7ar o atendimento de emerg\u00eancia\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-48459","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novo IVECO Daily pronto para emerg\u00eancias nas rodovias do Brasil - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novo IVECO Daily pronto para emerg\u00eancias nas rodovias do Brasil - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Coisas de Agora &nbsp; Apresentada em 2020, a linha do Novo IVECO Daily j\u00e1 mostrou ampla versatilidade em aplica\u00e7\u00f5es que v\u00e3o al\u00e9m do transporte de cargas, como as vers\u00f5es motorhome, verdadeiras \u2018casas sobre rodas\u2019. Recentemente quatro unidades ambul\u00e2ncia, montadas sobre a estrutura chassi-cabine, entraram para a frota da Way-306 para refor\u00e7ar o atendimento de emerg\u00eancia\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-03T11:14:15+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/03\\\/03\\\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/03\\\/03\\\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Novo IVECO Daily pronto para emerg\u00eancias nas rodovias do Brasil\",\"datePublished\":\"2021-03-03T11:14:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/03\\\/03\\\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\\\/\"},\"wordCount\":1079,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/03\\\/03\\\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/03\\\/03\\\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\\\/\",\"name\":\"Novo IVECO Daily pronto para emerg\u00eancias nas rodovias do Brasil - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2021-03-03T11:14:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/03\\\/03\\\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/03\\\/03\\\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2021\\\/03\\\/03\\\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Novo IVECO Daily pronto para emerg\u00eancias nas rodovias do Brasil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novo IVECO Daily pronto para emerg\u00eancias nas rodovias do Brasil - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/","og_locale":"pt_BR","og_type":"article","og_title":"Novo IVECO Daily pronto para emerg\u00eancias nas rodovias do Brasil - Canal Dana","og_description":"Coisas de Agora &nbsp; Apresentada em 2020, a linha do Novo IVECO Daily j\u00e1 mostrou ampla versatilidade em aplica\u00e7\u00f5es que v\u00e3o al\u00e9m do transporte de cargas, como as vers\u00f5es motorhome, verdadeiras \u2018casas sobre rodas\u2019. Recentemente quatro unidades ambul\u00e2ncia, montadas sobre a estrutura chassi-cabine, entraram para a frota da Way-306 para refor\u00e7ar o atendimento de emerg\u00eancia\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/","og_site_name":"Canal Dana","article_published_time":"2021-03-03T11:14:15+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Novo IVECO Daily pronto para emerg\u00eancias nas rodovias do Brasil","datePublished":"2021-03-03T11:14:15+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/"},"wordCount":1079,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/","url":"https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/","name":"Novo IVECO Daily pronto para emerg\u00eancias nas rodovias do Brasil - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2021-03-03T11:14:15+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2021\/03\/03\/novo-iveco-daily-pronto-para-emergencias-nas-rodovias-do-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Novo IVECO Daily pronto para emerg\u00eancias nas rodovias do Brasil"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/48459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=48459"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/48459\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=48459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=48459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=48459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}