{"id":45336,"date":"2020-10-06T08:29:58","date_gmt":"2020-10-06T11:29:58","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=45336"},"modified":"2020-10-06T08:29:58","modified_gmt":"2020-10-06T11:29:58","slug":"daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/","title":{"rendered":"DAF Caminh\u00f5es Brasil completa sete anos de opera\u00e7\u00e3o no pa\u00eds e comemora o desempenho da marca em 2020"},"content":{"rendered":"<p><em>Mec\u00e2nica Online<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Neste m\u00eas de outubro, a DAF Caminh\u00f5es Brasil comemora sete anos de opera\u00e7\u00e3o no pa\u00eds, com o novo XF, principal lan\u00e7amento da companhia ao longo desses anos.<\/p>\n<p>&nbsp;<\/p>\n<p>Produzido em sua f\u00e1brica situada em Ponta Grossa (PR), o novo XF chega para elevar o patamar de extrapesados no Brasil, com ainda mais seguran\u00e7a, conforto, dirigibilidade e economia de combust\u00edvel.<\/p>\n<p>&nbsp;<\/p>\n<p>A companhia tamb\u00e9m celebra a sua posi\u00e7\u00e3o no segmento de pesados, figurando entre as principais marcas do pa\u00eds, com mais de 10 mil caminh\u00f5es emplacados rodando pelas estradas brasileiras.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cO ano de 2020 \u00e9 muito especial para a DAF. Independentemente do momento que o pa\u00eds vive, temos muito orgulho de todo o nosso crescimento, enquanto profissionais e empresa, para o desenvolvimento de produtos cada vez melhores e que atendam sempre \u00e0s necessidades de nossos clientes. Durante esses sete anos, evolu\u00edmos em um ritmo acelerado e, neste ano, mantivemos a nossa estrat\u00e9gia de longo prazo com o mercado brasileiro. A maior prova disso \u00e9 o novo XF, que tem grande relev\u00e2ncia em nosso objetivo de nos solidificarmos ainda mais com as qualidades de robustez, conforto e baixo custo operacional\u201d, comenta Lance Walters, Presidente da DAF Caminh\u00f5es Brasil.<\/p>\n<p>&nbsp;<\/p>\n<p>Atualmente, a marca tem 41 pontos de atendimento, sendo 33 concession\u00e1rias, 5 Postos de Servi\u00e7o Autorizado e mais 3 Lojas TRP.<\/p>\n<p>&nbsp;<\/p>\n<p>O foco da DAF para os pr\u00f3ximos anos \u00e9 ampliar a Rede de Concession\u00e1rias para proporcionar uma experi\u00eancia cada vez mais assertiva para os clientes, manter o seu portf\u00f3lio atualizado e compat\u00edvel com as necessidades locais para manter-se como refer\u00eancia no segmento de pesados.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cPara isso, contamos com uma equipe muito comprometida e focada, que busca a evolu\u00e7\u00e3o constante, engajada com os nossos valores de qualidade e produtividade. Consequentemente, nossos produtos s\u00e3o reconhecidos no mercado pelo DNA de robustez, conforto e baixo consumo de combust\u00edvel. Agora, estamos prontos para o pr\u00f3ximo desafio que \u00e9 alcan\u00e7ar a lideran\u00e7a do novo XF no mercado\u201d, avalia Walters.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Trajet\u00f3ria da empresa<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>A DAF Trucks, fundada em 1928 na cidade de Eindhoven, na Holanda, \u00e9 uma das subsidi\u00e1rias do grupo americano PACCAR, que tamb\u00e9m possui as marcas de caminh\u00f5es Kenworth e Peterbilt.<\/p>\n<p>&nbsp;<\/p>\n<p>Atualmente, a DAF Trucks \u00e9 a que mais cresce na Europa e, al\u00e9m da matriz, holandesa, est\u00e1 presente na B\u00e9lgica, Inglaterra, Brasil e Austr\u00e1lia.<\/p>\n<p>&nbsp;<\/p>\n<p>A empresa chegou ao Brasil em 2011 e, dois anos depois, inaugurou sua f\u00e1brica em Ponta Grossa, no Paran\u00e1, em um terreno de 2,3 milh\u00f5es de m\u00b2, a maior \u00e1rea do Grupo PACCAR.<\/p>\n<p>&nbsp;<\/p>\n<p>O espa\u00e7o destinado \u00e0 f\u00e1brica possui 270 mil m\u00b2 e conta com aproximadamente 500 funcion\u00e1rios.<\/p>\n<p>&nbsp;<\/p>\n<p>Na unidade, a empresa iniciou esse ano a produ\u00e7\u00e3o do novo XF. Al\u00e9m disso, fabrica o XF105, desde 2013, e o pesado CF85, desde 2015.<\/p>\n<p>&nbsp;<\/p>\n<p>Desde novembro de 2015, a planta tamb\u00e9m produz os motores PACCAR MX, que equipam os caminh\u00f5es nacionais DAF.<\/p>\n<p>&nbsp;<\/p>\n<p>Em 2017, foram lan\u00e7adas as vers\u00f5es fora de estrada, desenvolvidas em parceria com a sede na Holanda.<\/p>\n<p>&nbsp;<\/p>\n<p>O processo de produ\u00e7\u00e3o em Ponta Grossa segue o princ\u00edpio do PPS (PACCAR Production System), sistema desenvolvido pela pr\u00f3pria empresa, que garante menor \u00edndice de desperd\u00edcio e a mais alta qualidade dos produtos. (Mec\u00e2nica Online)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mec\u00e2nica Online &nbsp; Neste m\u00eas de outubro, a DAF Caminh\u00f5es Brasil comemora sete anos de opera\u00e7\u00e3o no pa\u00eds, com o novo XF, principal lan\u00e7amento da companhia ao longo desses anos. &nbsp; Produzido em sua f\u00e1brica situada em Ponta Grossa (PR), o novo XF chega para elevar o patamar de extrapesados no Brasil, com ainda mais\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[61],"tags":[],"class_list":["post-45336","post","type-post","status-publish","format-standard","hentry","category-destaques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DAF Caminh\u00f5es Brasil completa sete anos de opera\u00e7\u00e3o no pa\u00eds e comemora o desempenho da marca em 2020 - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAF Caminh\u00f5es Brasil completa sete anos de opera\u00e7\u00e3o no pa\u00eds e comemora o desempenho da marca em 2020 - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Mec\u00e2nica Online &nbsp; Neste m\u00eas de outubro, a DAF Caminh\u00f5es Brasil comemora sete anos de opera\u00e7\u00e3o no pa\u00eds, com o novo XF, principal lan\u00e7amento da companhia ao longo desses anos. &nbsp; Produzido em sua f\u00e1brica situada em Ponta Grossa (PR), o novo XF chega para elevar o patamar de extrapesados no Brasil, com ainda mais\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-06T11:29:58+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"DAF Caminh\u00f5es Brasil completa sete anos de opera\u00e7\u00e3o no pa\u00eds e comemora o desempenho da marca em 2020\",\"datePublished\":\"2020-10-06T11:29:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\\\/\"},\"wordCount\":590,\"articleSection\":[\"Destaques\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\\\/\",\"name\":\"DAF Caminh\u00f5es Brasil completa sete anos de opera\u00e7\u00e3o no pa\u00eds e comemora o desempenho da marca em 2020 - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2020-10-06T11:29:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destaques\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/destaques\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DAF Caminh\u00f5es Brasil completa sete anos de opera\u00e7\u00e3o no pa\u00eds e comemora o desempenho da marca em 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DAF Caminh\u00f5es Brasil completa sete anos de opera\u00e7\u00e3o no pa\u00eds e comemora o desempenho da marca em 2020 - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/","og_locale":"pt_BR","og_type":"article","og_title":"DAF Caminh\u00f5es Brasil completa sete anos de opera\u00e7\u00e3o no pa\u00eds e comemora o desempenho da marca em 2020 - Canal Dana","og_description":"Mec\u00e2nica Online &nbsp; Neste m\u00eas de outubro, a DAF Caminh\u00f5es Brasil comemora sete anos de opera\u00e7\u00e3o no pa\u00eds, com o novo XF, principal lan\u00e7amento da companhia ao longo desses anos. &nbsp; Produzido em sua f\u00e1brica situada em Ponta Grossa (PR), o novo XF chega para elevar o patamar de extrapesados no Brasil, com ainda mais\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/","og_site_name":"Canal Dana","article_published_time":"2020-10-06T11:29:58+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"DAF Caminh\u00f5es Brasil completa sete anos de opera\u00e7\u00e3o no pa\u00eds e comemora o desempenho da marca em 2020","datePublished":"2020-10-06T11:29:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/"},"wordCount":590,"articleSection":["Destaques"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/","url":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/","name":"DAF Caminh\u00f5es Brasil completa sete anos de opera\u00e7\u00e3o no pa\u00eds e comemora o desempenho da marca em 2020 - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2020-10-06T11:29:58+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/daf-caminhoes-brasil-completa-sete-anos-de-operacao-no-pais-e-comemora-o-desempenho-da-marca-em-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Destaques","item":"https:\/\/dana.com.br\/canaldana\/destaques\/"},{"@type":"ListItem","position":3,"name":"DAF Caminh\u00f5es Brasil completa sete anos de opera\u00e7\u00e3o no pa\u00eds e comemora o desempenho da marca em 2020"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/45336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=45336"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/45336\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=45336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=45336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=45336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}