{"id":45328,"date":"2020-10-06T08:27:11","date_gmt":"2020-10-06T11:27:11","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=45328"},"modified":"2020-10-06T08:27:11","modified_gmt":"2020-10-06T11:27:11","slug":"mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/","title":{"rendered":"Mercado de ve\u00edculos importados tem queda de 31,2% e d\u00f3lar alto pode agravar situa\u00e7\u00e3o"},"content":{"rendered":"<p><em>Jornal do Carro<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>A Abeifa (Associa\u00e7\u00e3o Brasileira das Empresas Importadores e Fabricante de Ve\u00edculos Automotores) divulgou nesta sexta-feira (2) o balan\u00e7o do terceiro trimestre e do acumulado no ano. Houve uma queda de 31,2% na compra de ve\u00edculos importados entre janeiro e setembro deste ano em compara\u00e7\u00e3o a 2019.<\/p>\n<p>&nbsp;<\/p>\n<p>A retra\u00e7\u00e3o foi ainda maior nas vendas de autom\u00f3veis e comerciais leves nacionais e importados. Cerca de 32,9%. Para os associados da Abeifa, que re\u00fane montadoras como BMW, Jaguar Land Rover, Volvo, CAOA Chery, Porsche, Kia e Lamborghini, o tombo nos nove primeiros meses foi de 20,8% em rela\u00e7\u00e3o a 2019.<\/p>\n<p>&nbsp;<\/p>\n<p>Com o reaquecimento do mercado, a perspectiva \u00e9 de fechar o ano ainda em queda. Por\u00e9m com uma porcentagem menor do que a registrada at\u00e9 agora. O d\u00e9ficit em rela\u00e7\u00e3o ao passado dos ve\u00edculos nacionais e importados deve ser de 30%.<\/p>\n<p>&nbsp;<\/p>\n<p>A associa\u00e7\u00e3o, que sofre diretamente com a alta do d\u00f3lar, afirma que esse ano s\u00f3 n\u00e3o foi pior porque as marcas se prepararam para um ano de crescimento. E garantiram estoque com um c\u00e2mbio mais baixo. Com isso, conseguiram estabilizar os pre\u00e7os. Por\u00e9m, assim que os estoques acabarem, podemos esperar um novo lote j\u00e1 com o atual valor do d\u00f3lar.<\/p>\n<p>&nbsp;<\/p>\n<p>A entidade n\u00e3o acredita que as montadoras que importam ve\u00edculos sair\u00e3o do pa\u00eds devido ao d\u00f3lar alto, visto que para o pr\u00f3ximo ano a tend\u00eancia \u00e9 de uma leve baixa e estabiliza\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>Contudo, talvez seja necess\u00e1ria uma mudan\u00e7a no portf\u00f3lio das marcas e uma mudan\u00e7a no nicho do consumidor. \u201cInvestimentos industriais demonstram o compromisso de longo prazo que as marcas tem com o pa\u00eds. N\u00e3o devem cessar esse tipo de opera\u00e7\u00e3o.\u201d, afirma o presidente da Abeifa, Jo\u00e3o Henrique Oliveira.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Trabalho junto ao governo<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Oliveira ainda refor\u00e7ou a necessidade de duas aprova\u00e7\u00f5es de pauta junto ao governo. A da redu\u00e7\u00e3o do Imposto de Importa\u00e7\u00e3o de 35% para 20%, adaptando ao praticado pelo M\u00e9xico e Mercosul. E da compatibilidade das al\u00edquotas do Imposto sobre Produtos Industrializados (IPI) para h\u00edbridos e el\u00e9tricos.<\/p>\n<p>&nbsp;<\/p>\n<p>O imposto se torna mais caro do que em vers\u00f5es com motor a combust\u00e3o, pois o c\u00e1lculo \u00e9 feito de acordo com o peso do ve\u00edculo e a bateria el\u00e9trica tende a ser mais pesada.<\/p>\n<p>&nbsp;<\/p>\n<p>Com a paralisa\u00e7\u00e3o das atividades executivas, como o Congresso e o Senado, ficou mais dif\u00edcil das reformas serem apresentadas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Eletrificados aceleraram \u00e0s vendas da Porsche<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Das marcas associadas pela Abeifa, a Volvo \u00e9 que tem a maior participa\u00e7\u00e3o no mercado, com quase um quarto dos ve\u00edculos importados. Foram 4.813 unidades importadas neste ano. Uma queda de 11,8% em compara\u00e7\u00e3o ao ano passado.<\/p>\n<p>&nbsp;<\/p>\n<p>Entretanto, o destaque fica para Porsche, que teve um aumento de 62,5% de seus carros importados em rela\u00e7\u00e3o a 2019. Segundo Oliveira, os novos lan\u00e7amentos de h\u00edbridos e el\u00e9tricos da marca como Porsche Taycan levaram a uma maior procura por ve\u00edculos da montadora austr\u00edaca.<\/p>\n<p>&nbsp;<\/p>\n<p>O segmento de ve\u00edculos eletrificados \u00e9 de grande import\u00e2ncia para a entidade. Dado que quase metade dos carros el\u00e9tricos e h\u00edbridos vendidos no pa\u00eds s\u00e3o importados e produzidos por montadoras associadas. A categoria ainda corresponde a 3% do mercado e, segundo o dirigente da Abeifa, ser\u00e1 necess\u00e1ria a aprova\u00e7\u00e3o de diminui\u00e7\u00e3o do IPI pelo governo para o pre\u00e7o do ve\u00edculo el\u00e9trico, especialmente o SUV, ficar atraente e conquistar o poss\u00edvel consumidor. (Jornal do Carro)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jornal do Carro &nbsp; A Abeifa (Associa\u00e7\u00e3o Brasileira das Empresas Importadores e Fabricante de Ve\u00edculos Automotores) divulgou nesta sexta-feira (2) o balan\u00e7o do terceiro trimestre e do acumulado no ano. Houve uma queda de 31,2% na compra de ve\u00edculos importados entre janeiro e setembro deste ano em compara\u00e7\u00e3o a 2019. &nbsp; A retra\u00e7\u00e3o foi ainda\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-45328","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercado de ve\u00edculos importados tem queda de 31,2% e d\u00f3lar alto pode agravar situa\u00e7\u00e3o - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercado de ve\u00edculos importados tem queda de 31,2% e d\u00f3lar alto pode agravar situa\u00e7\u00e3o - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Jornal do Carro &nbsp; A Abeifa (Associa\u00e7\u00e3o Brasileira das Empresas Importadores e Fabricante de Ve\u00edculos Automotores) divulgou nesta sexta-feira (2) o balan\u00e7o do terceiro trimestre e do acumulado no ano. Houve uma queda de 31,2% na compra de ve\u00edculos importados entre janeiro e setembro deste ano em compara\u00e7\u00e3o a 2019. &nbsp; A retra\u00e7\u00e3o foi ainda\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-06T11:27:11+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Mercado de ve\u00edculos importados tem queda de 31,2% e d\u00f3lar alto pode agravar situa\u00e7\u00e3o\",\"datePublished\":\"2020-10-06T11:27:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\\\/\"},\"wordCount\":629,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\\\/\",\"name\":\"Mercado de ve\u00edculos importados tem queda de 31,2% e d\u00f3lar alto pode agravar situa\u00e7\u00e3o - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2020-10-06T11:27:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mercado de ve\u00edculos importados tem queda de 31,2% e d\u00f3lar alto pode agravar situa\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercado de ve\u00edculos importados tem queda de 31,2% e d\u00f3lar alto pode agravar situa\u00e7\u00e3o - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Mercado de ve\u00edculos importados tem queda de 31,2% e d\u00f3lar alto pode agravar situa\u00e7\u00e3o - Canal Dana","og_description":"Jornal do Carro &nbsp; A Abeifa (Associa\u00e7\u00e3o Brasileira das Empresas Importadores e Fabricante de Ve\u00edculos Automotores) divulgou nesta sexta-feira (2) o balan\u00e7o do terceiro trimestre e do acumulado no ano. Houve uma queda de 31,2% na compra de ve\u00edculos importados entre janeiro e setembro deste ano em compara\u00e7\u00e3o a 2019. &nbsp; A retra\u00e7\u00e3o foi ainda\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/","og_site_name":"Canal Dana","article_published_time":"2020-10-06T11:27:11+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Mercado de ve\u00edculos importados tem queda de 31,2% e d\u00f3lar alto pode agravar situa\u00e7\u00e3o","datePublished":"2020-10-06T11:27:11+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/"},"wordCount":629,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/","url":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/","name":"Mercado de ve\u00edculos importados tem queda de 31,2% e d\u00f3lar alto pode agravar situa\u00e7\u00e3o - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2020-10-06T11:27:11+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/mercado-de-veiculos-importados-tem-queda-de-312-e-dolar-alto-pode-agravar-situacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Mercado de ve\u00edculos importados tem queda de 31,2% e d\u00f3lar alto pode agravar situa\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/45328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=45328"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/45328\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=45328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=45328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=45328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}