{"id":45324,"date":"2020-10-06T08:25:45","date_gmt":"2020-10-06T11:25:45","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=45324"},"modified":"2020-10-06T08:25:45","modified_gmt":"2020-10-06T11:25:45","slug":"volvo-car-supera-a-audi-em-vendas-no-segmento-premium","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/","title":{"rendered":"Volvo Car supera a Audi em vendas no segmento premium"},"content":{"rendered":"<p><em>AutoInd\u00fastria<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Com planos de parar de produzir no Brasil, a alem\u00e3 Audi perdeu posi\u00e7\u00e3o para a Volvo Car no segmento premium. A marca sueca bateu recorde de vendas em setembro, com 788 emplacamentos, contra os 785 licenciamentos da alem\u00e3.<\/p>\n<p>&nbsp;<\/p>\n<p>De acordo com dados da Fenabrave, no acumulado dos primeiros nove meses de 2020 a BMW aparece em primeiro lugar entre as marcas de luxo, com 8.599 licenciamentos, seguida da Mercedes-Benz, com 6.712, da Volvo Car (4.813) e da Audi (4.701).<\/p>\n<p>&nbsp;<\/p>\n<p>Essa mesma ordem aparece no balan\u00e7o da entidade relativo ao m\u00eas de setembro, com a BMW tendo comercializado 1.361 unidades e a Mercedes-Benz, 880. O diretor geral de opera\u00e7\u00f5es e inova\u00e7\u00e3o da Volvo Car Brasil, Jo\u00e3o Oliveira, comemora o melhor m\u00eas de varejo da hist\u00f3ria da marca no Brasil:<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cOs resultados mostram que estamos corretos em nossas convic\u00e7\u00f5es. O futuro do mercado premium ser\u00e1 eletrificado e esse futuro j\u00e1 \u00e9 parte do nosso presente, estamos acelerando a migra\u00e7\u00e3o para os ve\u00edculos h\u00edbridos ainda mais e investindo em estrutura em todo o Brasil para termos 700 eletropostos at\u00e9 o fim deste ano, ampliando as possibilidades para os clientes usarem os ve\u00edculos no modo el\u00e9trico em diversos lugares\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>O grande destaque da marca sueca s\u00e3o os SUVs. Segundo a empresa, as vendas somadas do XC90, XC60 e XC40 levam os ve\u00edculos \u00e0 1\u00aa posi\u00e7\u00e3o entre os SUVs premium, com 26,2% de mercado no m\u00eas de setembro e na lideran\u00e7a do acumulado do ano, com 22%.<\/p>\n<p>&nbsp;<\/p>\n<p>A Volvo Car emplacou em 2019 quase 8 mil ve\u00edculos, registrando crescimento de 15,8% em rela\u00e7\u00e3o ao ano anterior. A marca conquistou a lideran\u00e7a no segmento de ve\u00edculos eletrificados, com 1,1 mil carros h\u00edbridos licenciados, posi\u00e7\u00e3o que mant\u00e9m este ano. J\u00e1 licenciou mais de 1,8 mil unidades nesse segmento, dominando a expressiva participa\u00e7\u00e3o de 60,9%. (AutoInd\u00fastria)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AutoInd\u00fastria &nbsp; Com planos de parar de produzir no Brasil, a alem\u00e3 Audi perdeu posi\u00e7\u00e3o para a Volvo Car no segmento premium. A marca sueca bateu recorde de vendas em setembro, com 788 emplacamentos, contra os 785 licenciamentos da alem\u00e3. &nbsp; De acordo com dados da Fenabrave, no acumulado dos primeiros nove meses de 2020\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-45324","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Volvo Car supera a Audi em vendas no segmento premium - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volvo Car supera a Audi em vendas no segmento premium - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"AutoInd\u00fastria &nbsp; Com planos de parar de produzir no Brasil, a alem\u00e3 Audi perdeu posi\u00e7\u00e3o para a Volvo Car no segmento premium. A marca sueca bateu recorde de vendas em setembro, com 788 emplacamentos, contra os 785 licenciamentos da alem\u00e3. &nbsp; De acordo com dados da Fenabrave, no acumulado dos primeiros nove meses de 2020\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-06T11:25:45+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Volvo Car supera a Audi em vendas no segmento premium\",\"datePublished\":\"2020-10-06T11:25:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\\\/\"},\"wordCount\":323,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\\\/\",\"name\":\"Volvo Car supera a Audi em vendas no segmento premium - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2020-10-06T11:25:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/06\\\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Volvo Car supera a Audi em vendas no segmento premium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Volvo Car supera a Audi em vendas no segmento premium - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/","og_locale":"pt_BR","og_type":"article","og_title":"Volvo Car supera a Audi em vendas no segmento premium - Canal Dana","og_description":"AutoInd\u00fastria &nbsp; Com planos de parar de produzir no Brasil, a alem\u00e3 Audi perdeu posi\u00e7\u00e3o para a Volvo Car no segmento premium. A marca sueca bateu recorde de vendas em setembro, com 788 emplacamentos, contra os 785 licenciamentos da alem\u00e3. &nbsp; De acordo com dados da Fenabrave, no acumulado dos primeiros nove meses de 2020\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/","og_site_name":"Canal Dana","article_published_time":"2020-10-06T11:25:45+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Volvo Car supera a Audi em vendas no segmento premium","datePublished":"2020-10-06T11:25:45+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/"},"wordCount":323,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/","url":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/","name":"Volvo Car supera a Audi em vendas no segmento premium - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2020-10-06T11:25:45+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/06\/volvo-car-supera-a-audi-em-vendas-no-segmento-premium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Volvo Car supera a Audi em vendas no segmento premium"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/45324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=45324"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/45324\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=45324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=45324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=45324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}