{"id":45232,"date":"2020-10-01T09:02:23","date_gmt":"2020-10-01T12:02:23","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=45232"},"modified":"2020-10-01T09:02:23","modified_gmt":"2020-10-01T12:02:23","slug":"valor-do-diesel-sobe-3","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/","title":{"rendered":"Valor do diesel sobe 3%"},"content":{"rendered":"<p><em>Blog do Caminhoneiro<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>A Petrobras anunciou ontem um aumento de 3% para o valor do diesel em suas refinarias, que passou a valer hoje. Desde agosto, o valor do diesel havia sido reduzido 3 vezes. A \u00faltima alta foi em 20 de agosto.<\/p>\n<p>&nbsp;<\/p>\n<p>O valor da gasolina tamb\u00e9m sofreu aumento, de 5%. Esse \u00e9 o segundo aumento seguido, ap\u00f3s um reajuste de 4% na semana passada.<\/p>\n<p>&nbsp;<\/p>\n<p>Nas refinarias, em m\u00e9dia, o valor do diesel \u00e9 comercializado para as distribuidoras por R$ 1,557 por litro.<\/p>\n<p>&nbsp;<\/p>\n<p>Apesar dessa alta, o valor do diesel est\u00e1 33,5% menor do que em 2019, segundo n\u00fameros divulgados pela Petrobras. Em abril, o valor do diesel nas refinarias chegou a R$ 1,30 o litro.<\/p>\n<p>&nbsp;<\/p>\n<p>O pre\u00e7o dos combust\u00edveis nas refinarias varia de acordo com a cota\u00e7\u00e3o do pre\u00e7o do petr\u00f3leo no mercado internacional, e tamb\u00e9m com a cota\u00e7\u00e3o do d\u00f3lar.<\/p>\n<p>&nbsp;<\/p>\n<p>O repasse das varia\u00e7\u00f5es de pre\u00e7o ao consumidor, sempre maiores do que as altas anunciadas pela Petrobras, se devem ao acr\u00e9scimo de impostos, custos de transporte, e outros valores adicionados pelas distribuidoras e postos de combust\u00edvel. (Blog do Caminhoneiro\/Rafael Brusque)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blog do Caminhoneiro &nbsp; A Petrobras anunciou ontem um aumento de 3% para o valor do diesel em suas refinarias, que passou a valer hoje. Desde agosto, o valor do diesel havia sido reduzido 3 vezes. A \u00faltima alta foi em 20 de agosto. &nbsp; O valor da gasolina tamb\u00e9m sofreu aumento, de 5%. Esse\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-45232","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Valor do diesel sobe 3% - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valor do diesel sobe 3% - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Blog do Caminhoneiro &nbsp; A Petrobras anunciou ontem um aumento de 3% para o valor do diesel em suas refinarias, que passou a valer hoje. Desde agosto, o valor do diesel havia sido reduzido 3 vezes. A \u00faltima alta foi em 20 de agosto. &nbsp; O valor da gasolina tamb\u00e9m sofreu aumento, de 5%. Esse\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-01T12:02:23+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/01\\\/valor-do-diesel-sobe-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/01\\\/valor-do-diesel-sobe-3\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Valor do diesel sobe 3%\",\"datePublished\":\"2020-10-01T12:02:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/01\\\/valor-do-diesel-sobe-3\\\/\"},\"wordCount\":199,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/01\\\/valor-do-diesel-sobe-3\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/01\\\/valor-do-diesel-sobe-3\\\/\",\"name\":\"Valor do diesel sobe 3% - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2020-10-01T12:02:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/01\\\/valor-do-diesel-sobe-3\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/01\\\/valor-do-diesel-sobe-3\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/10\\\/01\\\/valor-do-diesel-sobe-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Valor do diesel sobe 3%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valor do diesel sobe 3% - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/","og_locale":"pt_BR","og_type":"article","og_title":"Valor do diesel sobe 3% - Canal Dana","og_description":"Blog do Caminhoneiro &nbsp; A Petrobras anunciou ontem um aumento de 3% para o valor do diesel em suas refinarias, que passou a valer hoje. Desde agosto, o valor do diesel havia sido reduzido 3 vezes. A \u00faltima alta foi em 20 de agosto. &nbsp; O valor da gasolina tamb\u00e9m sofreu aumento, de 5%. Esse\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/","og_site_name":"Canal Dana","article_published_time":"2020-10-01T12:02:23+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Valor do diesel sobe 3%","datePublished":"2020-10-01T12:02:23+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/"},"wordCount":199,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/","url":"https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/","name":"Valor do diesel sobe 3% - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2020-10-01T12:02:23+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2020\/10\/01\/valor-do-diesel-sobe-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Valor do diesel sobe 3%"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/45232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=45232"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/45232\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=45232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=45232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=45232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}