{"id":45147,"date":"2020-09-29T08:39:11","date_gmt":"2020-09-29T11:39:11","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=45147"},"modified":"2020-09-29T08:39:11","modified_gmt":"2020-09-29T11:39:11","slug":"bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/","title":{"rendered":"BMW expande n\u00facleos de desenvolvimento de software no Brasil"},"content":{"rendered":"<p><em>Revista Torque<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>O BMW Group avan\u00e7a na ofensiva de liderar a transforma\u00e7\u00e3o da ind\u00fastria da mobilidade com desenvolvimento de engenharia em diversas partes do mundo. Assim como suspens\u00e3o, chassi, motores e componentes de hardwares, os produtos digitais s\u00e3o cada vez mais decisivos para entusiasmar os clientes. Em meio a um processo de expans\u00e3o dos n\u00facleos de desenvolvimento de software em todo mundo, a marca expande suas equipes de desenvolvimentos tamb\u00e9m no Brasil.<\/p>\n<p>&nbsp;<\/p>\n<p>No Pa\u00eds, o n\u00facleo de engenharia foi criado em 2014 pelo BMW Group e em 2017 se intensificou com o prop\u00f3sito de atender n\u00e3o apenas ao mercado interno, mas tamb\u00e9m \u00e0s demandas globais de tecnologia do BMW Group. Atualmente, o n\u00facleo brasileiro, composto por seis equipes, integra um hub global, que \u00e9 respons\u00e1vel pelo desenvolvimento de novas tecnologias vinculadas aos aplicativos BMW e MINI Connected. Al\u00e9m disso, as equipes nacionais tamb\u00e9m s\u00e3o respons\u00e1veis pela implanta\u00e7\u00e3o dos apps em novos mercados em todo o mundo, com bons resultados alcan\u00e7ados em pa\u00edses como Canad\u00e1 e R\u00fassia.<\/p>\n<p>&nbsp;<\/p>\n<p>No projeto, s\u00e3o utilizadas modernas metodologias para desenvolvimento de software, sempre alinhadas ao padr\u00e3o mundial da marca. Protagonista atual, a metodologia \u00c1gil busca alcan\u00e7ar um ambiente altamente colaborativo, auto gerenci\u00e1vel, flex\u00edvel e que trabalha com foco no valor entregue aos usu\u00e1rios. \u201cTemos um bom retrospecto em desenvolvimento de software no Brasil. O time est\u00e1 motivado, \u00e9 criativo e possui as compet\u00eancias t\u00e9cnicas necess\u00e1rias nos mais modernos processos de desenvolvimento. O Brasil, particularmente, se sobressai na boa utiliza\u00e7\u00e3o do \u00c1gil com seus princ\u00edpios e ferramentas\u201d afirma Jens Klingseisen, Gerente S\u00eanior de Engenharia da BMW do Brasil.<\/p>\n<p>&nbsp;<\/p>\n<p>Em processo de expans\u00e3o, os planos preveem a amplia\u00e7\u00e3o do n\u00facleo para 10 equipes at\u00e9 o final de 2022. A experi\u00eancia positiva e os bons resultados apresentados pelo n\u00facleo nacional incentivam esta expans\u00e3o. \u201cPara a BMW, como empresa de tecnologia, \u00e9 importante ter acesso aos melhores talentos em desenvolvimento de software mundialmente. No Brasil, encontramos circunst\u00e2ncias favor\u00e1veis, com excelentes universidades, polos de tecnologia em expans\u00e3o e cultura de uso de aplicativos\u201d afirma Herbert Negele, Diretor de Engenharia da BMW do Brasil.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m de fornecedores e desenvolvedores para atender a demandas globais voltadas ao BMW e MINI Connected, as equipes que operam no Brasil tamb\u00e9m atuam com solu\u00e7\u00f5es em nuvem (Cloud), visando otimizar o desempenho de funcionalidades, garantir a seguran\u00e7a no tratamento de dados e ampliar cada vez mais o horizonte dos servi\u00e7os digitais atuais e futuros da marca.<\/p>\n<p>&nbsp;<\/p>\n<p>O n\u00facleo nacional integra, por exemplo, o hub respons\u00e1vel pelo desenvolvimento da tecnologia Remote 3D View, vinculada ao app BMW Connected. O sistema utiliza as c\u00e2meras existentes no ve\u00edculo para fornecer uma vis\u00e3o 360\u00ba de seus entornos, acess\u00edvel pela interface dos aplicativos BMW Connected, em ve\u00edculos compat\u00edveis. Com isso, o usu\u00e1rio, de dentro de um restaurante, teatro ou evento que se encontra, pode eventualmente checar se o ve\u00edculo se encontra seguro no local que foi estacionado ou at\u00e9 mesmo verificar os arredores do carro momentos antes de seguir o embarque. (Revista Torque)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Revista Torque &nbsp; O BMW Group avan\u00e7a na ofensiva de liderar a transforma\u00e7\u00e3o da ind\u00fastria da mobilidade com desenvolvimento de engenharia em diversas partes do mundo. Assim como suspens\u00e3o, chassi, motores e componentes de hardwares, os produtos digitais s\u00e3o cada vez mais decisivos para entusiasmar os clientes. Em meio a um processo de expans\u00e3o dos\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113],"tags":[],"class_list":["post-45147","post","type-post","status-publish","format-standard","hentry","category-tecnologia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BMW expande n\u00facleos de desenvolvimento de software no Brasil - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BMW expande n\u00facleos de desenvolvimento de software no Brasil - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Revista Torque &nbsp; O BMW Group avan\u00e7a na ofensiva de liderar a transforma\u00e7\u00e3o da ind\u00fastria da mobilidade com desenvolvimento de engenharia em diversas partes do mundo. Assim como suspens\u00e3o, chassi, motores e componentes de hardwares, os produtos digitais s\u00e3o cada vez mais decisivos para entusiasmar os clientes. Em meio a um processo de expans\u00e3o dos\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-29T11:39:11+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"BMW expande n\u00facleos de desenvolvimento de software no Brasil\",\"datePublished\":\"2020-09-29T11:39:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\\\/\"},\"wordCount\":558,\"articleSection\":[\"Tecnologia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\\\/\",\"name\":\"BMW expande n\u00facleos de desenvolvimento de software no Brasil - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2020-09-29T11:39:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tecnologia\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/tecnologia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BMW expande n\u00facleos de desenvolvimento de software no Brasil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BMW expande n\u00facleos de desenvolvimento de software no Brasil - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/","og_locale":"pt_BR","og_type":"article","og_title":"BMW expande n\u00facleos de desenvolvimento de software no Brasil - Canal Dana","og_description":"Revista Torque &nbsp; O BMW Group avan\u00e7a na ofensiva de liderar a transforma\u00e7\u00e3o da ind\u00fastria da mobilidade com desenvolvimento de engenharia em diversas partes do mundo. Assim como suspens\u00e3o, chassi, motores e componentes de hardwares, os produtos digitais s\u00e3o cada vez mais decisivos para entusiasmar os clientes. Em meio a um processo de expans\u00e3o dos\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/","og_site_name":"Canal Dana","article_published_time":"2020-09-29T11:39:11+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"BMW expande n\u00facleos de desenvolvimento de software no Brasil","datePublished":"2020-09-29T11:39:11+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/"},"wordCount":558,"articleSection":["Tecnologia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/","url":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/","name":"BMW expande n\u00facleos de desenvolvimento de software no Brasil - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2020-09-29T11:39:11+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/bmw-expande-nucleos-de-desenvolvimento-de-software-no-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Tecnologia","item":"https:\/\/dana.com.br\/canaldana\/tecnologia\/"},{"@type":"ListItem","position":3,"name":"BMW expande n\u00facleos de desenvolvimento de software no Brasil"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/45147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=45147"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/45147\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=45147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=45147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=45147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}