{"id":45145,"date":"2020-09-29T08:38:20","date_gmt":"2020-09-29T11:38:20","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=45145"},"modified":"2020-09-29T08:38:20","modified_gmt":"2020-09-29T11:38:20","slug":"sondagem-mostra-recuperacao-da-industria","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/","title":{"rendered":"Sondagem mostra recupera\u00e7\u00e3o da ind\u00fastria"},"content":{"rendered":"<p><em>O Estado de S. Paulo <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>A terceira alta mensal consecutiva na produ\u00e7\u00e3o e nas contrata\u00e7\u00f5es, constatada pela Sondagem Industrial da Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI) relativa a agosto, mostra continuidade e firmeza da recupera\u00e7\u00e3o da atividade industrial.<\/p>\n<p>&nbsp;<\/p>\n<p>Tamb\u00e9m a utiliza\u00e7\u00e3o da capacidade instalada continua a crescer, tendo alcan\u00e7ado 71% em agosto. Est\u00e1, assim, 2 pontos porcentuais acima do \u00edndice apurado em agosto do ano passado. Igualmente, o indicador de utiliza\u00e7\u00e3o da capacidade instalada, medido em pontos (a linha divis\u00f3ria, que indica a atividade usual para o m\u00eas, \u00e9 de 50 pontos), est\u00e1 acima do observado um ano antes e muito pr\u00f3ximo do n\u00edvel de normalidade.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cNa esteira dessa recupera\u00e7\u00e3o, o otimismo do empres\u00e1rio tamb\u00e9m continuou aumentando, impulsionado tanto pela recupera\u00e7\u00e3o da economia como pelo in\u00edcio do per\u00edodo de fim de ano, sazonalmente mais favor\u00e1vel \u00e0 produ\u00e7\u00e3o industrial\u201d, observa o relat\u00f3rio da CNI.<\/p>\n<p>&nbsp;<\/p>\n<p>Em agosto, o \u00edndice de produ\u00e7\u00e3o ficou em 58,7 pontos, um pouco abaixo do registrado em julho, de 59,4 pontos, mas tamb\u00e9m bastante acima da linha divis\u00f3ria.<\/p>\n<p>&nbsp;<\/p>\n<p>O indicador da evolu\u00e7\u00e3o do n\u00famero de empregados chegou a 53,8 pontos em agosto, como consequ\u00eancia do aumento do emprego no setor industrial. \u201cO \u00edndice j\u00e1 havia superado a linha divis\u00f3ria de 50 pontos em julho, quando ficou em 50,9 pontos, mas, ao se afastar da linha, revela alta mais significativa e disseminada do emprego industrial\u201d, na interpreta\u00e7\u00e3o de Marcelo Souza Azevedo, gerente de An\u00e1lise Econ\u00f4mica da CNI.<\/p>\n<p>&nbsp;<\/p>\n<p>Destaque-se o fato de o \u00edndice de evolu\u00e7\u00e3o do emprego de agosto ser o maior da s\u00e9rie hist\u00f3rica mensal, iniciada em janeiro de 2011. Mas \u00e9 preciso levar em conta tamb\u00e9m o fato de que quatro meses antes, quando a pandemia do novo coronav\u00edrus levou \u00e0 paralisa\u00e7\u00e3o de boa parte da atividade econ\u00f4mica, o \u00edndice tinha mostrado forte queda, ficando em 38,2 pontos.<\/p>\n<p>&nbsp;<\/p>\n<p>A despeito da boa evolu\u00e7\u00e3o observada nos \u00faltimos meses, os estoques continuam em queda e em n\u00edvel abaixo do planejado pelo empresariado industrial. A queda vem ocorrendo desde abril.<\/p>\n<p>&nbsp;<\/p>\n<p>Quanto aos pr\u00f3ximos meses, o empresariado est\u00e1 otimista com rela\u00e7\u00e3o ao desempenho da economia, \u00e0 evolu\u00e7\u00e3o da demanda, ao n\u00famero de empregados e \u00e0 inten\u00e7\u00e3o de investir. S\u00e3o bons sinais. (O Estado de S. Paulo)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Estado de S. Paulo &nbsp; A terceira alta mensal consecutiva na produ\u00e7\u00e3o e nas contrata\u00e7\u00f5es, constatada pela Sondagem Industrial da Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI) relativa a agosto, mostra continuidade e firmeza da recupera\u00e7\u00e3o da atividade industrial. &nbsp; Tamb\u00e9m a utiliza\u00e7\u00e3o da capacidade instalada continua a crescer, tendo alcan\u00e7ado 71% em agosto. Est\u00e1, assim,\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[100],"tags":[],"class_list":["post-45145","post","type-post","status-publish","format-standard","hentry","category-artigo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sondagem mostra recupera\u00e7\u00e3o da ind\u00fastria - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sondagem mostra recupera\u00e7\u00e3o da ind\u00fastria - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"O Estado de S. Paulo &nbsp; A terceira alta mensal consecutiva na produ\u00e7\u00e3o e nas contrata\u00e7\u00f5es, constatada pela Sondagem Industrial da Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI) relativa a agosto, mostra continuidade e firmeza da recupera\u00e7\u00e3o da atividade industrial. &nbsp; Tamb\u00e9m a utiliza\u00e7\u00e3o da capacidade instalada continua a crescer, tendo alcan\u00e7ado 71% em agosto. Est\u00e1, assim,\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-29T11:38:20+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/sondagem-mostra-recuperacao-da-industria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/sondagem-mostra-recuperacao-da-industria\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Sondagem mostra recupera\u00e7\u00e3o da ind\u00fastria\",\"datePublished\":\"2020-09-29T11:38:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/sondagem-mostra-recuperacao-da-industria\\\/\"},\"wordCount\":410,\"articleSection\":[\"Artigo\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/sondagem-mostra-recuperacao-da-industria\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/sondagem-mostra-recuperacao-da-industria\\\/\",\"name\":\"Sondagem mostra recupera\u00e7\u00e3o da ind\u00fastria - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2020-09-29T11:38:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/sondagem-mostra-recuperacao-da-industria\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/sondagem-mostra-recuperacao-da-industria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/09\\\/29\\\/sondagem-mostra-recuperacao-da-industria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artigo\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/artigo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sondagem mostra recupera\u00e7\u00e3o da ind\u00fastria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sondagem mostra recupera\u00e7\u00e3o da ind\u00fastria - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/","og_locale":"pt_BR","og_type":"article","og_title":"Sondagem mostra recupera\u00e7\u00e3o da ind\u00fastria - Canal Dana","og_description":"O Estado de S. Paulo &nbsp; A terceira alta mensal consecutiva na produ\u00e7\u00e3o e nas contrata\u00e7\u00f5es, constatada pela Sondagem Industrial da Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI) relativa a agosto, mostra continuidade e firmeza da recupera\u00e7\u00e3o da atividade industrial. &nbsp; Tamb\u00e9m a utiliza\u00e7\u00e3o da capacidade instalada continua a crescer, tendo alcan\u00e7ado 71% em agosto. Est\u00e1, assim,\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/","og_site_name":"Canal Dana","article_published_time":"2020-09-29T11:38:20+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Sondagem mostra recupera\u00e7\u00e3o da ind\u00fastria","datePublished":"2020-09-29T11:38:20+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/"},"wordCount":410,"articleSection":["Artigo"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/","url":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/","name":"Sondagem mostra recupera\u00e7\u00e3o da ind\u00fastria - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2020-09-29T11:38:20+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2020\/09\/29\/sondagem-mostra-recuperacao-da-industria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Artigo","item":"https:\/\/dana.com.br\/canaldana\/artigo\/"},{"@type":"ListItem","position":3,"name":"Sondagem mostra recupera\u00e7\u00e3o da ind\u00fastria"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/45145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=45145"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/45145\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=45145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=45145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=45145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}