{"id":43893,"date":"2020-07-31T09:08:28","date_gmt":"2020-07-31T12:08:28","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=43893"},"modified":"2020-07-31T09:08:28","modified_gmt":"2020-07-31T12:08:28","slug":"governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/","title":{"rendered":"Governo tem d\u00e9ficit recorde e d\u00edvida pode ir a 98% do PIB"},"content":{"rendered":"<p><strong><em>O Estado de S. Paulo <\/em><\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>As contas do governo federal tiveram rombo de R$ 417,2 bilh\u00f5es no 1.\u00ba semestre, pior resultado para o per\u00edodo da s\u00e9rie hist\u00f3rica, iniciada em 1997. No mesmo per\u00edodo de 2019, o d\u00e9ficit fiscal foi de R$ 29,3 bilh\u00f5es. Somente em junho, as contas do governo ficaram negativas em R$ 194,7 bilh\u00f5es. O Minist\u00e9rio da Economia prev\u00ea que a d\u00edvida bruta alcance 98,2% do PIB em 2020.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>As contas do governo federal registraram um rombo de R$ 417,2 bilh\u00f5es no primeiro semestre deste ano, o pior resultado para o per\u00edodo desde o in\u00edcio da s\u00e9rie hist\u00f3rica, em 1997. No mesmo per\u00edodo do ano passado, o d\u00e9ficit fiscal somou R$ 29,3 bilh\u00f5es.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Somente em junho deste ano, as contas do governo apresentaram um rombo de R$ 194,7 bilh\u00f5es, tamb\u00e9m o pior resultado mensal da hist\u00f3ria. No mesmo per\u00edodo do ano passado, o d\u00e9ficit fiscal somou R$ 11,8 bilh\u00f5es.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Esse \u00e9 o volume em que as despesas superaram as receitas, sem incluir os gastos com juros da d\u00edvida p\u00fablica. Segundo o governo, o rombo recorde se deve ao aumento de despesas para combater a pandemia do novo coronav\u00edrus (at\u00e9 agora, R$ 210,6 bilh\u00f5es) e tamb\u00e9m \u00e0 perda de arrecada\u00e7\u00e3o com o tombo no n\u00edvel de atividade e o adiamento no prazo de tributos.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Com o aumento do resultado negativo, o governo tem de se endividar cada vez mais para cobrir seus gastos, o que leva a um aumento da d\u00edvida p\u00fablica. A previs\u00e3o do Minist\u00e9rio da Economia \u00e9 que a d\u00edvida bruta do governo geral alcance 98,2% do PIB neste ano.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>No ano passado, a d\u00edvida bruta terminou em R$ 5,5 trilh\u00f5es \u2013 75,8% do PIB, o que configurou o primeiro recuo em seis anos.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Em 2013, esse porcentual era de 51,5%. O quadro foi agravado a partir do descontrole fiscal no governo Dilma Rousseff.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>O porcentual da d\u00edvida em rela\u00e7\u00e3o ao PIB \u00e9 uma das principais preocupa\u00e7\u00f5es do governo e dos analistas econ\u00f4micos. Isso porque \u00e9 uma refer\u00eancia para avalia\u00e7\u00e3o, por parte das ag\u00eancias globais de classifica\u00e7\u00e3o de risco, da capacidade de solv\u00eancia do Pa\u00eds. Na pr\u00e1tica, quanto maior a d\u00edvida, maior o risco de calote do Brasil.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Para este ano, somente o governo tinha de atingir uma meta de d\u00e9ficit prim\u00e1rio de at\u00e9 R$ 124,1 bilh\u00f5es. Com o decreto de calamidade p\u00fablica, proposto pelo governo e aprovado pelo Congresso por conta da pandemia, n\u00e3o ser\u00e1 mais necess\u00e1rio atingir esse valor.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Tempor\u00e1rio<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>O Tesouro Nacional avaliou que o aumento de gastos neste ano \u00e9 tempor\u00e1rio, \u201ccom execu\u00e7\u00e3o concentrada no exerc\u00edcio de 2020\u201d. \u201cA situa\u00e7\u00e3o enfrentada por todo o mundo requeria uma resposta do poder p\u00fablico, e as a\u00e7\u00f5es implementadas para lidar com o problema (efeitos da pandemia) basearam-se na prote\u00e7\u00e3o aos mais vulner\u00e1veis e na preserva\u00e7\u00e3o de empregos e de empresas. Por\u00e9m, \u00e9 preciso observar que essas medidas t\u00eam um custo para a sociedade e geram uma conta que precisa ser paga no futuro pr\u00f3ximo\u201d, acrescentou o Tesouro.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Para o secret\u00e1rio do Tesouro, Bruno Funchal, mesmo com a estimativa de terminar as contas neste ano com d\u00e9ficit de R$ 800 bilh\u00f5es, a trajet\u00f3ria atual \u00e9 de \u201crecupera\u00e7\u00e3o\u201d. \u201cN\u00e3o esperamos que o cen\u00e1rio siga se deteriorando\u201d, afirmou Funchal. \u201cO cen\u00e1rio tende a melhorar daqui em diante, o que j\u00e1 est\u00e1 se traduzindo na atividade econ\u00f4mica.\u201d<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>O economista-chefe do banco de investimentos Haitong, Flavio Serrano, espera que os pr\u00f3ximos meses tragam melhora marginal nas contas, ainda sob impacto das medidas do governo para minimizar os efeitos da pandemia. \u201cA partir de outubro, n\u00e3o devemos mais ter os desembolsos do aux\u00edlio emergencial e os resultados devem melhorar de maneira significativa.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Tamb\u00e9m a atividade econ\u00f4mica deve melhorar e gerar uma recupera\u00e7\u00e3o das receitas, ainda marginalmente, nos pr\u00f3ximos meses, mas de forma mais marcada a partir de outubro. Mesmo em julho, acho que esse n\u00famero de R$ 190 bilh\u00f5es n\u00e3o deve se repetir.\u201d<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>J\u00e1 o especialista em contas p\u00fablicas Guilherme Tinoco disse que a crise do coronav\u00edrus eliminou qualquer possibilidade de o Pa\u00eds fechar as contas no azul antes de 2023. \u201cO que precisamos agora \u00e9 voltar a crescer, o que n\u00e3o est\u00e1vamos fazendo antes da pandemia, e o governo precisa dar o exemplo e mostrar que est\u00e1 fazendo o ajuste fiscal.\u201d (O Estado de S. Paulo\/Lorenna Rodrigues, Fabr\u00edcio de Castro, Gregory Prudenciano e C\u00edcero Cotrim)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Estado de S. Paulo \u00a0 As contas do governo federal tiveram rombo de R$ 417,2 bilh\u00f5es no 1.\u00ba semestre, pior resultado para o per\u00edodo da s\u00e9rie hist\u00f3rica, iniciada em 1997. No mesmo per\u00edodo de 2019, o d\u00e9ficit fiscal foi de R$ 29,3 bilh\u00f5es. Somente em junho, as contas do governo ficaram negativas em R$\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-43893","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo tem d\u00e9ficit recorde e d\u00edvida pode ir a 98% do PIB - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo tem d\u00e9ficit recorde e d\u00edvida pode ir a 98% do PIB - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"O Estado de S. Paulo \u00a0 As contas do governo federal tiveram rombo de R$ 417,2 bilh\u00f5es no 1.\u00ba semestre, pior resultado para o per\u00edodo da s\u00e9rie hist\u00f3rica, iniciada em 1997. No mesmo per\u00edodo de 2019, o d\u00e9ficit fiscal foi de R$ 29,3 bilh\u00f5es. Somente em junho, as contas do governo ficaram negativas em R$\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-31T12:08:28+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/07\\\/31\\\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/07\\\/31\\\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Governo tem d\u00e9ficit recorde e d\u00edvida pode ir a 98% do PIB\",\"datePublished\":\"2020-07-31T12:08:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/07\\\/31\\\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\\\/\"},\"wordCount\":789,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/07\\\/31\\\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/07\\\/31\\\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\\\/\",\"name\":\"Governo tem d\u00e9ficit recorde e d\u00edvida pode ir a 98% do PIB - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2020-07-31T12:08:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/07\\\/31\\\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/07\\\/31\\\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/07\\\/31\\\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Governo tem d\u00e9ficit recorde e d\u00edvida pode ir a 98% do PIB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo tem d\u00e9ficit recorde e d\u00edvida pode ir a 98% do PIB - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo tem d\u00e9ficit recorde e d\u00edvida pode ir a 98% do PIB - Canal Dana","og_description":"O Estado de S. Paulo \u00a0 As contas do governo federal tiveram rombo de R$ 417,2 bilh\u00f5es no 1.\u00ba semestre, pior resultado para o per\u00edodo da s\u00e9rie hist\u00f3rica, iniciada em 1997. No mesmo per\u00edodo de 2019, o d\u00e9ficit fiscal foi de R$ 29,3 bilh\u00f5es. Somente em junho, as contas do governo ficaram negativas em R$\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/","og_site_name":"Canal Dana","article_published_time":"2020-07-31T12:08:28+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Governo tem d\u00e9ficit recorde e d\u00edvida pode ir a 98% do PIB","datePublished":"2020-07-31T12:08:28+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/"},"wordCount":789,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/","url":"https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/","name":"Governo tem d\u00e9ficit recorde e d\u00edvida pode ir a 98% do PIB - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2020-07-31T12:08:28+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2020\/07\/31\/governo-tem-deficit-recorde-e-divida-pode-ir-a-98-do-pib\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"Governo tem d\u00e9ficit recorde e d\u00edvida pode ir a 98% do PIB"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/43893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=43893"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/43893\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=43893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=43893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=43893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}