{"id":42032,"date":"2020-05-05T09:05:31","date_gmt":"2020-05-05T12:05:31","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=42032"},"modified":"2020-05-05T09:05:31","modified_gmt":"2020-05-05T12:05:31","slug":"renault-volvo-daf-e-bmw-retomam-producao","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/","title":{"rendered":"Renault, Volvo, DAF e BMW retomam produ\u00e7\u00e3o"},"content":{"rendered":"<p><em>O Estado de S. Paulo <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Mais quatro montadoras retomam a produ\u00e7\u00e3o hoje. Renault, Volvo e DAF, todas com f\u00e1bricas no Paran\u00e1, e BMW, com unidade em Santa Catarina voltam a produzir, mas em ritmo inferior ao de antes das f\u00e9rias coletivas adotadas h\u00e1 cerca de um m\u00eas em raz\u00e3o da pandemia do coronav\u00edrus.<\/p>\n<p>&nbsp;<\/p>\n<p>A Renault e a BMW s\u00e3o as primeiras fabricantes de autom\u00f3veis a religar as m\u00e1quinas. No caso da Renault s\u00e3o quatro unidades fabris no mesmo complexo e n\u00e3o houve acordo de redu\u00e7\u00e3o de jornada e sal\u00e1rios com os funcion\u00e1rios. Assim, todos os 7,5 mil empregados voltam ao trabalho, incluindo o pessoal administrativo, que far\u00e1 home office.<\/p>\n<p>&nbsp;<\/p>\n<p>J\u00e1 tinham retomado atividades na \u00faltima segunda-feira, 27, a Scania e a Volkswagen\/MAN. Ambas produzem caminh\u00f5es e \u00f4nibus, assim como a Volvo. A DAF faz apenas caminh\u00f5es. Todas as empresas informam terem adotado normas de seguran\u00e7a para evitar contamina\u00e7\u00e3o pelo coronav\u00edrus e a maioria vai operar com quadro reduzido de pessoal.<\/p>\n<p>&nbsp;<\/p>\n<p>Das quatro que retornam agora, Volvo e BMW fizeram acordos previstos na MP 936, assim como a Volkswagen\/MAN.<\/p>\n<p>&nbsp;<\/p>\n<p>Na semana passada, a reportagem do Estado acompanhou o dia de trabalho dos funcion\u00e1rios da Scania, em S\u00e3o Bernardo do Campo, no ABC paulista, a \u00fanica at\u00e9 ent\u00e3o a retomar as atividades no Estado de S\u00e3o Paulo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Protocolos<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>H\u00e1 novos protocolos a serem seguidos, como uso de m\u00e1scaras, manter dist\u00e2ncia segura um do outro e n\u00e3o se cumprimentarem com apertos de m\u00e3o ou abra\u00e7os. \u201c\u00c9 preciso se adaptar ao \u201cnovo normal\u201d, a uma nova maneira de trabalhar\u201d, afirma Danilo Rocha, vice-presidente de Recursos Humanos da Scania.<\/p>\n<p>&nbsp;<\/p>\n<p>A Scania n\u00e3o adotou medidas de redu\u00e7\u00e3o de jornada e sal\u00e1rios, por isso retomou opera\u00e7\u00f5es com todo o quadro de funcion\u00e1rios da produ\u00e7\u00e3o, mas divididos em dois turnos para diminuir a densidade de pessoas no local. Metade da equipe trabalha das 7h \u00e0s 16h15 e a outra metade das 17h30 \u00e0s 00h20. Antes, havia s\u00f3 o primeiro turno.<\/p>\n<p>&nbsp;<\/p>\n<p>Segundo Rocha, todos os ve\u00edculos que est\u00e3o sendo produzidos j\u00e1 est\u00e3o vendidos, pois a empresa n\u00e3o trabalha com estoques. \u201cCada caminh\u00e3o que est\u00e1 saindo da linha j\u00e1 tem um dono\u201d. Segundo eles, as encomendas foram feitas antes da parada das f\u00e1bricas. Tamb\u00e9m h\u00e1 alguns ve\u00edculos destinados \u00e0 exporta\u00e7\u00e3o. (O Estado de S. Paulo\/Cleide Silva)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Estado de S. Paulo &nbsp; Mais quatro montadoras retomam a produ\u00e7\u00e3o hoje. Renault, Volvo e DAF, todas com f\u00e1bricas no Paran\u00e1, e BMW, com unidade em Santa Catarina voltam a produzir, mas em ritmo inferior ao de antes das f\u00e9rias coletivas adotadas h\u00e1 cerca de um m\u00eas em raz\u00e3o da pandemia do coronav\u00edrus. &nbsp;\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[61],"tags":[],"class_list":["post-42032","post","type-post","status-publish","format-standard","hentry","category-destaques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Renault, Volvo, DAF e BMW retomam produ\u00e7\u00e3o - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renault, Volvo, DAF e BMW retomam produ\u00e7\u00e3o - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"O Estado de S. Paulo &nbsp; Mais quatro montadoras retomam a produ\u00e7\u00e3o hoje. Renault, Volvo e DAF, todas com f\u00e1bricas no Paran\u00e1, e BMW, com unidade em Santa Catarina voltam a produzir, mas em ritmo inferior ao de antes das f\u00e9rias coletivas adotadas h\u00e1 cerca de um m\u00eas em raz\u00e3o da pandemia do coronav\u00edrus. &nbsp;\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-05T12:05:31+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/05\\\/05\\\/renault-volvo-daf-e-bmw-retomam-producao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/05\\\/05\\\/renault-volvo-daf-e-bmw-retomam-producao\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Renault, Volvo, DAF e BMW retomam produ\u00e7\u00e3o\",\"datePublished\":\"2020-05-05T12:05:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/05\\\/05\\\/renault-volvo-daf-e-bmw-retomam-producao\\\/\"},\"wordCount\":434,\"articleSection\":[\"Destaques\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/05\\\/05\\\/renault-volvo-daf-e-bmw-retomam-producao\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/05\\\/05\\\/renault-volvo-daf-e-bmw-retomam-producao\\\/\",\"name\":\"Renault, Volvo, DAF e BMW retomam produ\u00e7\u00e3o - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2020-05-05T12:05:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/05\\\/05\\\/renault-volvo-daf-e-bmw-retomam-producao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/05\\\/05\\\/renault-volvo-daf-e-bmw-retomam-producao\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/05\\\/05\\\/renault-volvo-daf-e-bmw-retomam-producao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destaques\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/destaques\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Renault, Volvo, DAF e BMW retomam produ\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renault, Volvo, DAF e BMW retomam produ\u00e7\u00e3o - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/","og_locale":"pt_BR","og_type":"article","og_title":"Renault, Volvo, DAF e BMW retomam produ\u00e7\u00e3o - Canal Dana","og_description":"O Estado de S. Paulo &nbsp; Mais quatro montadoras retomam a produ\u00e7\u00e3o hoje. Renault, Volvo e DAF, todas com f\u00e1bricas no Paran\u00e1, e BMW, com unidade em Santa Catarina voltam a produzir, mas em ritmo inferior ao de antes das f\u00e9rias coletivas adotadas h\u00e1 cerca de um m\u00eas em raz\u00e3o da pandemia do coronav\u00edrus. &nbsp;\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/","og_site_name":"Canal Dana","article_published_time":"2020-05-05T12:05:31+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Renault, Volvo, DAF e BMW retomam produ\u00e7\u00e3o","datePublished":"2020-05-05T12:05:31+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/"},"wordCount":434,"articleSection":["Destaques"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/","url":"https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/","name":"Renault, Volvo, DAF e BMW retomam produ\u00e7\u00e3o - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2020-05-05T12:05:31+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2020\/05\/05\/renault-volvo-daf-e-bmw-retomam-producao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Destaques","item":"https:\/\/dana.com.br\/canaldana\/destaques\/"},{"@type":"ListItem","position":3,"name":"Renault, Volvo, DAF e BMW retomam produ\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/42032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=42032"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/42032\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=42032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=42032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=42032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}