{"id":41649,"date":"2020-03-26T08:24:38","date_gmt":"2020-03-26T11:24:38","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=41649"},"modified":"2020-03-26T08:24:38","modified_gmt":"2020-03-26T11:24:38","slug":"citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/","title":{"rendered":"Citro\u00ebn, Peugeot e Hyundai adaptam regras nas revis\u00f5es de garantia devido a pandemia"},"content":{"rendered":"<p><em>AutoInd\u00fastria<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>As marcas do Grupo PSA, Peugeot e Citro\u00ebn anunciam altera\u00e7\u00f5es tempor\u00e1rias nos prazos de revis\u00f5es e manuten\u00e7\u00e3o aos ve\u00edculos ainda no per\u00edodo de garantia de f\u00e1brica.<\/p>\n<p>&nbsp;<\/p>\n<p>Devido \u00e0 pandemia provocada pelo coronav\u00edrus e alinhadas \u00e0s orienta\u00e7\u00f5es de combate \u00e0 Covid-19, os clientes ter\u00e3o mais tr\u00eas meses e\/ou 3 mil quil\u00f4metros para realizarem servi\u00e7os obrigat\u00f3rios a contar a parti de 17 de mar\u00e7o de 2020.<\/p>\n<p>&nbsp;<\/p>\n<p>Tamb\u00e9m os propriet\u00e1rios de ve\u00edculos com vencimento pr\u00f3ximo do fim da garantia estar\u00e3o cobertos por mais um m\u00eas ap\u00f3s a data limite, exce\u00e7\u00e3o para os modelos DS, que ganham at\u00e9 seis meses.<\/p>\n<p>&nbsp;<\/p>\n<p>As marcas garantem ainda que no caso de pane com ve\u00edculos dentro da garantia sem possiblidade de reparo no local do cliente, os servi\u00e7os de assist\u00eancia fornecer\u00e3o transporte do consumidor e reboque do ve\u00edculo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Prazos ampliados<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Tamb\u00e9m a Hyundai Motors informa que garantias e revis\u00f5es de ve\u00edculos das HB20 e Creta com vencimento a partir de 10 de mar\u00e7o ser\u00e3o asseguradas at\u00e9 30 de abril de 2020, com possibilidade de prorroga\u00e7\u00e3o a depender de eventuais orienta\u00e7\u00f5es governamentais para o combate \u00e0 Covid-19. A toler\u00e2ncia de quilometragem tamb\u00e9m ser\u00e1 ampliada em 2 mil km. Caso esta margem seja ultrapassada, o ve\u00edculo dever\u00e1 passar por uma inspe\u00e7\u00e3o nas 218 concession\u00e1rias da marca.<\/p>\n<p>&nbsp;<\/p>\n<p>Medidas semelhantes j\u00e1 foram tomadas pela Kia anteriormente, na sexta-feira passada, 20 de mar\u00e7o. A representante da marca no Brasil dobrou a toler\u00e2ncia de quilometragem para as revis\u00f5es peri\u00f3dicas para carros de passeios, de 1,5 mil km para 3 mil km, e triplicou nos utilit\u00e1rios, de 500 km para 1,5 mil km. (AutoInd\u00fastria)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AutoInd\u00fastria &nbsp; As marcas do Grupo PSA, Peugeot e Citro\u00ebn anunciam altera\u00e7\u00f5es tempor\u00e1rias nos prazos de revis\u00f5es e manuten\u00e7\u00e3o aos ve\u00edculos ainda no per\u00edodo de garantia de f\u00e1brica. &nbsp; Devido \u00e0 pandemia provocada pelo coronav\u00edrus e alinhadas \u00e0s orienta\u00e7\u00f5es de combate \u00e0 Covid-19, os clientes ter\u00e3o mais tr\u00eas meses e\/ou 3 mil quil\u00f4metros para realizarem\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[61],"tags":[],"class_list":["post-41649","post","type-post","status-publish","format-standard","hentry","category-destaques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Citro\u00ebn, Peugeot e Hyundai adaptam regras nas revis\u00f5es de garantia devido a pandemia - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citro\u00ebn, Peugeot e Hyundai adaptam regras nas revis\u00f5es de garantia devido a pandemia - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"AutoInd\u00fastria &nbsp; As marcas do Grupo PSA, Peugeot e Citro\u00ebn anunciam altera\u00e7\u00f5es tempor\u00e1rias nos prazos de revis\u00f5es e manuten\u00e7\u00e3o aos ve\u00edculos ainda no per\u00edodo de garantia de f\u00e1brica. &nbsp; Devido \u00e0 pandemia provocada pelo coronav\u00edrus e alinhadas \u00e0s orienta\u00e7\u00f5es de combate \u00e0 Covid-19, os clientes ter\u00e3o mais tr\u00eas meses e\/ou 3 mil quil\u00f4metros para realizarem\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-26T11:24:38+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/03\\\/26\\\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/03\\\/26\\\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Citro\u00ebn, Peugeot e Hyundai adaptam regras nas revis\u00f5es de garantia devido a pandemia\",\"datePublished\":\"2020-03-26T11:24:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/03\\\/26\\\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\\\/\"},\"wordCount\":315,\"articleSection\":[\"Destaques\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/03\\\/26\\\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/03\\\/26\\\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\\\/\",\"name\":\"Citro\u00ebn, Peugeot e Hyundai adaptam regras nas revis\u00f5es de garantia devido a pandemia - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2020-03-26T11:24:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/03\\\/26\\\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/03\\\/26\\\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2020\\\/03\\\/26\\\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destaques\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/destaques\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Citro\u00ebn, Peugeot e Hyundai adaptam regras nas revis\u00f5es de garantia devido a pandemia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citro\u00ebn, Peugeot e Hyundai adaptam regras nas revis\u00f5es de garantia devido a pandemia - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/","og_locale":"pt_BR","og_type":"article","og_title":"Citro\u00ebn, Peugeot e Hyundai adaptam regras nas revis\u00f5es de garantia devido a pandemia - Canal Dana","og_description":"AutoInd\u00fastria &nbsp; As marcas do Grupo PSA, Peugeot e Citro\u00ebn anunciam altera\u00e7\u00f5es tempor\u00e1rias nos prazos de revis\u00f5es e manuten\u00e7\u00e3o aos ve\u00edculos ainda no per\u00edodo de garantia de f\u00e1brica. &nbsp; Devido \u00e0 pandemia provocada pelo coronav\u00edrus e alinhadas \u00e0s orienta\u00e7\u00f5es de combate \u00e0 Covid-19, os clientes ter\u00e3o mais tr\u00eas meses e\/ou 3 mil quil\u00f4metros para realizarem\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/","og_site_name":"Canal Dana","article_published_time":"2020-03-26T11:24:38+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Citro\u00ebn, Peugeot e Hyundai adaptam regras nas revis\u00f5es de garantia devido a pandemia","datePublished":"2020-03-26T11:24:38+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/"},"wordCount":315,"articleSection":["Destaques"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/","url":"https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/","name":"Citro\u00ebn, Peugeot e Hyundai adaptam regras nas revis\u00f5es de garantia devido a pandemia - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2020-03-26T11:24:38+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2020\/03\/26\/citroen-peugeot-e-hyundai-adaptam-regras-nas-revisoes-de-garantia-devido-a-pandemia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Destaques","item":"https:\/\/dana.com.br\/canaldana\/destaques\/"},{"@type":"ListItem","position":3,"name":"Citro\u00ebn, Peugeot e Hyundai adaptam regras nas revis\u00f5es de garantia devido a pandemia"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/41649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=41649"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/41649\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=41649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=41649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=41649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}