{"id":30787,"date":"2018-11-23T08:28:16","date_gmt":"2018-11-23T10:28:16","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=30787"},"modified":"2018-11-23T08:28:16","modified_gmt":"2018-11-23T10:28:16","slug":"truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/","title":{"rendered":"TruckPad, uma das principais startups de transporte do Pa\u00eds, anuncia vagas em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o"},"content":{"rendered":"<p><em>Segs\u00a0 <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>O TruckPad, uma das principais startups do segmento de transportes do Pa\u00eds, que conecta o caminhoneiro aut\u00f4nomo \u00e0 carga por meio de um aplicativo, mant\u00e9m o ritmo acelerado de expans\u00e3o e anuncia uma s\u00e9rie de vagas em \u00e1reas estrat\u00e9gicas da companhia, instalada em S\u00e3o Paulo (SP).<\/p>\n<p>&nbsp;<\/p>\n<p>Entre elas, est\u00e3o oportunidades para analistas, coordenadores e desenvolvedores para os departamentos de log\u00edstica, recursos humanos, marketing e tecnologia da informa\u00e7\u00e3o. Para se candidatar, os interessados devem acessar o link: <a href=\"http:\/\/grupolbs.recruiterbox.com\/?team=TruckPad#content\" target=\"_blank\" rel=\"noopener\">http:\/\/grupolbs.recruiterbox.com\/?team=TruckPad#content<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre os benef\u00edcios oferecidos pelo TruckPad vale refei\u00e7\u00e3o, vale transporte, plano de sa\u00fade e odontol\u00f3gico, seguro de vida, aux\u00edlio idioma e aux\u00edlio creche. Tamb\u00e9m h\u00e1 frutas da esta\u00e7\u00e3o, caf\u00e9 da manh\u00e3, massagem relaxante e cerveja ao final do expediente, nas disponibilidades da empresa.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sobre o TruckPad<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Lan\u00e7ado em 2013 pelo empres\u00e1rio Carlos Mira, o TruckPad \u00e9 um marketplace que conecta o caminhoneiro \u00e0 carga. \u00c9 a primeira startup brasileira de tecnologia e log\u00edstica voltada ao transporte rodovi\u00e1rio de cargas e \u00e9 destinada tanto a caminhoneiros quanto a empresas que objetivam melhorar a sua performance operacional. O TruckPad foi idealizado para ser o amigo eletr\u00f4nico do motorista de caminh\u00e3o, por criar solu\u00e7\u00f5es para sua rotina di\u00e1ria, e fornecer informa\u00e7\u00f5es importantes para o seu dia-a-dia, como pre\u00e7o de ped\u00e1gio, custos de viagem, promo\u00e7\u00f5es exclusivas de fornecedores na rota e venda de produtos online atrav\u00e9s do aplicativo. O TruckPad oferece in\u00fameras vantagens para os usu\u00e1rios, como aumento de faturamento e tamb\u00e9m economia de tempo e \u00f3leo diesel. Na pr\u00e1tica, os caminhoneiros faturam cerca de 50% a mais com o caminh\u00e3o ao usar o aplicativo, enquanto as empresas usu\u00e1rias podem reduzir em at\u00e9 30% seus custos com o transporte rodovi\u00e1rio de cargas. (Segs\/Rodrigo Samy)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segs\u00a0 &nbsp; O TruckPad, uma das principais startups do segmento de transportes do Pa\u00eds, que conecta o caminhoneiro aut\u00f4nomo \u00e0 carga por meio de um aplicativo, mant\u00e9m o ritmo acelerado de expans\u00e3o e anuncia uma s\u00e9rie de vagas em \u00e1reas estrat\u00e9gicas da companhia, instalada em S\u00e3o Paulo (SP). &nbsp; Entre elas, est\u00e3o oportunidades para analistas,\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[58],"tags":[],"class_list":["post-30787","post","type-post","status-publish","format-standard","hentry","category-oportunidade"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TruckPad, uma das principais startups de transporte do Pa\u00eds, anuncia vagas em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TruckPad, uma das principais startups de transporte do Pa\u00eds, anuncia vagas em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Segs\u00a0 &nbsp; O TruckPad, uma das principais startups do segmento de transportes do Pa\u00eds, que conecta o caminhoneiro aut\u00f4nomo \u00e0 carga por meio de um aplicativo, mant\u00e9m o ritmo acelerado de expans\u00e3o e anuncia uma s\u00e9rie de vagas em \u00e1reas estrat\u00e9gicas da companhia, instalada em S\u00e3o Paulo (SP). &nbsp; Entre elas, est\u00e3o oportunidades para analistas,\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-23T10:28:16+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/11\\\/23\\\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/11\\\/23\\\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"TruckPad, uma das principais startups de transporte do Pa\u00eds, anuncia vagas em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o\",\"datePublished\":\"2018-11-23T10:28:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/11\\\/23\\\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\\\/\"},\"wordCount\":339,\"articleSection\":[\"Oportunidade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/11\\\/23\\\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/11\\\/23\\\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\\\/\",\"name\":\"TruckPad, uma das principais startups de transporte do Pa\u00eds, anuncia vagas em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2018-11-23T10:28:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/11\\\/23\\\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/11\\\/23\\\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/11\\\/23\\\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oportunidade\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/oportunidade\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TruckPad, uma das principais startups de transporte do Pa\u00eds, anuncia vagas em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TruckPad, uma das principais startups de transporte do Pa\u00eds, anuncia vagas em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/","og_locale":"pt_BR","og_type":"article","og_title":"TruckPad, uma das principais startups de transporte do Pa\u00eds, anuncia vagas em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o - Canal Dana","og_description":"Segs\u00a0 &nbsp; O TruckPad, uma das principais startups do segmento de transportes do Pa\u00eds, que conecta o caminhoneiro aut\u00f4nomo \u00e0 carga por meio de um aplicativo, mant\u00e9m o ritmo acelerado de expans\u00e3o e anuncia uma s\u00e9rie de vagas em \u00e1reas estrat\u00e9gicas da companhia, instalada em S\u00e3o Paulo (SP). &nbsp; Entre elas, est\u00e3o oportunidades para analistas,\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/","og_site_name":"Canal Dana","article_published_time":"2018-11-23T10:28:16+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"TruckPad, uma das principais startups de transporte do Pa\u00eds, anuncia vagas em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o","datePublished":"2018-11-23T10:28:16+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/"},"wordCount":339,"articleSection":["Oportunidade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/","url":"https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/","name":"TruckPad, uma das principais startups de transporte do Pa\u00eds, anuncia vagas em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2018-11-23T10:28:16+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2018\/11\/23\/truckpad-uma-das-principais-startups-de-transporte-do-pais-anuncia-vagas-em-varias-areas-de-atuacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Oportunidade","item":"https:\/\/dana.com.br\/canaldana\/oportunidade\/"},{"@type":"ListItem","position":3,"name":"TruckPad, uma das principais startups de transporte do Pa\u00eds, anuncia vagas em v\u00e1rias \u00e1reas de atua\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/30787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=30787"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/30787\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=30787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=30787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=30787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}