{"id":29523,"date":"2018-09-26T08:43:17","date_gmt":"2018-09-26T11:43:17","guid":{"rendered":"https:\/\/dana.com.br\/canaldana\/?p=29523"},"modified":"2018-09-26T08:43:17","modified_gmt":"2018-09-26T11:43:17","slug":"scania-em-alinhamento-sustentavel","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/","title":{"rendered":"Scania em alinhamento sustent\u00e1vel"},"content":{"rendered":"<p><em>AutoInd\u00fastria <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Na corrida por um transporte sem emiss\u00e3o de poluentes que ao mesmo tempo entregue efici\u00eancia operacional, tanto do ponto de vista da produtividade quanto dos custos, alinham todas as fabricantes de caminh\u00f5es. Os representantes das montadoras n\u00e3o deixam d\u00favidas de que o ve\u00edculo 100% el\u00e9trico se apresenta como grande parte da solu\u00e7\u00e3o. Sua viabilidade comercial para os dias atuais, no entanto, ainda esbarra na car\u00eancia de infraestrutura e no alto custo das baterias.<\/p>\n<p>&nbsp;<\/p>\n<p>No Sal\u00e3o Internacional de Ve\u00edculos Comerciais de Hanover, Alemanha, aberta at\u00e9 27 de setembro, a Scania deixa claro que o percurso na evolu\u00e7\u00e3o tecnol\u00f3gico segue por etapas. Antes da eletrifica\u00e7\u00e3o total, cabe oferecer efici\u00eancia a partir de propuls\u00f5es alternativas, especialmente baseada em biocombust\u00edveis.<\/p>\n<p>&nbsp;<\/p>\n<p>Baseada em sua nova gera\u00e7\u00e3o de caminh\u00f5es, a marca levou para seu estande novas op\u00e7\u00f5es h\u00edbridas ao transportador, tanto em vers\u00e3o plug-in (PHEV) quanto el\u00e9trico h\u00edbrido (HEV), ambos com possibilidade de funcionar com chamado HVO, \u00f3leo vegetal tratado com hidrocarbonetos ou diesel.<\/p>\n<p>&nbsp;<\/p>\n<p>Os modelos, prontos para chegar ao mercado, incorporam ainda o que a marca chamou de Scania Zone, um pacote de servi\u00e7o que permite programar o ve\u00edculo de acordo com regras de determinadas zonas geogr\u00e1ficas, como velocidade, ru\u00eddo ou mesmo emiss\u00f5es. Assim, ao entrar em uma regi\u00e3o pr\u00e9-definida, o caminh\u00e3o passa a circular conforme as regras estabelecidas, por exemplo, a 20 km\/h, em modo 100% el\u00e9trico.<\/p>\n<p>&nbsp;<\/p>\n<p>Junto \u00e0s novidades h\u00edbridas, a Scania refor\u00e7a suas propostas em motores movidos a combust\u00edveis alternativos, como o B100 (100% biodiesel), o g\u00e1s \u2013 gasoso ou liquefeito -, al\u00e9m do etanol. Op\u00e7\u00f5es para a mais diversas aplica\u00e7\u00f5es est\u00e3o presentes na \u00e1rea da empresa e, neste universo, a opera\u00e7\u00e3o brasileira passa a andar a par e passo com a Europa.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cO Brasil tem excesso de combust\u00edveis alternativos\u201d, diz Celso Mendon\u00e7a, gerente de desenvolvimento de neg\u00f3cios da fabricante. \u201cA tecnologia el\u00e9trica \u00e9 o futuro, mas ainda as baterias s\u00e3o pesadas e o custo muito alto.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>No pr\u00f3ximo dia 27 de dezembro, sair\u00e3o da linha de montagem da f\u00e1brica de Scania em S\u00e3o Bernardo do Campo (SP), as \u00faltimas unidades da s\u00e9rie PGR no mundo. No lugar, entra em produ\u00e7\u00e3o a nova gera\u00e7\u00e3o de caminh\u00f5es Scania e, com eles, ofertas in\u00e9ditas de motores movidos a combust\u00edveis alternativos para o transportador brasileiro, como o bioetanol e o biometano.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201c\u00c9 tamb\u00e9m oportunidade de desenvolver solu\u00e7\u00f5es locais\u201d, afirma Christopher Podgorsky, presidente da Scania Am\u00e9rica Latina. \u201cCom o motor de 13 litros h\u00e1 nichos de uso com etanol ou g\u00e1s. No setor sucroalcooleiro, por exemplo, o processo fabril tem matriz energ\u00e9tica f\u00f3ssil, mas pode o baga\u00e7o da cana \u00e9 mat\u00e9ria-prima para a biomassa e, dela, a possibilidade de produzir biog\u00e1s\u201d. (AutoInd\u00fastria\/D\u00e9cio Costa)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AutoInd\u00fastria &nbsp; Na corrida por um transporte sem emiss\u00e3o de poluentes que ao mesmo tempo entregue efici\u00eancia operacional, tanto do ponto de vista da produtividade quanto dos custos, alinham todas as fabricantes de caminh\u00f5es. Os representantes das montadoras n\u00e3o deixam d\u00favidas de que o ve\u00edculo 100% el\u00e9trico se apresenta como grande parte da solu\u00e7\u00e3o. Sua\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[97],"tags":[],"class_list":["post-29523","post","type-post","status-publish","format-standard","hentry","category-salao-de-hannover"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scania em alinhamento sustent\u00e1vel - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scania em alinhamento sustent\u00e1vel - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"AutoInd\u00fastria &nbsp; Na corrida por um transporte sem emiss\u00e3o de poluentes que ao mesmo tempo entregue efici\u00eancia operacional, tanto do ponto de vista da produtividade quanto dos custos, alinham todas as fabricantes de caminh\u00f5es. Os representantes das montadoras n\u00e3o deixam d\u00favidas de que o ve\u00edculo 100% el\u00e9trico se apresenta como grande parte da solu\u00e7\u00e3o. Sua\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-26T11:43:17+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/09\\\/26\\\/scania-em-alinhamento-sustentavel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/09\\\/26\\\/scania-em-alinhamento-sustentavel\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Scania em alinhamento sustent\u00e1vel\",\"datePublished\":\"2018-09-26T11:43:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/09\\\/26\\\/scania-em-alinhamento-sustentavel\\\/\"},\"wordCount\":511,\"articleSection\":[\"Sal\u00e3o de Hannover\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/09\\\/26\\\/scania-em-alinhamento-sustentavel\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/09\\\/26\\\/scania-em-alinhamento-sustentavel\\\/\",\"name\":\"Scania em alinhamento sustent\u00e1vel - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2018-09-26T11:43:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/09\\\/26\\\/scania-em-alinhamento-sustentavel\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/09\\\/26\\\/scania-em-alinhamento-sustentavel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2018\\\/09\\\/26\\\/scania-em-alinhamento-sustentavel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sal\u00e3o de Hannover\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/salao-de-hannover\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Scania em alinhamento sustent\u00e1vel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scania em alinhamento sustent\u00e1vel - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/","og_locale":"pt_BR","og_type":"article","og_title":"Scania em alinhamento sustent\u00e1vel - Canal Dana","og_description":"AutoInd\u00fastria &nbsp; Na corrida por um transporte sem emiss\u00e3o de poluentes que ao mesmo tempo entregue efici\u00eancia operacional, tanto do ponto de vista da produtividade quanto dos custos, alinham todas as fabricantes de caminh\u00f5es. Os representantes das montadoras n\u00e3o deixam d\u00favidas de que o ve\u00edculo 100% el\u00e9trico se apresenta como grande parte da solu\u00e7\u00e3o. Sua\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/","og_site_name":"Canal Dana","article_published_time":"2018-09-26T11:43:17+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Scania em alinhamento sustent\u00e1vel","datePublished":"2018-09-26T11:43:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/"},"wordCount":511,"articleSection":["Sal\u00e3o de Hannover"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/","url":"https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/","name":"Scania em alinhamento sustent\u00e1vel - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2018-09-26T11:43:17+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2018\/09\/26\/scania-em-alinhamento-sustentavel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Sal\u00e3o de Hannover","item":"https:\/\/dana.com.br\/canaldana\/salao-de-hannover\/"},{"@type":"ListItem","position":3,"name":"Scania em alinhamento sustent\u00e1vel"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/29523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=29523"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/29523\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=29523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=29523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=29523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}