{"id":11704,"date":"2016-09-21T08:19:25","date_gmt":"2016-09-21T11:19:25","guid":{"rendered":"http:\/\/dana.com.br\/canaldana\/?p=11704"},"modified":"2016-09-21T08:19:25","modified_gmt":"2016-09-21T11:19:25","slug":"bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/","title":{"rendered":"BMW confirma a chegada do novo S\u00e9rie 3 GT no Brasil em 2017"},"content":{"rendered":"<p><em>Carsale<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>A BMW j\u00e1 revelou que o novo S\u00e9rie 3 Gran Turismo ser\u00e1 um dos lan\u00e7amentos que a marca ir\u00e1 apresentar em outubro no Sal\u00e3o de Paris (Fran\u00e7a), que acontecer\u00e1 em outubro. A novidade tamb\u00e9m est\u00e1 confirmada para chegar ao Brasil no pr\u00f3ximo ano.<\/p>\n<p>&nbsp;<\/p>\n<p>Descrito pela BMW como um modelo que combina a eleg\u00e2ncia de um cup\u00ea, o espa\u00e7o de um sed\u00e3 e\u00a0 ampla capacidade do porta-malas, o S\u00e9rie 3 Gran Turismo traz uma gama de motores com tr\u00eas op\u00e7\u00f5es a gasolina e outras cinco a diesel.<\/p>\n<p>&nbsp;<\/p>\n<p>As op\u00e7\u00f5es a gasolina contam com vers\u00f5es com pot\u00eancia que varia de 184 cavalos at\u00e9 326 cv, sendo que h\u00e1 tamb\u00e9m cinco op\u00e7\u00f5es a diesel, entre 150 cv e 313 cv. O sistema de tra\u00e7\u00e3o pode ser traseira ou integral xDrive, associada a uma caixa de c\u00e2mbio manual, ou autom\u00e1tica Setptronic.<\/p>\n<p>&nbsp;<\/p>\n<p>Todos os motores a gasolina, de quatro e seis cilindros, assim como os blocos a diesel, de quatro cilindros, t\u00eam como origem a fam\u00edlia de motores de desenho recente e estrutura modular BMW EfficientDynamics, e est\u00e3o equipados com a mais moderna tecnologia BMW TwinPower Turbo. Ao todo, s\u00e3o 18 combina\u00e7\u00f5es diferentes de combina\u00e7\u00f5es de motor, transmiss\u00e3o e tra\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>O S\u00e9rie 3 Gran Turismo estreia nas vers\u00f5es Advantage, Sport Line, Luxury Line e M Sport, sendo que este \u00faltimo est\u00e1 dispon\u00edvel na exclusiva cor azul Estoril. O modelo conta com uma variada gama de equipamentos de s\u00e9rie que inclui, entre outros itens, ar condicionado, acionamento do motor sem chave, dire\u00e7\u00e3o Servotronic, seis airbags, far\u00f3is com luzes de LED, painel colorido de alta resolu\u00e7\u00e3o com seletor iDrive Controller, volante multifuncional revestido de couro e sistema de \u00e1udio com Bluetooth.<\/p>\n<p>&nbsp;<\/p>\n<p>Com um comprimento de 4.824 mil\u00edmetros, o BMW S\u00e9rie 3 Gran Turismo supera os demais integrantes da fam\u00edlia S\u00e9rie 3 em cerca de 200 mm. (Carsale)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carsale &nbsp; A BMW j\u00e1 revelou que o novo S\u00e9rie 3 Gran Turismo ser\u00e1 um dos lan\u00e7amentos que a marca ir\u00e1 apresentar em outubro no Sal\u00e3o de Paris (Fran\u00e7a), que acontecer\u00e1 em outubro. A novidade tamb\u00e9m est\u00e1 confirmada para chegar ao Brasil no pr\u00f3ximo ano. &nbsp; Descrito pela BMW como um modelo que combina a\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79],"tags":[],"class_list":["post-11704","post","type-post","status-publish","format-standard","hentry","category-mercado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BMW confirma a chegada do novo S\u00e9rie 3 GT no Brasil em 2017 - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BMW confirma a chegada do novo S\u00e9rie 3 GT no Brasil em 2017 - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Carsale &nbsp; A BMW j\u00e1 revelou que o novo S\u00e9rie 3 Gran Turismo ser\u00e1 um dos lan\u00e7amentos que a marca ir\u00e1 apresentar em outubro no Sal\u00e3o de Paris (Fran\u00e7a), que acontecer\u00e1 em outubro. A novidade tamb\u00e9m est\u00e1 confirmada para chegar ao Brasil no pr\u00f3ximo ano. &nbsp; Descrito pela BMW como um modelo que combina a\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-21T11:19:25+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/09\\\/21\\\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/09\\\/21\\\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"BMW confirma a chegada do novo S\u00e9rie 3 GT no Brasil em 2017\",\"datePublished\":\"2016-09-21T11:19:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/09\\\/21\\\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\\\/\"},\"wordCount\":345,\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/09\\\/21\\\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/09\\\/21\\\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\\\/\",\"name\":\"BMW confirma a chegada do novo S\u00e9rie 3 GT no Brasil em 2017 - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2016-09-21T11:19:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/09\\\/21\\\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/09\\\/21\\\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/09\\\/21\\\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/mercado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BMW confirma a chegada do novo S\u00e9rie 3 GT no Brasil em 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BMW confirma a chegada do novo S\u00e9rie 3 GT no Brasil em 2017 - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/","og_locale":"pt_BR","og_type":"article","og_title":"BMW confirma a chegada do novo S\u00e9rie 3 GT no Brasil em 2017 - Canal Dana","og_description":"Carsale &nbsp; A BMW j\u00e1 revelou que o novo S\u00e9rie 3 Gran Turismo ser\u00e1 um dos lan\u00e7amentos que a marca ir\u00e1 apresentar em outubro no Sal\u00e3o de Paris (Fran\u00e7a), que acontecer\u00e1 em outubro. A novidade tamb\u00e9m est\u00e1 confirmada para chegar ao Brasil no pr\u00f3ximo ano. &nbsp; Descrito pela BMW como um modelo que combina a\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/","og_site_name":"Canal Dana","article_published_time":"2016-09-21T11:19:25+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"BMW confirma a chegada do novo S\u00e9rie 3 GT no Brasil em 2017","datePublished":"2016-09-21T11:19:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/"},"wordCount":345,"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/","url":"https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/","name":"BMW confirma a chegada do novo S\u00e9rie 3 GT no Brasil em 2017 - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2016-09-21T11:19:25+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2016\/09\/21\/bmw-confirma-a-chegada-do-novo-serie-3-gt-no-brasil-em-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/dana.com.br\/canaldana\/mercado\/"},{"@type":"ListItem","position":3,"name":"BMW confirma a chegada do novo S\u00e9rie 3 GT no Brasil em 2017"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/11704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=11704"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/11704\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=11704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=11704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=11704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}