{"id":10817,"date":"2016-08-17T08:54:25","date_gmt":"2016-08-17T11:54:25","guid":{"rendered":"http:\/\/dana.com.br\/canaldana\/?p=10817"},"modified":"2016-08-17T08:54:25","modified_gmt":"2016-08-17T11:54:25","slug":"governo-discute-com-industria-programa-para-renovar-frota-de-veiculos","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/","title":{"rendered":"Governo discute com ind\u00fastria programa para renovar frota de ve\u00edculos"},"content":{"rendered":"<p><em>O Estado de S. Paulo<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>O governo federal voltou a discutir com entidades do setor automotivo a possibilidade de tirar do papel um programa de renova\u00e7\u00e3o de frota, informaram nesta ter\u00e7a-feira, 16, o ministro do Desenvolvimento, Ind\u00fastria e Com\u00e9rcio (MDIC), Marcos Pereira, e o presidente da Associa\u00e7\u00e3o Nacional dos Fabricantes de Ve\u00edculos Automotores (Anfavea), Antonio Megale, em evento da Federa\u00e7\u00e3o Nacional de Distribui\u00e7\u00e3o de Ve\u00edculos Automotores (Fenabrave).<\/p>\n<p>&nbsp;<\/p>\n<p>Em discurso para os participantes do evento, o ministro disse que est\u00e1 empenhado com o projeto e que pretende envolver os bancos p\u00fablicos para facilitar o financiamento. &#8220;J\u00e1 conversei com o presidente do Banco do Brasil e com o presidente da Caixa&#8221;, contou. Afirmou tamb\u00e9m que quer ver o projeto do programa de renova\u00e7\u00e3o de frota finalizado at\u00e9 o fim deste ano, para que entre em vigor j\u00e1 no ano que vem.<\/p>\n<p>&nbsp;<\/p>\n<p>As conversas entre o setor e governo come\u00e7aram no governo de Dilma Rousseff e foram interrompidas quando teve in\u00edcio o processo de impeachment da petista. A iniciativa, batizada de Programa de Sustentabilidade Veicular, tem o objetivo tirar de circula\u00e7\u00e3o ve\u00edculos muito antigos e substitui-los por ve\u00edculos novos e mais eficientes do ponto de vista energ\u00e9tico.<\/p>\n<p>&nbsp;<\/p>\n<p>As negocia\u00e7\u00f5es foram retomadas na semana passada, quando Megale se encontrou com Pereira em Bras\u00edlia para apresentar a vers\u00e3o preliminar do projeto. Segundo o presidente da Anfavea, ainda n\u00e3o h\u00e1 uma defini\u00e7\u00e3o de que como programa vai funcionar e nem qual \u00e9 a previs\u00e3o de qual ser\u00e1 o impacto no mercado interno de ve\u00edculos.<\/p>\n<p>&nbsp;<\/p>\n<p>O ministro disse que recebeu pessoalmente do presidente em exerc\u00edcio Michel Temer a miss\u00e3o de tocar as conversas com o setor. Ao todo, 19 entidades do setor participam das negocia\u00e7\u00f5es, entre elas a Anfavea, a Fenabrave e o Sindipe\u00e7as.<\/p>\n<p>&nbsp;<\/p>\n<p>Em linhas gerais, a ideia do programa \u00e9 que os propriet\u00e1rios de ve\u00edculos antigos ganhem um cr\u00e9dito ao trocar o antigo por um novo. O antigo seria mandado para sucata e a troca seria volunt\u00e1ria e n\u00e3o obrigat\u00f3ria.<\/p>\n<p>&nbsp;<\/p>\n<p>Em janeiro, quando Dilma ainda estava no comando do governo, o presidente da Fenabrave, Alarico Assump\u00e7\u00e3o Jr, disse que as conversas estavam avan\u00e7adas e que o programa envolveria caminh\u00f5es com mais de 30 anos de uso e carros com mais de 15 anos de uso. \u00c0 \u00e9poca, afirmou que o programa resultaria em um aumento anual de 500 mil unidades no mercado interno. (O Estado de S. Paulo\/Andr\u00e9 \u00cdtalo Rocha)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Estado de S. Paulo &nbsp; O governo federal voltou a discutir com entidades do setor automotivo a possibilidade de tirar do papel um programa de renova\u00e7\u00e3o de frota, informaram nesta ter\u00e7a-feira, 16, o ministro do Desenvolvimento, Ind\u00fastria e Com\u00e9rcio (MDIC), Marcos Pereira, e o presidente da Associa\u00e7\u00e3o Nacional dos Fabricantes de Ve\u00edculos Automotores (Anfavea),\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[61],"tags":[],"class_list":["post-10817","post","type-post","status-publish","format-standard","hentry","category-destaques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo discute com ind\u00fastria programa para renovar frota de ve\u00edculos - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo discute com ind\u00fastria programa para renovar frota de ve\u00edculos - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"O Estado de S. Paulo &nbsp; O governo federal voltou a discutir com entidades do setor automotivo a possibilidade de tirar do papel um programa de renova\u00e7\u00e3o de frota, informaram nesta ter\u00e7a-feira, 16, o ministro do Desenvolvimento, Ind\u00fastria e Com\u00e9rcio (MDIC), Marcos Pereira, e o presidente da Associa\u00e7\u00e3o Nacional dos Fabricantes de Ve\u00edculos Automotores (Anfavea),\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-17T11:54:25+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/17\\\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/17\\\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Governo discute com ind\u00fastria programa para renovar frota de ve\u00edculos\",\"datePublished\":\"2016-08-17T11:54:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/17\\\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\\\/\"},\"wordCount\":445,\"articleSection\":[\"Destaques\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/17\\\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/17\\\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\\\/\",\"name\":\"Governo discute com ind\u00fastria programa para renovar frota de ve\u00edculos - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2016-08-17T11:54:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/17\\\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/17\\\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/17\\\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destaques\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/destaques\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Governo discute com ind\u00fastria programa para renovar frota de ve\u00edculos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo discute com ind\u00fastria programa para renovar frota de ve\u00edculos - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo discute com ind\u00fastria programa para renovar frota de ve\u00edculos - Canal Dana","og_description":"O Estado de S. Paulo &nbsp; O governo federal voltou a discutir com entidades do setor automotivo a possibilidade de tirar do papel um programa de renova\u00e7\u00e3o de frota, informaram nesta ter\u00e7a-feira, 16, o ministro do Desenvolvimento, Ind\u00fastria e Com\u00e9rcio (MDIC), Marcos Pereira, e o presidente da Associa\u00e7\u00e3o Nacional dos Fabricantes de Ve\u00edculos Automotores (Anfavea),\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/","og_site_name":"Canal Dana","article_published_time":"2016-08-17T11:54:25+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Governo discute com ind\u00fastria programa para renovar frota de ve\u00edculos","datePublished":"2016-08-17T11:54:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/"},"wordCount":445,"articleSection":["Destaques"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/","url":"https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/","name":"Governo discute com ind\u00fastria programa para renovar frota de ve\u00edculos - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2016-08-17T11:54:25+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2016\/08\/17\/governo-discute-com-industria-programa-para-renovar-frota-de-veiculos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Destaques","item":"https:\/\/dana.com.br\/canaldana\/destaques\/"},{"@type":"ListItem","position":3,"name":"Governo discute com ind\u00fastria programa para renovar frota de ve\u00edculos"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/10817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=10817"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/10817\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=10817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=10817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=10817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}