{"id":10363,"date":"2016-08-01T09:39:31","date_gmt":"2016-08-01T12:39:31","guid":{"rendered":"http:\/\/dana.com.br\/canaldana\/?p=10363"},"modified":"2016-08-01T09:39:31","modified_gmt":"2016-08-01T12:39:31","slug":"relogio-calendario-perpetuo","status":"publish","type":"post","link":"https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/","title":{"rendered":"Rel\u00f3gio calend\u00e1rio perp\u00e9tuo"},"content":{"rendered":"<p>Desenho \u00fanico resultado de 40 anos de experi\u00eancia do Dr. Ludwig Oeschlin, marca dia, m\u00eas data de cada m\u00eas, incluindo fevereiro, e ano. No per\u00edmetro do mostrador, h\u00e1 30 + 1 orif\u00edcios, com a cada 10 minutos como pontos de refer\u00eancia. Quando o marcado indica 30 minutos, tamb\u00e9m mostra o d\u00e9cimo quinto dia do m\u00eas. (30\/2-15). Os marcadores de 5 dias d\u00e3o a leitura r\u00e1pido da data.<\/p>\n<p>&nbsp;<\/p>\n<p>Clique <a href=\"http:\/\/www.techtalk.com.br\/materia.php?id=2775\" target=\"_blank\">aqui<\/a>, leia mais e acesse a mat\u00e9ria.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desenho \u00fanico resultado de 40 anos de experi\u00eancia do Dr. Ludwig Oeschlin, marca dia, m\u00eas data de cada m\u00eas, incluindo fevereiro, e ano. No per\u00edmetro do mostrador, h\u00e1 30 + 1 orif\u00edcios, com a cada 10 minutos como pontos de refer\u00eancia. Quando o marcado indica 30 minutos, tamb\u00e9m mostra o d\u00e9cimo quinto dia do m\u00eas.\u2026 <a class=\"readmore\" href=\"https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/\">Leia mais \u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[88],"tags":[],"class_list":["post-10363","post","type-post","status-publish","format-standard","hentry","category-tech-talk"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rel\u00f3gio calend\u00e1rio perp\u00e9tuo - Canal Dana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rel\u00f3gio calend\u00e1rio perp\u00e9tuo - Canal Dana\" \/>\n<meta property=\"og:description\" content=\"Desenho \u00fanico resultado de 40 anos de experi\u00eancia do Dr. Ludwig Oeschlin, marca dia, m\u00eas data de cada m\u00eas, incluindo fevereiro, e ano. No per\u00edmetro do mostrador, h\u00e1 30 + 1 orif\u00edcios, com a cada 10 minutos como pontos de refer\u00eancia. Quando o marcado indica 30 minutos, tamb\u00e9m mostra o d\u00e9cimo quinto dia do m\u00eas.\u2026 Leia mais \u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal Dana\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-01T12:39:31+00:00\" \/>\n<meta name=\"author\" content=\"Canal Dana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Dana\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/01\\\/relogio-calendario-perpetuo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/01\\\/relogio-calendario-perpetuo\\\/\"},\"author\":{\"name\":\"Canal Dana\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"headline\":\"Rel\u00f3gio calend\u00e1rio perp\u00e9tuo\",\"datePublished\":\"2016-08-01T12:39:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/01\\\/relogio-calendario-perpetuo\\\/\"},\"wordCount\":89,\"articleSection\":[\"Tech Talk\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/01\\\/relogio-calendario-perpetuo\\\/\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/01\\\/relogio-calendario-perpetuo\\\/\",\"name\":\"Rel\u00f3gio calend\u00e1rio perp\u00e9tuo - Canal Dana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\"},\"datePublished\":\"2016-08-01T12:39:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/01\\\/relogio-calendario-perpetuo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/01\\\/relogio-calendario-perpetuo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/2016\\\/08\\\/01\\\/relogio-calendario-perpetuo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tech Talk\",\"item\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/tech-talk\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rel\u00f3gio calend\u00e1rio perp\u00e9tuo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#website\",\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/\",\"name\":\"Canal Dana\",\"description\":\"Informativo com as principais not\u00edcias da ind\u00fastria automotiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/#\\\/schema\\\/person\\\/3c21f22f56fcf3bc46b94bc60ea4fef6\",\"name\":\"Canal Dana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g\",\"caption\":\"Canal Dana\"},\"url\":\"https:\\\/\\\/dana.com.br\\\/canaldana\\\/author\\\/cdeditor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rel\u00f3gio calend\u00e1rio perp\u00e9tuo - Canal Dana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/","og_locale":"pt_BR","og_type":"article","og_title":"Rel\u00f3gio calend\u00e1rio perp\u00e9tuo - Canal Dana","og_description":"Desenho \u00fanico resultado de 40 anos de experi\u00eancia do Dr. Ludwig Oeschlin, marca dia, m\u00eas data de cada m\u00eas, incluindo fevereiro, e ano. No per\u00edmetro do mostrador, h\u00e1 30 + 1 orif\u00edcios, com a cada 10 minutos como pontos de refer\u00eancia. Quando o marcado indica 30 minutos, tamb\u00e9m mostra o d\u00e9cimo quinto dia do m\u00eas.\u2026 Leia mais \u00bb","og_url":"https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/","og_site_name":"Canal Dana","article_published_time":"2016-08-01T12:39:31+00:00","author":"Canal Dana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Dana"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/#article","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/"},"author":{"name":"Canal Dana","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"headline":"Rel\u00f3gio calend\u00e1rio perp\u00e9tuo","datePublished":"2016-08-01T12:39:31+00:00","mainEntityOfPage":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/"},"wordCount":89,"articleSection":["Tech Talk"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/","url":"https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/","name":"Rel\u00f3gio calend\u00e1rio perp\u00e9tuo - Canal Dana","isPartOf":{"@id":"https:\/\/dana.com.br\/canaldana\/#website"},"datePublished":"2016-08-01T12:39:31+00:00","author":{"@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6"},"breadcrumb":{"@id":"https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dana.com.br\/canaldana\/2016\/08\/01\/relogio-calendario-perpetuo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dana.com.br\/canaldana\/"},{"@type":"ListItem","position":2,"name":"Tech Talk","item":"https:\/\/dana.com.br\/canaldana\/tech-talk\/"},{"@type":"ListItem","position":3,"name":"Rel\u00f3gio calend\u00e1rio perp\u00e9tuo"}]},{"@type":"WebSite","@id":"https:\/\/dana.com.br\/canaldana\/#website","url":"https:\/\/dana.com.br\/canaldana\/","name":"Canal Dana","description":"Informativo com as principais not\u00edcias da ind\u00fastria automotiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dana.com.br\/canaldana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/dana.com.br\/canaldana\/#\/schema\/person\/3c21f22f56fcf3bc46b94bc60ea4fef6","name":"Canal Dana","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/420aaf9278582877d9018637c6817617705899d2858d7572ef0fe59a6b6454b4?s=96&d=mm&r=g","caption":"Canal Dana"},"url":"https:\/\/dana.com.br\/canaldana\/author\/cdeditor\/"}]}},"_links":{"self":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/10363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/comments?post=10363"}],"version-history":[{"count":0,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/posts\/10363\/revisions"}],"wp:attachment":[{"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/media?parent=10363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/categories?post=10363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dana.com.br\/canaldana\/wp-json\/wp\/v2\/tags?post=10363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}